{"id":316,"date":"2024-11-20T12:02:02","date_gmt":"2024-11-20T11:02:02","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/"},"modified":"2024-11-20T12:02:46","modified_gmt":"2024-11-20T11:02:46","slug":"avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/","title":{"rendered":"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026"},"content":{"rendered":"<p><em>Scadenza presentazione domande ore 12.00 del 29\/11\/2024<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p style=\"text-align: left\">Il Comune di Lucoli per l&#8217;attuazione del Piano Neve della stagione invernali 2024\/2025 e 2025\/2026, intende acquisire la manifestazione di interesse da parte di Ditte e\/o Aziende private, in possesso di adeguate attrezzature, disponibili ad assumere la responsabilit\u00e0 dello sgombero della neve e spargimento del sale nelle strade e altre aree pubbliche del territorio comunale con materiale antigelo fornito dall\u2019Amministrazione.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_323\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/Prot_Arr-0006810-del-20-11-2024-Allegato-AVVISO-PUBBLICO-PIANO-NEVE-STAGIONE-INVERNALE-2024-2026-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/Prot_Arr-0006810-del-20-11-2024-Allegato-AVVISO-PUBBLICO-PIANO-NEVE-STAGIONE-INVERNALE-2024-2026-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Prot_Arr 0006810 del 20-11-2024 &#8211; Allegato AVVISO PUBBLICO PIANO NEVE STAGIONE INVERNALE 2024-2026<\/a><\/li>\n<li><a id=\"wpba_attachment_list_324\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/Prot_Arr-0006810-del-20-11-2024-Allegato-Allegato-A-Schema-di-Domanda-1.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/Prot_Arr-0006810-del-20-11-2024-Allegato-Allegato-A-Schema-di-Domanda-1.docx', '_system'); return false;\"><i class='icon attachment'><\/i>Prot_Arr 0006810 del 20-11-2024 &#8211; Allegato Allegato A Schema di Domanda<\/a><\/li>\n<li><a id=\"wpba_attachment_list_325\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/Prot_Arr-0006810-del-20-11-2024-Allegato-Capitolato-doneri-servizio-sgombero-neve-2024-2026-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/Prot_Arr-0006810-del-20-11-2024-Allegato-Capitolato-doneri-servizio-sgombero-neve-2024-2026-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>&#8216;oneri servizio sgombero neve 2024-2026<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Scadenza presentazione domande ore 12.00 del 29\/11\/2024&nbsp; Descrizione&nbsp; Il Comune di Lucoli per l&#8217;attuazione del Piano Neve della stagione invernali 2024\/2025 e 2025\/2026, intende acquisire la manifestazione di interesse da [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026 - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026 - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Scadenza presentazione domande ore 12.00 del 29\/11\/2024&nbsp; Descrizione&nbsp; Il Comune di Lucoli per l&#8217;attuazione del Piano Neve della stagione invernali 2024\/2025 e 2025\/2026, intende acquisire la manifestazione di interesse da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T11:02:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T11:02:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/spazzaneve-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"474\" \/>\n\t<meta property=\"og:image:height\" content=\"258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\\\/2025 e 2025\\\/2026\",\"datePublished\":\"2024-11-20T11:02:02+00:00\",\"dateModified\":\"2024-11-20T11:02:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/\"},\"wordCount\":88,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/11\\\/spazzaneve-1.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/\",\"name\":\"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\\\/2025 e 2025\\\/2026 - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/11\\\/spazzaneve-1.jpg\",\"datePublished\":\"2024-11-20T11:02:02+00:00\",\"dateModified\":\"2024-11-20T11:02:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/11\\\/spazzaneve-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/11\\\/spazzaneve-1.jpg\",\"width\":474,\"height\":258},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/11\\\/20\\\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\\\/2025 e 2025\\\/2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026 - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026 - Lucoli","og_description":"Scadenza presentazione domande ore 12.00 del 29\/11\/2024&nbsp; Descrizione&nbsp; Il Comune di Lucoli per l&#8217;attuazione del Piano Neve della stagione invernali 2024\/2025 e 2025\/2026, intende acquisire la manifestazione di interesse da [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-11-20T11:02:02+00:00","article_modified_time":"2024-11-20T11:02:46+00:00","og_image":[{"width":474,"height":258,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/spazzaneve-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026","datePublished":"2024-11-20T11:02:02+00:00","dateModified":"2024-11-20T11:02:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/"},"wordCount":88,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/spazzaneve-1.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/","url":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/","name":"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026 - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/spazzaneve-1.jpg","datePublished":"2024-11-20T11:02:02+00:00","dateModified":"2024-11-20T11:02:46+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/spazzaneve-1.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/11\/spazzaneve-1.jpg","width":474,"height":258},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/11\/20\/avviso-pubblico-manifestazione-di-interesse-allaffidamento-del-servizio-di-pulizia-delle-strade-sgombero-neve-e-spargimento-prodotti-antighiaccio-2024-2025-e-2025-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico manifestazione di interesse all\u2019affidamento del servizio di pulizia delle strade \u2013 sgombero neve e spargimento prodotti antighiaccio 2024\/2025 e 2025\/2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000708"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"predecessor-version":[{"id":321,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/316\/revisions\/321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/322"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}