{"id":33,"date":"2024-05-09T17:04:32","date_gmt":"2024-05-09T15:04:32","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/?p=33"},"modified":"2024-05-09T17:04:34","modified_gmt":"2024-05-09T15:04:34","slug":"elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/","title":{"rendered":"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio"},"content":{"rendered":"<p><em>Gioved\u00ec 16 maggio ore 17.30<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>La Commissione elettorale comunale \u00e8 convocata nella sede del Comune in pubblica adunanza per il giorno 16 maggio 2024, alle ore 17.30 per procedere alla nomina degli scrutatori che saranno destinati agli uffici elettorali di sezione per le elezioni di sabato 8 giugno e domenica 9 giugno 2024.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_40\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/05\/MANIFESTO-CONVOCAZIONE-COMMISSIONE-ELETTORALE.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/05\/MANIFESTO-CONVOCAZIONE-COMMISSIONE-ELETTORALE.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MANIFESTO CONVOCAZIONE COMMISSIONE ELETTORALE<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 16 maggio ore 17.30&nbsp; Descrizione&nbsp; La Commissione elettorale comunale \u00e8 convocata nella sede del Comune in pubblica adunanza per il giorno 16 maggio 2024, alle ore 17.30 per procedere [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-33","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 16 maggio ore 17.30&nbsp; Descrizione&nbsp; La Commissione elettorale comunale \u00e8 convocata nella sede del Comune in pubblica adunanza per il giorno 16 maggio 2024, alle ore 17.30 per procedere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-09T15:04:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-09T15:04:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio\",\"datePublished\":\"2024-05-09T15:04:32+00:00\",\"dateModified\":\"2024-05-09T15:04:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/\"},\"wordCount\":59,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/\",\"name\":\"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"datePublished\":\"2024-05-09T15:04:32+00:00\",\"dateModified\":\"2024-05-09T15:04:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/05\\\/09\\\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio - Lucoli","og_description":"Gioved\u00ec 16 maggio ore 17.30&nbsp; Descrizione&nbsp; La Commissione elettorale comunale \u00e8 convocata nella sede del Comune in pubblica adunanza per il giorno 16 maggio 2024, alle ore 17.30 per procedere [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-05-09T15:04:32+00:00","article_modified_time":"2024-05-09T15:04:34+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio","datePublished":"2024-05-09T15:04:32+00:00","dateModified":"2024-05-09T15:04:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/"},"wordCount":59,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/","url":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/","name":"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"datePublished":"2024-05-09T15:04:32+00:00","dateModified":"2024-05-09T15:04:34+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/05\/09\/elezioni-del-parlamento-europeo-convocazione-commissione-elettorale-per-nomina-scrutatori-di-seggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Elezioni del Parlamento Europeo: convocazione commissione elettorale per nomina scrutatori di seggio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000478"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"predecessor-version":[{"id":36,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/33\/revisions\/36"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}