{"id":503,"date":"2025-04-24T09:23:55","date_gmt":"2025-04-24T07:23:55","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/"},"modified":"2025-04-24T09:23:55","modified_gmt":"2025-04-24T07:23:55","slug":"avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/","title":{"rendered":"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali"},"content":{"rendered":"<p><em>Scadenza presentazione domande venerd\u00ec 2 maggio 2025<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Sindaco comunica che si intende istituire, <strong>esclusivamente per questa tornata elettorale referendaria<\/strong>, un elenco aggiuntivo dei componenti di seggio per eventuali sostituzioni. Tutti i cittadini e le cittadine iscritte nelle liste elettorali, pertanto, <strong>ove non gi\u00e0 iscritti negli Albi appositi<\/strong>, potranno esprimere preventivamente la propria disponibilit\u00e0 a essere inseriti in tale elenco, fornendo cos\u00ec la disponibilit\u00e0 a subentrare nell&#8217;esercizio delle funzioni di componente di seggio, in tutti i casi di improvvisa vacanza non surrogabile con le modalit\u00e0 ordinarie.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_505\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/AVVISO-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/AVVISO-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali<\/a><\/li>\n<li><a id=\"wpba_attachment_list_506\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/DOMANDA-di-inserimento-nellelenco-aggiuntivo-non-iscritti-agli-Albi-per-lo-svolgimento-di-funzioni-presso-i-seggi-elettorali.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/DOMANDA-di-inserimento-nellelenco-aggiuntivo-non-iscritti-agli-Albi-per-lo-svolgimento-di-funzioni-presso-i-seggi-elettorali.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>DOMANDA di inserimento nell\u2019elenco aggiuntivo (non iscritti agli Albi) per lo svolgimento di funzioni presso i seggi elettorali<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Scadenza presentazione domande venerd\u00ec 2 maggio 2025&nbsp; Descrizione&nbsp; Il Sindaco comunica che si intende istituire, esclusivamente per questa tornata elettorale referendaria, un elenco aggiuntivo dei componenti di seggio per eventuali [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Scadenza presentazione domande venerd\u00ec 2 maggio 2025&nbsp; Descrizione&nbsp; Il Sindaco comunica che si intende istituire, esclusivamente per questa tornata elettorale referendaria, un elenco aggiuntivo dei componenti di seggio per eventuali [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-24T07:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/referendum-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali\",\"datePublished\":\"2025-04-24T07:23:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/\"},\"wordCount\":104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/04\\\/referendum-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/\",\"name\":\"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/04\\\/referendum-1.jpg\",\"datePublished\":\"2025-04-24T07:23:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/04\\\/referendum-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/04\\\/referendum-1.jpg\",\"width\":760,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/04\\\/24\\\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali - Lucoli","og_description":"Scadenza presentazione domande venerd\u00ec 2 maggio 2025&nbsp; Descrizione&nbsp; Il Sindaco comunica che si intende istituire, esclusivamente per questa tornata elettorale referendaria, un elenco aggiuntivo dei componenti di seggio per eventuali [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-24T07:23:55+00:00","og_image":[{"width":760,"height":475,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/referendum-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali","datePublished":"2025-04-24T07:23:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/"},"wordCount":104,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/referendum-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/","url":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/","name":"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/referendum-1.jpg","datePublished":"2025-04-24T07:23:55+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/referendum-1.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/04\/referendum-1.jpg","width":760,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/04\/24\/avviso-volto-alla-creazione-di-un-elenco-aggiuntivo-di-componenti-delle-sezioni-elettorali-per-eventuali-sostituzioni-emergenziali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Avviso volto alla creazione di un elenco aggiuntivo di componenti delle sezioni elettorali per eventuali sostituzioni emergenziali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000834"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=503"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/504"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}