{"id":681,"date":"2025-07-17T10:20:57","date_gmt":"2025-07-17T08:20:57","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/"},"modified":"2025-07-17T10:21:52","modified_gmt":"2025-07-17T08:21:52","slug":"stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/","title":{"rendered":"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale."},"content":{"rendered":"<p><em>999^ su 7.896 Comuni Italiani &#8211; 25^ su 305 Comuni Abruzzesi &#8211; 9^ su 108 Comuni della Provincia di L\u2019Aquila<br \/>\n<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p style=\"margin-top: 0cm;text-align: justify;background: white\"><span style=\"color: #1a1a1a\">Dopo il subentro nell&#8217;<strong>Anagrafe Nazionale della Popolazione Residente (ANPR)<\/strong>\u00a0e l&#8217;integrazione nell&#8217;ANPR delle\u00a0<strong>liste elettorali,\u00a0<\/strong>\u00a0il Comune di Lucoli subentra ufficialmente anche nell\u2019<strong>Archivio Nazionale Informatizzato dei Registri dello Stato Civile (ANSC)<\/strong>.<\/span><\/p>\n<p><strong>Da oggi, 17 luglio 2025, l&#8217;Ufficio di Stato Civile chiude definitivamente i registri cartacei e inizier\u00e0 a registrare e conservare digitalmente i documenti dei propri cittadini (nascita, matrimonio, unione civile, cittadinanza e morte).<\/strong> Fino a questa data atti, registri e fascicoli di allegati concernenti lo stato civile hanno avuto gestione cartacea coinvolgendo, nel corso del tempo, Comuni, Prefetture e Archivi di Stato per gli aspetti di conservazione. Il passaggio al sistema digitale, che utilizza esclusivamente i servizi messi a disposizione dal nuovo sistema per la formazione e l&#8217;iscrizione nell\u2019archivio nazionale degli atti dello Stato Civile, comporta\u00a0<em><strong>dopo 159 anni la<\/strong><\/em><strong><em>\u00a0<\/em><em>dismissione dei registri cartacei in uso dal 1866<\/em><\/strong> (lo Stato Civile fu istituito con Regio Decreto n. 2602 del 15 novembre 1865).<\/p>\n<p><strong>Sar\u00e0 un importante strumento di semplificazione delle attivit\u00e0 svolte dagli Ufficiali dello Stato Civile con l&#8217;obiettivo di realizzare servizi mirati ad agevolare lo scambio dei dati dei cittadini e dei loro aggiornamenti<\/strong>. Lucoli \u00e8 il nono Comune della Provincia di L\u2019Aquila che passa all\u2019Archivio Nazionale informatizzato dei registri dello Stato Civile (ANSC). Il sistema costituisce un\u2019estensione delle funzionalit\u00e0 dell\u2019Anagrafe Nazionale digitale della Popolazione Residente (ANPR) ed \u00e8 stato possibile grazie alle risorse del PNRR, un contributo messo a disposizione dal Dipartimento per la trasformazione digitale della Presidenza del Consiglio dei Ministri.<\/p>\n<p>Con l\u2019introduzione dello Stato Civile digitale, gli operatori comunali possono disporre di una piattaforma unica e centralizzata, accessibile a tutti i Comuni, che permette di gestire digitalmente tutte le operazioni relative all\u2019iscrizione, trascrizione, annotazione e conservazione degli atti nei registri dello Stato Civile e offre l\u2019opportunit\u00e0 di generare digitalmente certificati con piena valenza legale. Aspetto davvero rivoluzionario \u00e8 che gli atti formati nel nuovo ambiente digitale (ANSC) potranno essere sottoscritti dai dichiaranti, ove previsto, identificandosi tramite la propria identit\u00e0 digitale SPID, Carta d\u2019Identit\u00e0 Elettronica (CIE) e Carta Nazionale dei Servizi (CNS); in alternativa, per casi particolari o per coloro che fossero sprovvisti di identit\u00e0 digitale, \u00e8 sempre possibile apporre la propria firma autografa per essere poi digitalizzati e valere come unico originale.<br \/>\nGrazie al passaggio allo stato civile digitale i cittadini possono cos\u00ec accedere a certificati di stato civile sempre aggiornati e in tempi ridotti collegandosi direttamente al portale ANPR, senza necessit\u00e0 di recarsi all\u2019ente. Questi i principali vantaggi:<\/p>\n<ul>\n<li>Certificati disponibili online: sar\u00e0 possibile ottenere in modo autonomo, sicuro e gratuito i principali certificati di stato civile, direttamente dal portale dell\u2019ANPR (Anagrafe Nazionale della Popolazione Residente)<\/li>\n<li>Riduzione delle attese: meno code agli sportelli e tempi di rilascio pi\u00f9 brevi per documenti e certificazioni<\/li>\n<li>Maggior efficienza e trasparenza: i dati saranno sempre aggiornati e accessibili in tempo reale, migliorando l\u2019interazione tra cittadini e pubblica amministrazione<\/li>\n<li>Valore legale dei documenti digitali: i certificati rilasciati digitalmente hanno piena validit\u00e0 giuridica.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>999^ su 7.896 Comuni Italiani &#8211; 25^ su 305 Comuni Abruzzesi &#8211; 9^ su 108 Comuni della Provincia di L\u2019Aquila &nbsp; Descrizione&nbsp; Dopo il subentro nell&#8217;Anagrafe Nazionale della Popolazione Residente [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale. - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale. - Lucoli\" \/>\n<meta property=\"og:description\" content=\"999^ su 7.896 Comuni Italiani &#8211; 25^ su 305 Comuni Abruzzesi &#8211; 9^ su 108 Comuni della Provincia di L\u2019Aquila &nbsp; Descrizione&nbsp; Dopo il subentro nell&#8217;Anagrafe Nazionale della Popolazione Residente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-17T08:20:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T08:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/07\/foto-registri-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1126\" \/>\n\t<meta property=\"og:image:height\" content=\"1604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale.\",\"datePublished\":\"2025-07-17T08:20:57+00:00\",\"dateModified\":\"2025-07-17T08:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/\"},\"wordCount\":512,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/07\\\/foto-registri-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/\",\"name\":\"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale. - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/07\\\/foto-registri-1.jpg\",\"datePublished\":\"2025-07-17T08:20:57+00:00\",\"dateModified\":\"2025-07-17T08:21:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/07\\\/foto-registri-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2025\\\/07\\\/foto-registri-1.jpg\",\"width\":1126,\"height\":1604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2025\\\/07\\\/17\\\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale. - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale. - Lucoli","og_description":"999^ su 7.896 Comuni Italiani &#8211; 25^ su 305 Comuni Abruzzesi &#8211; 9^ su 108 Comuni della Provincia di L\u2019Aquila &nbsp; Descrizione&nbsp; Dopo il subentro nell&#8217;Anagrafe Nazionale della Popolazione Residente [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-17T08:20:57+00:00","article_modified_time":"2025-07-17T08:21:52+00:00","og_image":[{"width":1126,"height":1604,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/07\/foto-registri-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale.","datePublished":"2025-07-17T08:20:57+00:00","dateModified":"2025-07-17T08:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/"},"wordCount":512,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/07\/foto-registri-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/","url":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/","name":"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale. - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/07\/foto-registri-1.jpg","datePublished":"2025-07-17T08:20:57+00:00","dateModified":"2025-07-17T08:21:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/07\/foto-registri-1.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2025\/07\/foto-registri-1.jpg","width":1126,"height":1604},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2025\/07\/17\/stop-ai-registri-cartacei-a-lucoli-lo-stato-civile-diventa-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Stop ai registri cartacei. A Lucoli lo Stato Civile diventa digitale."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000918"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=681"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/681\/revisions"}],"predecessor-version":[{"id":683,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/681\/revisions\/683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/684"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}