{"id":74,"date":"2024-06-03T15:17:49","date_gmt":"2024-06-03T13:17:49","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/"},"modified":"2024-06-03T15:17:49","modified_gmt":"2024-06-03T13:17:49","slug":"ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/","title":{"rendered":"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; dal civico 41 fino all&#8217;intersezione con la S.P. 32, frazione Lucoli Alto"},"content":{"rendered":"<p><em>Giorno 06\/06\/2024 dalle ore 7:30 alle ore 20:00<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; dal civico 41 fino all&#8217;intersezione con la S.P. 32, fraz. Lucoli Alto per il giorno 06\/06\/2024 dalle ore 7:30 alle ore 20:00<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_76\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Ordinanza-n.-18.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Ordinanza-n.-18.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza n. 18<\/a><\/li>\n<li><a id=\"wpba_attachment_list_77\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Tratto-interessato-e-percorsi-alternativi.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Tratto-interessato-e-percorsi-alternativi.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Tratto interessato e percorsi alternativi<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Giorno 06\/06\/2024 dalle ore 7:30 alle ore 20:00&nbsp; Descrizione&nbsp; Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":75,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-74","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &quot;via Lunga&quot; dal civico 41 fino all&#039;intersezione con la S.P. 32, frazione Lucoli Alto - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &quot;via Lunga&quot; dal civico 41 fino all&#039;intersezione con la S.P. 32, frazione Lucoli Alto - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Giorno 06\/06\/2024 dalle ore 7:30 alle ore 20:00&nbsp; Descrizione&nbsp; Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T13:17:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/strada-chiusa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; dal civico 41 fino all&#8217;intersezione con la S.P. 32, frazione Lucoli Alto\",\"datePublished\":\"2024-06-03T13:17:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/\"},\"wordCount\":75,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/strada-chiusa.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/\",\"name\":\"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale \\\"via Lunga\\\" dal civico 41 fino all'intersezione con la S.P. 32, frazione Lucoli Alto - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/strada-chiusa.jpg\",\"datePublished\":\"2024-06-03T13:17:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/strada-chiusa.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/strada-chiusa.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/03\\\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; dal civico 41 fino all&#8217;intersezione con la S.P. 32, frazione Lucoli Alto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale \"via Lunga\" dal civico 41 fino all'intersezione con la S.P. 32, frazione Lucoli Alto - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale \"via Lunga\" dal civico 41 fino all'intersezione con la S.P. 32, frazione Lucoli Alto - Lucoli","og_description":"Giorno 06\/06\/2024 dalle ore 7:30 alle ore 20:00&nbsp; Descrizione&nbsp; Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-06-03T13:17:49+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/strada-chiusa.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; dal civico 41 fino all&#8217;intersezione con la S.P. 32, frazione Lucoli Alto","datePublished":"2024-06-03T13:17:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/"},"wordCount":75,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/strada-chiusa.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/","url":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/","name":"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale \"via Lunga\" dal civico 41 fino all'intersezione con la S.P. 32, frazione Lucoli Alto - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/strada-chiusa.jpg","datePublished":"2024-06-03T13:17:49+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/strada-chiusa.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/strada-chiusa.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/03\/ordinanza-di-chiusura-al-traffico-veicolare-della-s-p-32-dal-km-3240-al-km-3400-e-della-strada-comunale-via-lunga-dal-civico-41-fino-allintersezione-con-la-s-p-32-frazione-lucoli-alto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Ordinanza di chiusura al traffico veicolare della S.P. 32 dal km 3+240 al km 3+400 e della strada comunale &#8220;via Lunga&#8221; dal civico 41 fino all&#8217;intersezione con la S.P. 32, frazione Lucoli Alto"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000516"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}