{"id":85,"date":"2024-06-19T11:17:24","date_gmt":"2024-06-19T09:17:24","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/?p=85"},"modified":"2024-06-19T11:17:25","modified_gmt":"2024-06-19T09:17:25","slug":"centro-estivo-comune-di-lucoli-parco-dello-sport","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/","title":{"rendered":"Centro estivo Comune di Lucoli &#8211; Parco dello Sport"},"content":{"rendered":"<p><em>Scheda di iscrizione e tesseramento per assicurazione<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Le famiglie interessate possono presentare domanda per il centro estivo compilando l&#8217;apposita modulistica per l&#8217;iscrizione e il tesseramento assicurativo reinviando tutto per email a <strong><em>segreteriaparcodellosport@gmail.com<\/em><\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_91\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Scheda-dIscrizione-2024-LUCOLI-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Scheda-dIscrizione-2024-LUCOLI-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Scheda-dIscrizione-2024 LUCOLI<\/a><\/li>\n<li><a id=\"wpba_attachment_list_92\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Tesseramento-per-assicurazione-ASD-PARCO-DELLO-SPORT-1-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/Tesseramento-per-assicurazione-ASD-PARCO-DELLO-SPORT-1-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Tesseramento per assicurazione ASD PARCO DELLO SPORT (1)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Scheda di iscrizione e tesseramento per assicurazione&nbsp; Descrizione&nbsp; Le famiglie interessate possono presentare domanda per il centro estivo compilando l&#8217;apposita modulistica per l&#8217;iscrizione e il tesseramento assicurativo reinviando tutto per [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":90,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-85","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro estivo Comune di Lucoli - Parco dello Sport - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro estivo Comune di Lucoli - Parco dello Sport - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Scheda di iscrizione e tesseramento per assicurazione&nbsp; Descrizione&nbsp; Le famiglie interessate possono presentare domanda per il centro estivo compilando l&#8217;apposita modulistica per l&#8217;iscrizione e il tesseramento assicurativo reinviando tutto per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T09:17:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T09:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/centro-estivo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Centro estivo Comune di Lucoli &#8211; Parco dello Sport\",\"datePublished\":\"2024-06-19T09:17:24+00:00\",\"dateModified\":\"2024-06-19T09:17:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/\"},\"wordCount\":46,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/centro-estivo-1.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/\",\"name\":\"Centro estivo Comune di Lucoli - Parco dello Sport - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/centro-estivo-1.jpg\",\"datePublished\":\"2024-06-19T09:17:24+00:00\",\"dateModified\":\"2024-06-19T09:17:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/centro-estivo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/06\\\/centro-estivo-1.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/06\\\/19\\\/centro-estivo-comune-di-lucoli-parco-dello-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro estivo Comune di Lucoli &#8211; Parco dello Sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro estivo Comune di Lucoli - Parco dello Sport - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/","og_locale":"it_IT","og_type":"article","og_title":"Centro estivo Comune di Lucoli - Parco dello Sport - Lucoli","og_description":"Scheda di iscrizione e tesseramento per assicurazione&nbsp; Descrizione&nbsp; Le famiglie interessate possono presentare domanda per il centro estivo compilando l&#8217;apposita modulistica per l&#8217;iscrizione e il tesseramento assicurativo reinviando tutto per [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-06-19T09:17:24+00:00","article_modified_time":"2024-06-19T09:17:25+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/centro-estivo-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Centro estivo Comune di Lucoli &#8211; Parco dello Sport","datePublished":"2024-06-19T09:17:24+00:00","dateModified":"2024-06-19T09:17:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/"},"wordCount":46,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/centro-estivo-1.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/","url":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/","name":"Centro estivo Comune di Lucoli - Parco dello Sport - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/centro-estivo-1.jpg","datePublished":"2024-06-19T09:17:24+00:00","dateModified":"2024-06-19T09:17:25+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/centro-estivo-1.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/06\/centro-estivo-1.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/06\/19\/centro-estivo-comune-di-lucoli-parco-dello-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Centro estivo Comune di Lucoli &#8211; Parco dello Sport"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000537"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/85\/revisions"}],"predecessor-version":[{"id":89,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/85\/revisions\/89"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/90"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=85"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=85"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}