{"id":1034,"date":"2018-10-02T16:23:37","date_gmt":"2018-10-02T14:23:37","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1034"},"modified":"2018-10-02T16:23:37","modified_gmt":"2018-10-02T14:23:37","slug":"chiusura-temporanea-isola-ecologica-unione-dei-comuni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/","title":{"rendered":"CHIUSURA TEMPORANEA ISOLA ECOLOGICA &#8211; UNIONE DEI COMUNI"},"content":{"rendered":"<p>Considerate le difficolt\u00e0 registrate nel corso del periodo di affidamento del servizio, l\u2019Unione dei Comuni della Valle Ustica, rende noto di aver raggiunto un accordo consensuale per la conclusione anticipata e a proprio favore del rapporto contrattuale con la societ\u00e0 TAC Ecologia, di conseguenza a seguito del procedimento di scorrimento della vecchia gara di appalto, dal prossimo luned\u00ec 8 ottobre p.v. il servizio di raccolta, gestione dei rifiuti e gestione dell\u2019isola ecologica, saranno presi in carico dalla Societ\u00e0 Pragma di Castel Madama, per i prossimi mesi e comunque nelle more dei tempi e delle procedure richieste per il nuovo appalto.<\/p>\n<p>In base a quanto sopra, si comunica \u00a0che <strong><u>da gioved\u00ec 4 ottobre a marted\u00ec 9, l\u2019isola ecologica dell\u2019Unione dei Comuni della Valle Ustica sar\u00e0 chiusa al pubblico<\/u><\/strong> per pulizia dell\u2019area, sgombero degli scarrabili da parte della societ\u00e0 TAC e predisposizione dell\u2019area da parte della societ\u00e0 Pragma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerate le difficolt\u00e0 registrate nel corso del periodo di affidamento del servizio, l\u2019Unione dei Comuni della Valle Ustica, rende noto di aver raggiunto un accordo consensuale per la conclusione anticipata [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":1035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHIUSURA TEMPORANEA ISOLA ECOLOGICA - UNIONE DEI COMUNI - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHIUSURA TEMPORANEA ISOLA ECOLOGICA - UNIONE DEI COMUNI - Mandela\" \/>\n<meta property=\"og:description\" content=\"Considerate le difficolt\u00e0 registrate nel corso del periodo di affidamento del servizio, l\u2019Unione dei Comuni della Valle Ustica, rende noto di aver raggiunto un accordo consensuale per la conclusione anticipata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T14:23:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/10\/chiusura-centro-comunale-raccolta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1121\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"CHIUSURA TEMPORANEA ISOLA ECOLOGICA &#8211; UNIONE DEI COMUNI\",\"datePublished\":\"2018-10-02T14:23:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/\"},\"wordCount\":158,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/chiusura-centro-comunale-raccolta.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/\",\"name\":\"CHIUSURA TEMPORANEA ISOLA ECOLOGICA - UNIONE DEI COMUNI - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/chiusura-centro-comunale-raccolta.jpg\",\"datePublished\":\"2018-10-02T14:23:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/chiusura-centro-comunale-raccolta.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/chiusura-centro-comunale-raccolta.jpg\",\"width\":1121,\"height\":705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/02\\\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHIUSURA TEMPORANEA ISOLA ECOLOGICA &#8211; UNIONE DEI COMUNI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHIUSURA TEMPORANEA ISOLA ECOLOGICA - UNIONE DEI COMUNI - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/","og_locale":"it_IT","og_type":"article","og_title":"CHIUSURA TEMPORANEA ISOLA ECOLOGICA - UNIONE DEI COMUNI - Mandela","og_description":"Considerate le difficolt\u00e0 registrate nel corso del periodo di affidamento del servizio, l\u2019Unione dei Comuni della Valle Ustica, rende noto di aver raggiunto un accordo consensuale per la conclusione anticipata [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/","og_site_name":"Mandela","article_published_time":"2018-10-02T14:23:37+00:00","og_image":[{"width":1121,"height":705,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/10\/chiusura-centro-comunale-raccolta.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"CHIUSURA TEMPORANEA ISOLA ECOLOGICA &#8211; UNIONE DEI COMUNI","datePublished":"2018-10-02T14:23:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/"},"wordCount":158,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/10\/chiusura-centro-comunale-raccolta.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/","url":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/","name":"CHIUSURA TEMPORANEA ISOLA ECOLOGICA - UNIONE DEI COMUNI - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/10\/chiusura-centro-comunale-raccolta.jpg","datePublished":"2018-10-02T14:23:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/10\/chiusura-centro-comunale-raccolta.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/10\/chiusura-centro-comunale-raccolta.jpg","width":1121,"height":705},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/02\/chiusura-temporanea-isola-ecologica-unione-dei-comuni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"CHIUSURA TEMPORANEA ISOLA ECOLOGICA &#8211; UNIONE DEI COMUNI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1034"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1034\/revisions"}],"predecessor-version":[{"id":1036,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1034\/revisions\/1036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1035"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}