{"id":1062,"date":"2018-10-23T16:55:29","date_gmt":"2018-10-23T14:55:29","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1062"},"modified":"2018-10-23T16:55:29","modified_gmt":"2018-10-23T14:55:29","slug":"sciopero-del-personale-scolastico-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/","title":{"rendered":"SCIOPERO DEL PERSONALE SCOLASTICO"},"content":{"rendered":"<p style=\"text-align: center\">Si informano i genitori degli alunni delle scuole\u00a0<em>(materna, elementari e medie)<\/em>, che in considerazione del previsto sciopero del personale scolastico di<strong>\u00a0venerd\u00ec 26 ottobre p.v.<\/strong>,\u00a0<strong><u>il Servizio di<\/u><\/strong><u>\u00a0<strong>Scuolabus\u00a0<\/strong><strong>sar\u00e0 effettuato esclusivamente per il viaggio di ritorno.<\/strong><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informano i genitori degli alunni delle scuole\u00a0(materna, elementari e medie), che in considerazione del previsto sciopero del personale scolastico di\u00a0venerd\u00ec 26 ottobre p.v.,\u00a0il Servizio di\u00a0Scuolabus\u00a0sar\u00e0 effettuato esclusivamente per il [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCIOPERO DEL PERSONALE SCOLASTICO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCIOPERO DEL PERSONALE SCOLASTICO - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informano i genitori degli alunni delle scuole\u00a0(materna, elementari e medie), che in considerazione del previsto sciopero del personale scolastico di\u00a0venerd\u00ec 26 ottobre p.v.,\u00a0il Servizio di\u00a0Scuolabus\u00a0sar\u00e0 effettuato esclusivamente per il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-23T14:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"605\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"SCIOPERO DEL PERSONALE SCOLASTICO\",\"datePublished\":\"2018-10-23T14:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/\"},\"wordCount\":42,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/\",\"name\":\"SCIOPERO DEL PERSONALE SCOLASTICO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"datePublished\":\"2018-10-23T14:55:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"width\":605,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/10\\\/23\\\/sciopero-del-personale-scolastico-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCIOPERO DEL PERSONALE SCOLASTICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCIOPERO DEL PERSONALE SCOLASTICO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/","og_locale":"it_IT","og_type":"article","og_title":"SCIOPERO DEL PERSONALE SCOLASTICO - Mandela","og_description":"Si informano i genitori degli alunni delle scuole\u00a0(materna, elementari e medie), che in considerazione del previsto sciopero del personale scolastico di\u00a0venerd\u00ec 26 ottobre p.v.,\u00a0il Servizio di\u00a0Scuolabus\u00a0sar\u00e0 effettuato esclusivamente per il [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/","og_site_name":"Mandela","article_published_time":"2018-10-23T14:55:29+00:00","og_image":[{"width":605,"height":454,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"SCIOPERO DEL PERSONALE SCOLASTICO","datePublished":"2018-10-23T14:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/"},"wordCount":42,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/","url":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/","name":"SCIOPERO DEL PERSONALE SCOLASTICO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","datePublished":"2018-10-23T14:55:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","width":605,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2018\/10\/23\/sciopero-del-personale-scolastico-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"SCIOPERO DEL PERSONALE SCOLASTICO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1062\/revisions"}],"predecessor-version":[{"id":1063,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1062\/revisions\/1063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/673"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}