{"id":1177,"date":"2019-01-02T21:42:54","date_gmt":"2019-01-02T20:42:54","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1177"},"modified":"2019-01-02T21:42:54","modified_gmt":"2019-01-02T20:42:54","slug":"pericolo-ghiaccio-e-gelo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/","title":{"rendered":"PERICOLO GHIACCIO E GELO"},"content":{"rendered":"<p>Il bollettino Meteo prevede per i prossimi giorni temperature sotto zero, si consiglia di prestare particolare attenzione durante le ore notturne e le prime ore del mattino alle\u00a0<strong><u>gelate del manto stradale<\/u><\/strong>\u00a0che malgrado lo spargimento di sale che continuer\u00e0 ad essere effettuato dai volontari della Protezione Civile, resta comunque\u00a0<strong><u>pericoloso per il transito dei veicoli e delle persone.<\/u><\/strong><\/p>\n<p>Si consiglia inoltre di\u00a0<strong><u>coprire i tratti di tubatura\u00a0<em>-all\u2019interno delle propriet\u00e0 &#8211;<\/em>\u00a0soggetti a possibili gelate che potrebbero causare l\u2019interruzione della fornitura idrica\u00a0nelle case<\/u> <\/strong>e in alcuni casi la possibile rottura della conduttura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il bollettino Meteo prevede per i prossimi giorni temperature sotto zero, si consiglia di prestare particolare attenzione durante le ore notturne e le prime ore del mattino alle\u00a0gelate del manto [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PERICOLO GHIACCIO E GELO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PERICOLO GHIACCIO E GELO - Mandela\" \/>\n<meta property=\"og:description\" content=\"Il bollettino Meteo prevede per i prossimi giorni temperature sotto zero, si consiglia di prestare particolare attenzione durante le ore notturne e le prime ore del mattino alle\u00a0gelate del manto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-02T20:42:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/12\/gelo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t<meta property=\"og:image:height\" content=\"285\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"PERICOLO GHIACCIO E GELO\",\"datePublished\":\"2019-01-02T20:42:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/\"},\"wordCount\":100,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/12\\\/gelo.jpg\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/\",\"name\":\"PERICOLO GHIACCIO E GELO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/12\\\/gelo.jpg\",\"datePublished\":\"2019-01-02T20:42:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/12\\\/gelo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/12\\\/gelo.jpg\",\"width\":270,\"height\":285},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/01\\\/02\\\/pericolo-ghiaccio-e-gelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PERICOLO GHIACCIO E GELO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PERICOLO GHIACCIO E GELO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/","og_locale":"it_IT","og_type":"article","og_title":"PERICOLO GHIACCIO E GELO - Mandela","og_description":"Il bollettino Meteo prevede per i prossimi giorni temperature sotto zero, si consiglia di prestare particolare attenzione durante le ore notturne e le prime ore del mattino alle\u00a0gelate del manto [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/","og_site_name":"Mandela","article_published_time":"2019-01-02T20:42:54+00:00","og_image":[{"width":270,"height":285,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/12\/gelo.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"PERICOLO GHIACCIO E GELO","datePublished":"2019-01-02T20:42:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/"},"wordCount":100,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/12\/gelo.jpg","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/","url":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/","name":"PERICOLO GHIACCIO E GELO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/12\/gelo.jpg","datePublished":"2019-01-02T20:42:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/12\/gelo.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/12\/gelo.jpg","width":270,"height":285},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2019\/01\/02\/pericolo-ghiaccio-e-gelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"PERICOLO GHIACCIO E GELO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1177"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1177\/revisions"}],"predecessor-version":[{"id":1178,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1177\/revisions\/1178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/728"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}