{"id":1229,"date":"2019-02-25T10:00:48","date_gmt":"2019-02-25T09:00:48","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1229"},"modified":"2019-02-25T11:06:55","modified_gmt":"2019-02-25T10:06:55","slug":"guasto-elettrico-privato-e-pubblico-3","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/","title":{"rendered":"GUASTO ELETTRICO &#8211; PRIVATO E PUBBLICO"},"content":{"rendered":"<p style=\"text-align: center;\">AGGIORNAMENTO INTERRUZIONE FORNITURA DI ENERGIA ELETTRICA<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\">25\/2 Ore 10<\/span><\/p>\n<p>A seguito dell\u2019interruzione di fornitura dell\u2019energia elettrica in circa 64 abitazioni di Mandela e parte dell\u2019illuminazione pubblica, oltre ai vari reclami inoltrati dai cittadini per le proprie utenze, l\u2019Amministrazione comunale gi\u00e0 da sabato pomeriggio ha continuato a sollecitare il pronto intervento di Enel distribuzione, fino a pochi minuti fa, principalmente per il ripristino nelle abitazioni.<\/p>\n<p>Oltre a Enel sono stati informati da ieri sia il Comando dei Carabinieri, la sala operativa della Protezione Civile e la Regione Lazio.<\/p>\n<p>E\u2019 stato anche chiesto un gruppo elettrogeno di emergenza, ma la sala operativa della Protezione Civile non pu\u00f2 intervenire direttamente senza intervento dei tecnici Enel.<\/p>\n<p>Il comando dei carabinieri ci ha informato poco fa che il guasto \u00e8 relativo alla tratta di linea <u>Mandela- San Polo dei cavalieri \u2013 Marcellina<\/u>, le chiamate di richiesta di intervento sono migliaia e la societ\u00e0 di distribuzione \u00e8 all\u2019opera per il ripristino della linea.<\/p>\n<p>Non abbiamo notizia sui tempi di risoluzione, essendo il guasto definito grave, restiamo in attesa di ulteriori notizie per informare tutte le famiglie.<\/p>\n<p style=\"text-align: center;\">I volontari della Protezione Civile restano a disposizione per situazioni di emergenza. Nel caso contattare il Comune al 0774.492003<\/p>\n<p style=\"text-align: center;\"><em>Si informa che le Pubbliche Amministrazioni non hanno nessun canale diretto per situazioni di emergenza relativamente all&#8217;interruzione di energia.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AGGIORNAMENTO INTERRUZIONE FORNITURA DI ENERGIA ELETTRICA 25\/2 Ore 10 A seguito dell\u2019interruzione di fornitura dell\u2019energia elettrica in circa 64 abitazioni di Mandela e parte dell\u2019illuminazione pubblica, oltre ai vari reclami [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":1223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GUASTO ELETTRICO - PRIVATO E PUBBLICO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GUASTO ELETTRICO - PRIVATO E PUBBLICO - Mandela\" \/>\n<meta property=\"og:description\" content=\"AGGIORNAMENTO INTERRUZIONE FORNITURA DI ENERGIA ELETTRICA 25\/2 Ore 10 A seguito dell\u2019interruzione di fornitura dell\u2019energia elettrica in circa 64 abitazioni di Mandela e parte dell\u2019illuminazione pubblica, oltre ai vari reclami [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-25T09:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-25T10:06:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/02\/interruzione-enel-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"GUASTO ELETTRICO &#8211; PRIVATO E PUBBLICO\",\"datePublished\":\"2019-02-25T09:00:48+00:00\",\"dateModified\":\"2019-02-25T10:06:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/\"},\"wordCount\":222,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/02\\\/interruzione-enel-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/\",\"name\":\"GUASTO ELETTRICO - PRIVATO E PUBBLICO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/02\\\/interruzione-enel-1.jpg\",\"datePublished\":\"2019-02-25T09:00:48+00:00\",\"dateModified\":\"2019-02-25T10:06:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/02\\\/interruzione-enel-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/02\\\/interruzione-enel-1.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/02\\\/25\\\/guasto-elettrico-privato-e-pubblico-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GUASTO ELETTRICO &#8211; PRIVATO E PUBBLICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GUASTO ELETTRICO - PRIVATO E PUBBLICO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/","og_locale":"it_IT","og_type":"article","og_title":"GUASTO ELETTRICO - PRIVATO E PUBBLICO - Mandela","og_description":"AGGIORNAMENTO INTERRUZIONE FORNITURA DI ENERGIA ELETTRICA 25\/2 Ore 10 A seguito dell\u2019interruzione di fornitura dell\u2019energia elettrica in circa 64 abitazioni di Mandela e parte dell\u2019illuminazione pubblica, oltre ai vari reclami [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/","og_site_name":"Mandela","article_published_time":"2019-02-25T09:00:48+00:00","article_modified_time":"2019-02-25T10:06:55+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/02\/interruzione-enel-1.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"GUASTO ELETTRICO &#8211; PRIVATO E PUBBLICO","datePublished":"2019-02-25T09:00:48+00:00","dateModified":"2019-02-25T10:06:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/"},"wordCount":222,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/02\/interruzione-enel-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/","url":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/","name":"GUASTO ELETTRICO - PRIVATO E PUBBLICO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/02\/interruzione-enel-1.jpg","datePublished":"2019-02-25T09:00:48+00:00","dateModified":"2019-02-25T10:06:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/02\/interruzione-enel-1.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/02\/interruzione-enel-1.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2019\/02\/25\/guasto-elettrico-privato-e-pubblico-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"GUASTO ELETTRICO &#8211; PRIVATO E PUBBLICO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1229"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1229\/revisions"}],"predecessor-version":[{"id":1231,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1229\/revisions\/1231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1223"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}