{"id":1373,"date":"2019-06-10T10:14:38","date_gmt":"2019-06-10T08:14:38","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1373"},"modified":"2019-06-10T10:14:38","modified_gmt":"2019-06-10T08:14:38","slug":"falo-di-san-giovanni-23-giugno","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/","title":{"rendered":"FALO&#8217; DI SAN GIOVANNI -23 GIUGNO"},"content":{"rendered":"<p style=\"text-align: center\">DOMENICA 23 GIUGNO\u00a0 &#8211; ORE 19<\/p>\n<p style=\"text-align: center\">FALO\u2019 DI SAN GIOVANNI<\/p>\n<p style=\"text-align: center\">Area Verde \u201cFonte Bove\u201d<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>DOMENICA 23 GIUGNO\u00a0 &#8211; ORE 19 FALO\u2019 DI SAN GIOVANNI Area Verde \u201cFonte Bove\u201d<\/p>\n","protected":false},"author":175,"featured_media":1374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FALO&#039; DI SAN GIOVANNI -23 GIUGNO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FALO&#039; DI SAN GIOVANNI -23 GIUGNO - Mandela\" \/>\n<meta property=\"og:description\" content=\"DOMENICA 23 GIUGNO\u00a0 &#8211; ORE 19 FALO\u2019 DI SAN GIOVANNI Area Verde \u201cFonte Bove\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-10T08:14:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/06\/FaloSanGiovanni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1754\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"FALO&#8217; DI SAN GIOVANNI -23 GIUGNO\",\"datePublished\":\"2019-06-10T08:14:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/\"},\"wordCount\":18,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/06\\\/FaloSanGiovanni.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/\",\"name\":\"FALO' DI SAN GIOVANNI -23 GIUGNO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/06\\\/FaloSanGiovanni.jpg\",\"datePublished\":\"2019-06-10T08:14:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/06\\\/FaloSanGiovanni.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/06\\\/FaloSanGiovanni.jpg\",\"width\":1754,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/06\\\/10\\\/falo-di-san-giovanni-23-giugno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FALO&#8217; DI SAN GIOVANNI -23 GIUGNO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FALO' DI SAN GIOVANNI -23 GIUGNO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/","og_locale":"it_IT","og_type":"article","og_title":"FALO' DI SAN GIOVANNI -23 GIUGNO - Mandela","og_description":"DOMENICA 23 GIUGNO\u00a0 &#8211; ORE 19 FALO\u2019 DI SAN GIOVANNI Area Verde \u201cFonte Bove\u201d","og_url":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/","og_site_name":"Mandela","article_published_time":"2019-06-10T08:14:38+00:00","og_image":[{"width":1754,"height":1240,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/06\/FaloSanGiovanni.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"FALO&#8217; DI SAN GIOVANNI -23 GIUGNO","datePublished":"2019-06-10T08:14:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/"},"wordCount":18,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/06\/FaloSanGiovanni.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/","url":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/","name":"FALO' DI SAN GIOVANNI -23 GIUGNO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/06\/FaloSanGiovanni.jpg","datePublished":"2019-06-10T08:14:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/06\/FaloSanGiovanni.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/06\/FaloSanGiovanni.jpg","width":1754,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2019\/06\/10\/falo-di-san-giovanni-23-giugno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"FALO&#8217; DI SAN GIOVANNI -23 GIUGNO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1373"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1373\/revisions"}],"predecessor-version":[{"id":1375,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1373\/revisions\/1375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1374"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}