{"id":1430,"date":"2019-08-12T15:53:30","date_gmt":"2019-08-12T13:53:30","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1430"},"modified":"2019-08-12T15:53:30","modified_gmt":"2019-08-12T13:53:30","slug":"raccolta-rifiuti-venerdi-16-agosto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/","title":{"rendered":"RACCOLTA RIFIUTI &#8211; VENERDI&#8217; 16 AGOSTO"},"content":{"rendered":"<p>Si informano i cittadini che la societ\u00e0 di raccolta dei rifiuti Pragma,\u00a0<u>effettuer\u00e0 <strong>il giorno 16 agosto la raccolta dell\u2019organico e del secco non riciclabile.<\/strong><\/u><\/p>\n<p>Sabato 17 Agosto sar\u00e0 effettuata, come da calendario, la raccolta dell\u2019organico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informano i cittadini che la societ\u00e0 di raccolta dei rifiuti Pragma,\u00a0effettuer\u00e0 il giorno 16 agosto la raccolta dell\u2019organico e del secco non riciclabile. Sabato 17 Agosto sar\u00e0 effettuata, come [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RACCOLTA RIFIUTI - VENERDI&#039; 16 AGOSTO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RACCOLTA RIFIUTI - VENERDI&#039; 16 AGOSTO - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informano i cittadini che la societ\u00e0 di raccolta dei rifiuti Pragma,\u00a0effettuer\u00e0 il giorno 16 agosto la raccolta dell\u2019organico e del secco non riciclabile. Sabato 17 Agosto sar\u00e0 effettuata, come [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-12T13:53:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/03\/RACCOLTA-RIFIUTI-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"RACCOLTA RIFIUTI &#8211; VENERDI&#8217; 16 AGOSTO\",\"datePublished\":\"2019-08-12T13:53:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/\"},\"wordCount\":41,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/03\\\/RACCOLTA-RIFIUTI-1.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/\",\"name\":\"RACCOLTA RIFIUTI - VENERDI' 16 AGOSTO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/03\\\/RACCOLTA-RIFIUTI-1.jpg\",\"datePublished\":\"2019-08-12T13:53:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/03\\\/RACCOLTA-RIFIUTI-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/03\\\/RACCOLTA-RIFIUTI-1.jpg\",\"width\":810,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2019\\\/08\\\/12\\\/raccolta-rifiuti-venerdi-16-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RACCOLTA RIFIUTI &#8211; VENERDI&#8217; 16 AGOSTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RACCOLTA RIFIUTI - VENERDI' 16 AGOSTO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/","og_locale":"it_IT","og_type":"article","og_title":"RACCOLTA RIFIUTI - VENERDI' 16 AGOSTO - Mandela","og_description":"Si informano i cittadini che la societ\u00e0 di raccolta dei rifiuti Pragma,\u00a0effettuer\u00e0 il giorno 16 agosto la raccolta dell\u2019organico e del secco non riciclabile. Sabato 17 Agosto sar\u00e0 effettuata, come [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/","og_site_name":"Mandela","article_published_time":"2019-08-12T13:53:30+00:00","og_image":[{"width":810,"height":540,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/03\/RACCOLTA-RIFIUTI-1.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"RACCOLTA RIFIUTI &#8211; VENERDI&#8217; 16 AGOSTO","datePublished":"2019-08-12T13:53:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/"},"wordCount":41,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/03\/RACCOLTA-RIFIUTI-1.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/","url":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/","name":"RACCOLTA RIFIUTI - VENERDI' 16 AGOSTO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/03\/RACCOLTA-RIFIUTI-1.jpg","datePublished":"2019-08-12T13:53:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/03\/RACCOLTA-RIFIUTI-1.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/03\/RACCOLTA-RIFIUTI-1.jpg","width":810,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2019\/08\/12\/raccolta-rifiuti-venerdi-16-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"RACCOLTA RIFIUTI &#8211; VENERDI&#8217; 16 AGOSTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1430"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1430\/revisions"}],"predecessor-version":[{"id":1431,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1430\/revisions\/1431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/881"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}