{"id":1636,"date":"2020-01-09T17:59:46","date_gmt":"2020-01-09T16:59:46","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1636"},"modified":"2020-01-09T18:00:41","modified_gmt":"2020-01-09T17:00:41","slug":"scuola-infanzia-iscrizioni-anno-2020-21","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/","title":{"rendered":"SCUOLA INFANZIA &#8211; ISCRIZIONI ANNO 2020\/21"},"content":{"rendered":"<p>Si comunica ai genitori dei bambini della Scuola Materna che i <strong>Moduli\u00a0 di Iscrizione per l\u2019anno scolastico 2020\/21<\/strong> sono disponibili presso il plesso di Mandela (Maestre della Scuola Materna)<\/p>\n<p><strong>Il termine per la presentazione delle domande \u00e8 fissato al 31\/01\/2020.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica ai genitori dei bambini della Scuola Materna che i Moduli\u00a0 di Iscrizione per l\u2019anno scolastico 2020\/21 sono disponibili presso il plesso di Mandela (Maestre della Scuola Materna) Il [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":1637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCUOLA INFANZIA - ISCRIZIONI ANNO 2020\/21 - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCUOLA INFANZIA - ISCRIZIONI ANNO 2020\/21 - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si comunica ai genitori dei bambini della Scuola Materna che i Moduli\u00a0 di Iscrizione per l\u2019anno scolastico 2020\/21 sono disponibili presso il plesso di Mandela (Maestre della Scuola Materna) Il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-09T16:59:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-09T17:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/01\/iscrizione-scuola-infanzia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"715\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"SCUOLA INFANZIA &#8211; ISCRIZIONI ANNO 2020\\\/21\",\"datePublished\":\"2020-01-09T16:59:46+00:00\",\"dateModified\":\"2020-01-09T17:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/\"},\"wordCount\":43,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/01\\\/iscrizione-scuola-infanzia.png\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/\",\"name\":\"SCUOLA INFANZIA - ISCRIZIONI ANNO 2020\\\/21 - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/01\\\/iscrizione-scuola-infanzia.png\",\"datePublished\":\"2020-01-09T16:59:46+00:00\",\"dateModified\":\"2020-01-09T17:00:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/01\\\/iscrizione-scuola-infanzia.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/01\\\/iscrizione-scuola-infanzia.png\",\"width\":715,\"height\":392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/01\\\/09\\\/scuola-infanzia-iscrizioni-anno-2020-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCUOLA INFANZIA &#8211; ISCRIZIONI ANNO 2020\\\/21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCUOLA INFANZIA - ISCRIZIONI ANNO 2020\/21 - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/","og_locale":"it_IT","og_type":"article","og_title":"SCUOLA INFANZIA - ISCRIZIONI ANNO 2020\/21 - Mandela","og_description":"Si comunica ai genitori dei bambini della Scuola Materna che i Moduli\u00a0 di Iscrizione per l\u2019anno scolastico 2020\/21 sono disponibili presso il plesso di Mandela (Maestre della Scuola Materna) Il [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/","og_site_name":"Mandela","article_published_time":"2020-01-09T16:59:46+00:00","article_modified_time":"2020-01-09T17:00:41+00:00","og_image":[{"width":715,"height":392,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/01\/iscrizione-scuola-infanzia.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"SCUOLA INFANZIA &#8211; ISCRIZIONI ANNO 2020\/21","datePublished":"2020-01-09T16:59:46+00:00","dateModified":"2020-01-09T17:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/"},"wordCount":43,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/01\/iscrizione-scuola-infanzia.png","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/","url":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/","name":"SCUOLA INFANZIA - ISCRIZIONI ANNO 2020\/21 - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/01\/iscrizione-scuola-infanzia.png","datePublished":"2020-01-09T16:59:46+00:00","dateModified":"2020-01-09T17:00:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/01\/iscrizione-scuola-infanzia.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/01\/iscrizione-scuola-infanzia.png","width":715,"height":392},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2020\/01\/09\/scuola-infanzia-iscrizioni-anno-2020-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"SCUOLA INFANZIA &#8211; ISCRIZIONI ANNO 2020\/21"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1636"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1636\/revisions"}],"predecessor-version":[{"id":1639,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1636\/revisions\/1639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1637"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}