{"id":1695,"date":"2020-03-04T19:10:02","date_gmt":"2020-03-04T18:10:02","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1695"},"modified":"2020-03-04T19:10:02","modified_gmt":"2020-03-04T18:10:02","slug":"misure-urgenti-coronavirus","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/","title":{"rendered":"MISURE URGENTI &#8211; CORONAVIRUS"},"content":{"rendered":"<p style=\"text-align: center\"><strong>Ulteriori misure urgenti di contenimento del contagio sull\u2019intero territorio nazionale (estratto)<\/strong><\/p>\n<p style=\"text-align: center\"><strong>EMESSE OGGI 4 MARZO 2020<\/strong><\/p>\n<ol>\n<li>Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, sull\u2019intero territorio nazionale si applicano le seguenti misure:<\/li>\n<li>a) sospensione di congressi, riunioni, meeting ed eventi sociali, per il personale sanitario e il personale che garantisce i servizi pubblici essenziali e di pubblica utilit\u00e0;<\/li>\n<li>b) rinvio di tutte le attivit\u00e0 convegnistiche e congressuali;<\/li>\n<li>c) sospensione di manifestazioni di qualsiasi natura, nonch\u00e9 degli eventi in luogo pubblico o privato e in luogo chiuso aperto al pubblico (inclusi cinema e teatri) [Proposta MIBACTSALUTE], che comportino affollamento di persone e che non garantiscano il rispetto della distanza di sicurezza\/interpersonale di almeno un metro;<\/li>\n<li>d) divieto per accompagnatori dei pazienti di permanenza nelle sale di attesa dei Dipartimenti emergenze e accettazione e dei pronto soccorso (DEA\/PS), salvo specifica indicazione del personale sanitario del triage; e) limitazione dell\u2019accesso di parenti e visitatori a strutture quali hospice, residenze sanitarie assistite (RSA) e strutture residenziali per anziani autosufficienti e non, ai soli casi consentiti dalla direzione sanitaria della struttura, adottando le misure necessarie a prevenire possibili trasmissioni di infezione;<\/li>\n<li>f) raccomandazione a tutte le persone anziane e\/o affette da patologie croniche, con multimobilit\u00e0, nonch\u00e9 con stati di immunodepressione congenita o acquisita di limitare le uscite non strettamente necessarie ed evitare luoghi affollati nei quali non sia possibile mantenere la distanza di sicurezza\/interpersonale di almeno un metro;<\/li>\n<li>g) adozione dei seguenti comportamenti:<\/li>\n<li>lavaggio frequente delle mani;<\/li>\n<li>igiene respiratoria (starnutire o\/o tossire in un fazzoletto evitando il contatto delle mani con le secrezioni respiratorie);<\/li>\n<li>mantenimento nei contatti sociali di una distanza interpersonale di almeno un metro;<\/li>\n<li>evitare abbracci e strette di mano;<\/li>\n<li>evitare scambi di bottiglie, bicchieri in particolare durante attivit\u00e0 sportive. (Le misure di cui alla lettera g) potrebbero integrare le misure igieniche elencate nell\u2019allegato 4 al d.P.C.M. 1\u00b0 marzo 2020, in quanto parzialmente sovrapponibili).<\/li>\n<li>h) sospensione degli eventi e delle competizioni sportive di ogni ordine e disciplina, in luoghi pubblici o privati. Resta consentito lo svolgimento dei predetti eventi e competizioni, nonch\u00e9 delle sedute di allenamento degli atleti agonisti, all\u2019interno di impianti sportivi utilizzati a porte chiuse, nei Comuni diversi da quelli di cui all\u2019allegato 1.<\/li>\n<\/ol>\n<p>Lo sport di base e le attivit\u00e0 motorie in genere, svolti all\u2019interno di palestre, piscine e centri sportivi di ogni tipo, sono consentiti esclusivamente nel rispetto delle raccomandazioni previste dalla lettera g).<\/p>\n<p>E&#8217; fatto divieto di trasferta dei tifosi residenti nelle regioni e nelle province di cui all&#8217;allegato 2 per la partecipazione ad eventi e competizioni sportive che si svolgono nelle restanti regioni e province (???);<\/p>\n<p><strong>i) raccomandazione ai comuni, agli enti territoriali, alle associazioni culturali e associazioni sportive di offrire attivit\u00e0 ricreative individuali alternative, che promuovano e favoriscano le attivit\u00e0 all\u2019aperto (senza assembramenti) o presso il proprio domicilio;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ulteriori misure urgenti di contenimento del contagio sull\u2019intero territorio nazionale (estratto) EMESSE OGGI 4 MARZO 2020 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, sull\u2019intero territorio nazionale [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":1691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MISURE URGENTI - CORONAVIRUS - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MISURE URGENTI - CORONAVIRUS - Mandela\" \/>\n<meta property=\"og:description\" content=\"Ulteriori misure urgenti di contenimento del contagio sull\u2019intero territorio nazionale (estratto) EMESSE OGGI 4 MARZO 2020 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, sull\u2019intero territorio nazionale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-04T18:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/02\/Corona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"MISURE URGENTI &#8211; CORONAVIRUS\",\"datePublished\":\"2020-03-04T18:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/\"},\"wordCount\":477,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/02\\\/Corona.png\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/\",\"name\":\"MISURE URGENTI - CORONAVIRUS - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/02\\\/Corona.png\",\"datePublished\":\"2020-03-04T18:10:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/02\\\/Corona.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/02\\\/Corona.png\",\"width\":1240,\"height\":1754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/03\\\/04\\\/misure-urgenti-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MISURE URGENTI &#8211; CORONAVIRUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MISURE URGENTI - CORONAVIRUS - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/","og_locale":"it_IT","og_type":"article","og_title":"MISURE URGENTI - CORONAVIRUS - Mandela","og_description":"Ulteriori misure urgenti di contenimento del contagio sull\u2019intero territorio nazionale (estratto) EMESSE OGGI 4 MARZO 2020 Allo scopo di contrastare e contenere il diffondersi del virus COVID-19, sull\u2019intero territorio nazionale [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/","og_site_name":"Mandela","article_published_time":"2020-03-04T18:10:02+00:00","og_image":[{"width":1240,"height":1754,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/02\/Corona.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"MISURE URGENTI &#8211; CORONAVIRUS","datePublished":"2020-03-04T18:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/"},"wordCount":477,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/02\/Corona.png","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/","url":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/","name":"MISURE URGENTI - CORONAVIRUS - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/02\/Corona.png","datePublished":"2020-03-04T18:10:02+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/02\/Corona.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/02\/Corona.png","width":1240,"height":1754},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2020\/03\/04\/misure-urgenti-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"MISURE URGENTI &#8211; CORONAVIRUS"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1695"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1695\/revisions"}],"predecessor-version":[{"id":1696,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1695\/revisions\/1696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1691"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}