{"id":1899,"date":"2020-05-02T19:54:21","date_gmt":"2020-05-02T17:54:21","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=1899"},"modified":"2020-05-02T19:56:46","modified_gmt":"2020-05-02T17:56:46","slug":"regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/","title":{"rendered":"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO &#8211; DAL 4 MAGGIO"},"content":{"rendered":"<h2 style=\"text-align: center\">Vademecum in otto punti\u00a0che\u00a0identifica le misure di sicurezza da rispettare da parte degli esercizi commerciali del settore dell\u2019alimentazione a partire da luned\u00ec 4 maggio<\/h2>\n<h5 style=\"text-align: center\">(produzione, confezionamento e la vendita di cibo e bevande da asporto)<\/h5>\n<ol>\n<li><strong><u>\u00c8 consentita<\/u><\/strong> ai sensi del Dpcm 26 aprile 2020 <strong><u>la vendita di cibo e bevande da asporto <\/u><\/strong>da parte degli esercizi di somministrazione di alimenti e bevande e delle attivit\u00e0 artigianali (bar, pub, ristoranti, rosticcerie, friggitorie, gelaterie, pasticcerie, pizzerie al taglio, paninoteche, yogurterie, piadinerie\u00a0ecc)<\/li>\n<li><strong><u>Si raccomanda ai clienti l\u2019ordinazione on-line o telefonica<\/u><\/strong>, in modo da garantire che il ritiro dei prodotti ordinati avvenga per appuntamenti dilazionati nel tempo, allo scopo di evitare assembramenti all\u2019esterno, dove in ogni caso <u>i clienti dovranno rispettare il distanziamento interpersonale di almeno un metro;<\/u><\/li>\n<li><strong><u>All\u2019interno dei locali i clienti sono obbligati a indossare guanti e dispositivi di protezione delle vie respiratorie;<\/u><\/strong><\/li>\n<li><strong><u>\u00a0I clienti entrano uno alla volta<\/u><\/strong> e devono permanere all\u2019interno dei locali per il<strong><u> tempo strettamente necessario al pagamento e ritiro della merce<\/u><\/strong>. Non \u00e8 consentito per i clienti l\u2019utilizzo dei bagni;<\/li>\n<li>Fermo restando quanto gi\u00e0 disposto dalla normativa in materia di igiene e sicurezza degli alimenti e delle bevande (Reg. (CE) 852\/2004), <strong><u>gestore e addetti devono indossare mascherina e guanti per tutto il tempo di permanenza nei locali e mantenere, ove possibile, un distanziamento interpersonale di almeno un metro<\/u><\/strong>. <u>Devono, altres\u00ec, adottare tutte le precauzioni igieniche, in particolare per le mani, per le quali \u00e8 raccomandato un lavaggio frequente con acqua e sapone o altri prodotti igienizzanti<\/u>;<\/li>\n<li><strong><u>\u00c8 vietata ogni forma di consumo sul posto<\/u><\/strong>. I prodotti devono essere consegnati chiusi in confezioni da asporto;<\/li>\n<li><u>Dovr\u00e0 essere data ampia disponibilit\u00e0 e accessibilit\u00e0 a sistemi e prodotti per l\u2019igienizzazione delle mani (preferibilmente a induzione automatica)<\/u>. In particolare, detti sistemi devono essere disponibili sia per il personale, sia per i clienti, all\u2019ingresso del locale;<\/li>\n<li>Deve essere data informazione sulle misure di sicurezza dei lavoratori come da normativa vigente; deve, <strong><u>altres\u00ec, essere fornita completa informazione sulle norme di comportamento dei clienti e sulle modalit\u00e0 di ordinazione e ritiro della merce, mediante esposizione di cartellonistica all\u2019ingresso<\/u><\/strong> ed eventualmente anche sui siti internet e pagine social aziendali. <u>Si raccomanda ai gestori di esporre in vetrina un cartello che indichi che l\u2019attivit\u00e0 di ristorazione \u00e8 sospesa ad eccezione della ristorazione con consegna a domicilio e con asporto.<\/u><\/li>\n<\/ol>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Vademecum in otto punti\u00a0che\u00a0identifica le misure di sicurezza da rispettare da parte degli esercizi commerciali del settore dell\u2019alimentazione a partire da luned\u00ec 4 maggio (produzione, confezionamento e la vendita di [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":1900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO - DAL 4 MAGGIO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO - DAL 4 MAGGIO - Mandela\" \/>\n<meta property=\"og:description\" content=\"Vademecum in otto punti\u00a0che\u00a0identifica le misure di sicurezza da rispettare da parte degli esercizi commerciali del settore dell\u2019alimentazione a partire da luned\u00ec 4 maggio (produzione, confezionamento e la vendita di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-02T17:54:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-02T17:56:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/05\/CIBO-DA-ASPORTO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO &#8211; DAL 4 MAGGIO\",\"datePublished\":\"2020-05-02T17:54:21+00:00\",\"dateModified\":\"2020-05-02T17:56:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/\"},\"wordCount\":400,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/05\\\/CIBO-DA-ASPORTO.png\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/\",\"name\":\"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO - DAL 4 MAGGIO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/05\\\/CIBO-DA-ASPORTO.png\",\"datePublished\":\"2020-05-02T17:54:21+00:00\",\"dateModified\":\"2020-05-02T17:56:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/05\\\/CIBO-DA-ASPORTO.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/05\\\/CIBO-DA-ASPORTO.png\",\"width\":777,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/05\\\/02\\\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO &#8211; DAL 4 MAGGIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO - DAL 4 MAGGIO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/","og_locale":"it_IT","og_type":"article","og_title":"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO - DAL 4 MAGGIO - Mandela","og_description":"Vademecum in otto punti\u00a0che\u00a0identifica le misure di sicurezza da rispettare da parte degli esercizi commerciali del settore dell\u2019alimentazione a partire da luned\u00ec 4 maggio (produzione, confezionamento e la vendita di [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/","og_site_name":"Mandela","article_published_time":"2020-05-02T17:54:21+00:00","article_modified_time":"2020-05-02T17:56:46+00:00","og_image":[{"width":777,"height":508,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/05\/CIBO-DA-ASPORTO.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO &#8211; DAL 4 MAGGIO","datePublished":"2020-05-02T17:54:21+00:00","dateModified":"2020-05-02T17:56:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/"},"wordCount":400,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/05\/CIBO-DA-ASPORTO.png","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/","url":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/","name":"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO - DAL 4 MAGGIO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/05\/CIBO-DA-ASPORTO.png","datePublished":"2020-05-02T17:54:21+00:00","dateModified":"2020-05-02T17:56:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/05\/CIBO-DA-ASPORTO.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2020\/05\/CIBO-DA-ASPORTO.png","width":777,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2020\/05\/02\/regole-per-la-vendita-di-cibo-e-bevande-da-asporto-dal-4-maggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"REGOLE PER LA VENDITA DI CIBO E BEVANDE DA ASPORTO &#8211; DAL 4 MAGGIO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=1899"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1899\/revisions"}],"predecessor-version":[{"id":1903,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/1899\/revisions\/1903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1900"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=1899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=1899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=1899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}