{"id":2079,"date":"2020-08-12T12:10:37","date_gmt":"2020-08-12T10:10:37","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2079"},"modified":"2020-08-12T12:10:37","modified_gmt":"2020-08-12T10:10:37","slug":"integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/","title":{"rendered":"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA&#8217; &#8211; MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO)"},"content":{"rendered":"<p>Si informa la popolazione che con ord. n. 13\/2020\u00a0 \u00e8 stato modificato l&#8217;orario di istituzione dell&#8217;area pedonale nel centro storico, pertanto\u00a0 dalla data odierna, (nei giorni dal lunedi al sabato e prefestivi)\u00a0 il nuovo orario di chiusura\u00a0 al traffico sar\u00e0 dalle ore 21.00.<\/p>\n<p>Resta invariato quanto non modificato dalla predetta ordinanza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa la popolazione che con ord. n. 13\/2020\u00a0 \u00e8 stato modificato l&#8217;orario di istituzione dell&#8217;area pedonale nel centro storico, pertanto\u00a0 dalla data odierna, (nei giorni dal lunedi al sabato [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2079","post","type-post","status-publish","format-standard","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA&#039; - MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO) - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA&#039; - MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO) - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa la popolazione che con ord. n. 13\/2020\u00a0 \u00e8 stato modificato l&#8217;orario di istituzione dell&#8217;area pedonale nel centro storico, pertanto\u00a0 dalla data odierna, (nei giorni dal lunedi al sabato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T10:10:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/pubblica-sicurezza.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"INTEGRAZIONE\\\/MODIFICA ORDINANZA N. 10 (VIABILITA&#8217; &#8211; MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO)\",\"datePublished\":\"2020-08-12T10:10:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/\"},\"wordCount\":61,\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/\",\"name\":\"INTEGRAZIONE\\\/MODIFICA ORDINANZA N. 10 (VIABILITA' - MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO) - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"datePublished\":\"2020-08-12T10:10:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2020\\\/08\\\/12\\\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INTEGRAZIONE\\\/MODIFICA ORDINANZA N. 10 (VIABILITA&#8217; &#8211; MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA' - MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO) - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/","og_locale":"it_IT","og_type":"article","og_title":"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA' - MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO) - Mandela","og_description":"Si informa la popolazione che con ord. n. 13\/2020\u00a0 \u00e8 stato modificato l&#8217;orario di istituzione dell&#8217;area pedonale nel centro storico, pertanto\u00a0 dalla data odierna, (nei giorni dal lunedi al sabato [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/","og_site_name":"Mandela","article_published_time":"2020-08-12T10:10:37+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/pubblica-sicurezza.png","height":600,"width":1200,"type":""}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA&#8217; &#8211; MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO)","datePublished":"2020-08-12T10:10:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/"},"wordCount":61,"articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/","url":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/","name":"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA' - MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO) - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"datePublished":"2020-08-12T10:10:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2020\/08\/12\/integrazione-modifica-ordinanza-n-10-viabilita-modifica-orario-istituzione-area-pedonale-centro-storico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"INTEGRAZIONE\/MODIFICA ORDINANZA N. 10 (VIABILITA&#8217; &#8211; MODIFICA ORARIO ISTITUZIONE AREA PEDONALE CENTRO STORICO)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2079"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2079\/revisions"}],"predecessor-version":[{"id":2080,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2079\/revisions\/2080"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}