{"id":229,"date":"2015-06-22T16:00:42","date_gmt":"2015-06-22T14:00:42","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=229"},"modified":"2015-06-22T16:00:42","modified_gmt":"2015-06-22T14:00:42","slug":"avviso-disinfestazione-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/","title":{"rendered":"AVVISO DISINFESTAZIONE"},"content":{"rendered":"<h3 style=\"text-align: justify\"><span style=\"color: #000000\">Vista l&#8217;impossibilit\u00e0 di effettuare la disinfestazione programmata del giorno 16 Giugno, causa condizioni meteorologiche non idonee, si avvisa la cittadinanza che quest&#8217;ultima verr\u00e0 svolta il giorno\u00a0 25 Giugno dalle ore 22.00 in poi.\u00a0 <\/span><\/h3>\n<h3 style=\"text-align: justify\"><span style=\"color: #000000\">Modalit\u00e0 e dettagli nell&#8217;ordinanza da scaricare dal sito www.comune.mandela.roma.it<br \/>\nSi ringrazia per la collaborazione\u00a0<\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Vista l&#8217;impossibilit\u00e0 di effettuare la disinfestazione programmata del giorno 16 Giugno, causa condizioni meteorologiche non idonee, si avvisa la cittadinanza che quest&#8217;ultima verr\u00e0 svolta il giorno\u00a0 25 Giugno dalle ore [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO DISINFESTAZIONE - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO DISINFESTAZIONE - Mandela\" \/>\n<meta property=\"og:description\" content=\"Vista l&#8217;impossibilit\u00e0 di effettuare la disinfestazione programmata del giorno 16 Giugno, causa condizioni meteorologiche non idonee, si avvisa la cittadinanza che quest&#8217;ultima verr\u00e0 svolta il giorno\u00a0 25 Giugno dalle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-22T14:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2015\/06\/zanzara-tigre-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"558\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"AVVISO DISINFESTAZIONE\",\"datePublished\":\"2015-06-22T14:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/\"},\"wordCount\":50,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/06\\\/zanzara-tigre-1.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/\",\"name\":\"AVVISO DISINFESTAZIONE - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/06\\\/zanzara-tigre-1.jpg\",\"datePublished\":\"2015-06-22T14:00:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/06\\\/zanzara-tigre-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/06\\\/zanzara-tigre-1.jpg\",\"width\":558,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2015\\\/06\\\/22\\\/avviso-disinfestazione-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO DISINFESTAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO DISINFESTAZIONE - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO DISINFESTAZIONE - Mandela","og_description":"Vista l&#8217;impossibilit\u00e0 di effettuare la disinfestazione programmata del giorno 16 Giugno, causa condizioni meteorologiche non idonee, si avvisa la cittadinanza che quest&#8217;ultima verr\u00e0 svolta il giorno\u00a0 25 Giugno dalle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/","og_site_name":"Mandela","article_published_time":"2015-06-22T14:00:42+00:00","og_image":[{"width":558,"height":400,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2015\/06\/zanzara-tigre-1.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"AVVISO DISINFESTAZIONE","datePublished":"2015-06-22T14:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/"},"wordCount":50,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2015\/06\/zanzara-tigre-1.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/","url":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/","name":"AVVISO DISINFESTAZIONE - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2015\/06\/zanzara-tigre-1.jpg","datePublished":"2015-06-22T14:00:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2015\/06\/zanzara-tigre-1.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2015\/06\/zanzara-tigre-1.jpg","width":558,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2015\/06\/22\/avviso-disinfestazione-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"AVVISO DISINFESTAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=229"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/229\/revisions"}],"predecessor-version":[{"id":231,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/229\/revisions\/231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/230"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}