{"id":2402,"date":"2021-01-05T19:21:31","date_gmt":"2021-01-05T18:21:31","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2402"},"modified":"2021-01-05T19:21:31","modified_gmt":"2021-01-05T18:21:31","slug":"fornitura-idrica-calo-pressione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/","title":{"rendered":"Fornitura Idrica &#8211; Calo pressione"},"content":{"rendered":"<p>Poco fa \u00e8 stata segnalato il calo di pressione dell&#8217;acqua, con conseguente riduzione del flusso idrico in alcune abitazioni di Mandela.<\/p>\n<p>Stiamo provvedendo a verificare la conduttura idrica e i serbatoi per cercare di individuare da dove nasce la problematica.<\/p>\n<p>Non appena riusciremo ad avere informazioni in merito sar\u00e0 data pronta comunicazione<\/p>\n<p>ci scusiamo per il disagio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poco fa \u00e8 stata segnalato il calo di pressione dell&#8217;acqua, con conseguente riduzione del flusso idrico in alcune abitazioni di Mandela. Stiamo provvedendo a verificare la conduttura idrica e i [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":2403,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fornitura Idrica - Calo pressione - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fornitura Idrica - Calo pressione - Mandela\" \/>\n<meta property=\"og:description\" content=\"Poco fa \u00e8 stata segnalato il calo di pressione dell&#8217;acqua, con conseguente riduzione del flusso idrico in alcune abitazioni di Mandela. Stiamo provvedendo a verificare la conduttura idrica e i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-05T18:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/riduzione-pressione.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"Fornitura Idrica &#8211; Calo pressione\",\"datePublished\":\"2021-01-05T18:21:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/\"},\"wordCount\":61,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/riduzione-pressione.jpeg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/\",\"name\":\"Fornitura Idrica - Calo pressione - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/riduzione-pressione.jpeg\",\"datePublished\":\"2021-01-05T18:21:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/riduzione-pressione.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/riduzione-pressione.jpeg\",\"width\":630,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/05\\\/fornitura-idrica-calo-pressione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fornitura Idrica &#8211; Calo pressione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fornitura Idrica - Calo pressione - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/","og_locale":"it_IT","og_type":"article","og_title":"Fornitura Idrica - Calo pressione - Mandela","og_description":"Poco fa \u00e8 stata segnalato il calo di pressione dell&#8217;acqua, con conseguente riduzione del flusso idrico in alcune abitazioni di Mandela. Stiamo provvedendo a verificare la conduttura idrica e i [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/","og_site_name":"Mandela","article_published_time":"2021-01-05T18:21:31+00:00","og_image":[{"width":630,"height":315,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/riduzione-pressione.jpeg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"Fornitura Idrica &#8211; Calo pressione","datePublished":"2021-01-05T18:21:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/"},"wordCount":61,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/riduzione-pressione.jpeg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/","name":"Fornitura Idrica - Calo pressione - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/riduzione-pressione.jpeg","datePublished":"2021-01-05T18:21:31+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/riduzione-pressione.jpeg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/riduzione-pressione.jpeg","width":630,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/05\/fornitura-idrica-calo-pressione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"Fornitura Idrica &#8211; Calo pressione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2402"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2402\/revisions"}],"predecessor-version":[{"id":2404,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2402\/revisions\/2404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/2403"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}