{"id":2467,"date":"2021-01-22T14:58:19","date_gmt":"2021-01-22T13:58:19","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2467"},"modified":"2021-01-22T14:58:19","modified_gmt":"2021-01-22T13:58:19","slug":"mandela-sviluppo-nuova-fermata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/","title":{"rendered":"MANDELA SVILUPPO &#8211; NUOVA FERMATA"},"content":{"rendered":"<p>Circa due anni fa l\u2019Amministrazione ha intrapreso un percorso con la Citt\u00e0 Metropolitana, Regione e Cotral, per l\u2019istituzione di una ulteriore fermata Cotral a Mandela, in prossimit\u00e0 di Colle Cappellino (1\u00b0 ingresso), a servizio dei cittadini residenti nella zona.<\/p>\n<p>Dopo una serie di difficolt\u00e0 e prescrizioni tecniche per mettere in sicurezza l\u2019area, indicazioni a cui l\u2019Amministrazione ha provveduto al fine di avere pareri positivi per la nuova fermata, finalmente<strong>, <span style=\"color: #000080\">da qualche giorno, la Nuova \u00a0fermata COTRAL di Via San Cosimato Sp36a (altezza 1 ingresso Colle Cappellino) \u00e8 ufficialmente operativa.<\/span><\/strong><\/p>\n<p><span style=\"color: #000080\"><strong><u>La fermata ha funzione di Capolinea per la sola corsa delle ore 07:20 (corsa Studenti)<\/u><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circa due anni fa l\u2019Amministrazione ha intrapreso un percorso con la Citt\u00e0 Metropolitana, Regione e Cotral, per l\u2019istituzione di una ulteriore fermata Cotral a Mandela, in prossimit\u00e0 di Colle Cappellino [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":2468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANDELA SVILUPPO - NUOVA FERMATA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANDELA SVILUPPO - NUOVA FERMATA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Circa due anni fa l\u2019Amministrazione ha intrapreso un percorso con la Citt\u00e0 Metropolitana, Regione e Cotral, per l\u2019istituzione di una ulteriore fermata Cotral a Mandela, in prossimit\u00e0 di Colle Cappellino [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-22T13:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/cotral-implementazione.png\" \/>\n\t<meta property=\"og:image:width\" content=\"568\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"MANDELA SVILUPPO &#8211; NUOVA FERMATA\",\"datePublished\":\"2021-01-22T13:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/\"},\"wordCount\":110,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/cotral-implementazione.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/\",\"name\":\"MANDELA SVILUPPO - NUOVA FERMATA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/cotral-implementazione.png\",\"datePublished\":\"2021-01-22T13:58:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/cotral-implementazione.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/01\\\/cotral-implementazione.png\",\"width\":568,\"height\":348},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/01\\\/22\\\/mandela-sviluppo-nuova-fermata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANDELA SVILUPPO &#8211; NUOVA FERMATA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANDELA SVILUPPO - NUOVA FERMATA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/","og_locale":"it_IT","og_type":"article","og_title":"MANDELA SVILUPPO - NUOVA FERMATA - Mandela","og_description":"Circa due anni fa l\u2019Amministrazione ha intrapreso un percorso con la Citt\u00e0 Metropolitana, Regione e Cotral, per l\u2019istituzione di una ulteriore fermata Cotral a Mandela, in prossimit\u00e0 di Colle Cappellino [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/","og_site_name":"Mandela","article_published_time":"2021-01-22T13:58:19+00:00","og_image":[{"width":568,"height":348,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/cotral-implementazione.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"MANDELA SVILUPPO &#8211; NUOVA FERMATA","datePublished":"2021-01-22T13:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/"},"wordCount":110,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/cotral-implementazione.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/","name":"MANDELA SVILUPPO - NUOVA FERMATA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/cotral-implementazione.png","datePublished":"2021-01-22T13:58:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/cotral-implementazione.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/01\/cotral-implementazione.png","width":568,"height":348},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/01\/22\/mandela-sviluppo-nuova-fermata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"MANDELA SVILUPPO &#8211; NUOVA FERMATA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2467"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2467\/revisions"}],"predecessor-version":[{"id":2469,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2467\/revisions\/2469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/2468"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}