{"id":2523,"date":"2021-02-16T16:14:20","date_gmt":"2021-02-16T15:14:20","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2523"},"modified":"2021-02-16T16:14:20","modified_gmt":"2021-02-16T15:14:20","slug":"manutenzione-selciato-via-roma","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/","title":{"rendered":"MANUTENZIONE SELCIATO VIA ROMA"},"content":{"rendered":"<p style=\"text-align: center\">Si informa la cittadinanza che domani mattina 17 febbraio dalle ore 08:00 fino alla fine dei lavori, <strong>sar\u00e0 vietato il passaggio degli autoveicoli in Via La Bastidonne e Via Roma<\/strong> per una manutenzione straordinaria del selciato stradale (ordinanza n.3\/2021).<\/p>\n<p>Ci scusiamo per il disagio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa la cittadinanza che domani mattina 17 febbraio dalle ore 08:00 fino alla fine dei lavori, sar\u00e0 vietato il passaggio degli autoveicoli in Via La Bastidonne e Via Roma [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":2524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANUTENZIONE SELCIATO VIA ROMA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANUTENZIONE SELCIATO VIA ROMA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa la cittadinanza che domani mattina 17 febbraio dalle ore 08:00 fino alla fine dei lavori, sar\u00e0 vietato il passaggio degli autoveicoli in Via La Bastidonne e Via Roma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-16T15:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/02\/selciato.png\" \/>\n\t<meta property=\"og:image:width\" content=\"204\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"MANUTENZIONE SELCIATO VIA ROMA\",\"datePublished\":\"2021-02-16T15:14:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/\"},\"wordCount\":46,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/02\\\/selciato.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/\",\"name\":\"MANUTENZIONE SELCIATO VIA ROMA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/02\\\/selciato.png\",\"datePublished\":\"2021-02-16T15:14:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/02\\\/selciato.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/02\\\/selciato.png\",\"width\":204,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/02\\\/16\\\/manutenzione-selciato-via-roma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANUTENZIONE SELCIATO VIA ROMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANUTENZIONE SELCIATO VIA ROMA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/","og_locale":"it_IT","og_type":"article","og_title":"MANUTENZIONE SELCIATO VIA ROMA - Mandela","og_description":"Si informa la cittadinanza che domani mattina 17 febbraio dalle ore 08:00 fino alla fine dei lavori, sar\u00e0 vietato il passaggio degli autoveicoli in Via La Bastidonne e Via Roma [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/","og_site_name":"Mandela","article_published_time":"2021-02-16T15:14:20+00:00","og_image":[{"width":204,"height":512,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/02\/selciato.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"MANUTENZIONE SELCIATO VIA ROMA","datePublished":"2021-02-16T15:14:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/"},"wordCount":46,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/02\/selciato.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/","name":"MANUTENZIONE SELCIATO VIA ROMA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/02\/selciato.png","datePublished":"2021-02-16T15:14:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/02\/selciato.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/02\/selciato.png","width":204,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/02\/16\/manutenzione-selciato-via-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"MANUTENZIONE SELCIATO VIA ROMA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2523"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2523\/revisions"}],"predecessor-version":[{"id":2525,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2523\/revisions\/2525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/2524"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}