{"id":2642,"date":"2021-04-06T16:34:35","date_gmt":"2021-04-06T14:34:35","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2642"},"modified":"2021-04-06T16:34:35","modified_gmt":"2021-04-06T14:34:35","slug":"mandela-sviluppo-pensilina-fermata-cotral","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/","title":{"rendered":"MANDELA SVILUPPO &#8211; PENSILINA FERMATA COTRAL"},"content":{"rendered":"<p>Si informa che nell\u2019ambito del progetto per il miglioramento del servizio di trasporto pubblico a servizio dei cittadini residenti, l\u2019Amministrazione comunale ha fatto installare una nuova <strong>Pensilina a servizio della fermata Cotral<\/strong> sulla via Tiburtina al km 50.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che nell\u2019ambito del progetto per il miglioramento del servizio di trasporto pubblico a servizio dei cittadini residenti, l\u2019Amministrazione comunale ha fatto installare una nuova Pensilina a servizio della [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":2643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANDELA SVILUPPO - PENSILINA FERMATA COTRAL - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANDELA SVILUPPO - PENSILINA FERMATA COTRAL - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa che nell\u2019ambito del progetto per il miglioramento del servizio di trasporto pubblico a servizio dei cittadini residenti, l\u2019Amministrazione comunale ha fatto installare una nuova Pensilina a servizio della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-06T14:34:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/04\/pensilina-tiburtina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"643\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"MANDELA SVILUPPO &#8211; PENSILINA FERMATA COTRAL\",\"datePublished\":\"2021-04-06T14:34:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/\"},\"wordCount\":45,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/04\\\/pensilina-tiburtina.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/\",\"name\":\"MANDELA SVILUPPO - PENSILINA FERMATA COTRAL - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/04\\\/pensilina-tiburtina.png\",\"datePublished\":\"2021-04-06T14:34:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/04\\\/pensilina-tiburtina.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/04\\\/pensilina-tiburtina.png\",\"width\":643,\"height\":482},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/04\\\/06\\\/mandela-sviluppo-pensilina-fermata-cotral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANDELA SVILUPPO &#8211; PENSILINA FERMATA COTRAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANDELA SVILUPPO - PENSILINA FERMATA COTRAL - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/","og_locale":"it_IT","og_type":"article","og_title":"MANDELA SVILUPPO - PENSILINA FERMATA COTRAL - Mandela","og_description":"Si informa che nell\u2019ambito del progetto per il miglioramento del servizio di trasporto pubblico a servizio dei cittadini residenti, l\u2019Amministrazione comunale ha fatto installare una nuova Pensilina a servizio della [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/","og_site_name":"Mandela","article_published_time":"2021-04-06T14:34:35+00:00","og_image":[{"width":643,"height":482,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/04\/pensilina-tiburtina.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"MANDELA SVILUPPO &#8211; PENSILINA FERMATA COTRAL","datePublished":"2021-04-06T14:34:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/"},"wordCount":45,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/04\/pensilina-tiburtina.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/","name":"MANDELA SVILUPPO - PENSILINA FERMATA COTRAL - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/04\/pensilina-tiburtina.png","datePublished":"2021-04-06T14:34:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/04\/pensilina-tiburtina.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/04\/pensilina-tiburtina.png","width":643,"height":482},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/04\/06\/mandela-sviluppo-pensilina-fermata-cotral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"MANDELA SVILUPPO &#8211; PENSILINA FERMATA COTRAL"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2642"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2642\/revisions"}],"predecessor-version":[{"id":2644,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2642\/revisions\/2644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/2643"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}