{"id":2769,"date":"2021-05-19T15:48:19","date_gmt":"2021-05-19T13:48:19","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2769"},"modified":"2021-05-19T15:48:19","modified_gmt":"2021-05-19T13:48:19","slug":"prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/","title":{"rendered":"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 &#8211; ANNI DAL 1974 AL 1977"},"content":{"rendered":"<h3 class=\"titolo_evidenziato\" style=\"text-align: center\">PRENOTAZIONI DELLE VACCINAZIONI ANTI COVID-19 PER FASCE D&#8217;ET\u00c0:<\/h3>\n<h3 class=\"titolo_evidenziato\" style=\"text-align: center\">AL VIA DA VENERD\u00cc 21 MAGGIO 2021 ALLE 00.00 ET\u00c0 44-47 ANNI<\/h3>\n<h3 class=\"titolo_evidenziato\" style=\"text-align: center\"><strong>(anni di nascita dal 1974\u00a0al\u00a01977)<\/strong><\/h3>\n<p>L&#8217;adesione alla vaccinazione \u00e8 libera e volontaria.<br \/>\nPossono prenotare la vaccinazione le persone assistite dal Servizio Sanitario Regionale (SSR) della Regione Lazio, ovvero tutti coloro che sono assistiti da un medico di famiglia convenzionato con il SSR della Regione Lazio.<\/p>\n<p>Per prenotare \u00e8 sufficiente la Tessera sanitaria.<\/p>\n<p>Per prenotare occorre la Tessera Sanitaria in corso di validit\u00e0 per comunicare:<\/p>\n<p>1. Il Codice Fiscale<br \/>\n2. Le ultime 13 cifre del codice numerico (TEAM)\u00a0posto sul retro della tessera<\/p>\n<div><img decoding=\"async\" title=\"Tessera sanitaria\" src=\"https:\/\/www.salutelazio.it\/documents\/10182\/58937266\/03_retro-tessera-sanitaria.png\/67103fbd-02e8-5217-b915-bc0192fcbb48?t=1613225950668\" alt=\"\" \/><\/div>\n<div><\/div>\n<p>Con la prenotazione del primo appuntamento sar\u00e0 automaticamente prenotato anche il richiamo, se previsto, da effettuare sempre nella stessa sede. 72 ore prima dell&#8217;appuntamento prenotato, un SMS ricorder\u00e0 l&#8217;appuntamento fissato.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRENOTAZIONI DELLE VACCINAZIONI ANTI COVID-19 PER FASCE D&#8217;ET\u00c0: AL VIA DA VENERD\u00cc 21 MAGGIO 2021 ALLE 00.00 ET\u00c0 44-47 ANNI (anni di nascita dal 1974\u00a0al\u00a01977) L&#8217;adesione alla vaccinazione \u00e8 libera [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":2770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRENOTAZIONE VACCINAZIONI ANTI COVID 19 - ANNI DAL 1974 AL 1977 - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 - ANNI DAL 1974 AL 1977 - Mandela\" \/>\n<meta property=\"og:description\" content=\"PRENOTAZIONI DELLE VACCINAZIONI ANTI COVID-19 PER FASCE D&#8217;ET\u00c0: AL VIA DA VENERD\u00cc 21 MAGGIO 2021 ALLE 00.00 ET\u00c0 44-47 ANNI (anni di nascita dal 1974\u00a0al\u00a01977) L&#8217;adesione alla vaccinazione \u00e8 libera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T13:48:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/05\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"296\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 &#8211; ANNI DAL 1974 AL 1977\",\"datePublished\":\"2021-05-19T13:48:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/\"},\"wordCount\":132,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/05\\\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/\",\"name\":\"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 - ANNI DAL 1974 AL 1977 - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/05\\\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png\",\"datePublished\":\"2021-05-19T13:48:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/05\\\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/05\\\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png\",\"width\":1140,\"height\":296},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/05\\\/19\\\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 &#8211; ANNI DAL 1974 AL 1977\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 - ANNI DAL 1974 AL 1977 - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/","og_locale":"it_IT","og_type":"article","og_title":"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 - ANNI DAL 1974 AL 1977 - Mandela","og_description":"PRENOTAZIONI DELLE VACCINAZIONI ANTI COVID-19 PER FASCE D&#8217;ET\u00c0: AL VIA DA VENERD\u00cc 21 MAGGIO 2021 ALLE 00.00 ET\u00c0 44-47 ANNI (anni di nascita dal 1974\u00a0al\u00a01977) L&#8217;adesione alla vaccinazione \u00e8 libera [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/","og_site_name":"Mandela","article_published_time":"2021-05-19T13:48:19+00:00","og_image":[{"width":1140,"height":296,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/05\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 &#8211; ANNI DAL 1974 AL 1977","datePublished":"2021-05-19T13:48:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/"},"wordCount":132,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/05\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/","name":"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 - ANNI DAL 1974 AL 1977 - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/05\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png","datePublished":"2021-05-19T13:48:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/05\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/05\/00_PRIMU_17_fasce_eta_44_47_img_18_05.png","width":1140,"height":296},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/05\/19\/prenotazione-vaccinazioni-anti-covid-19-anni-dal-1974-al-1977\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"PRENOTAZIONE VACCINAZIONI ANTI COVID 19 &#8211; ANNI DAL 1974 AL 1977"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2769"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2769\/revisions"}],"predecessor-version":[{"id":2771,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2769\/revisions\/2771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/2770"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}