{"id":288,"date":"2016-02-15T14:34:11","date_gmt":"2016-02-15T13:34:11","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=288"},"modified":"2016-02-15T14:40:30","modified_gmt":"2016-02-15T13:40:30","slug":"avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/","title":{"rendered":"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16"},"content":{"rendered":"<p>Si avvisa la cittadinanza che sono previsti dei lavori di manutenzione sulla rete elettrica dell&#8217;ENEL per Mercoledi 17.2.16 dalle ore 8 alle 16.00 .<\/p>\n<p>Verificare se la propia abitazione rientra nella zona dove potrebbero esserci delle interuzioni come descritte nell&#8217;allegato.<\/p>\n<p>Si prega prendere le dovute accortezze in merito<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si avvisa la cittadinanza che sono previsti dei lavori di manutenzione sulla rete elettrica dell&#8217;ENEL per Mercoledi 17.2.16 dalle ore 8 alle 16.00 . Verificare se la propia abitazione rientra [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-288","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16 - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16 - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si avvisa la cittadinanza che sono previsti dei lavori di manutenzione sulla rete elettrica dell&#8217;ENEL per Mercoledi 17.2.16 dalle ore 8 alle 16.00 . Verificare se la propia abitazione rientra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-15T13:34:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-15T13:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16\",\"datePublished\":\"2016-02-15T13:34:11+00:00\",\"dateModified\":\"2016-02-15T13:40:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/\"},\"wordCount\":51,\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/\",\"name\":\"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16 - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"datePublished\":\"2016-02-15T13:34:11+00:00\",\"dateModified\":\"2016-02-15T13:40:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/02\\\/15\\\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16 - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16 - Mandela","og_description":"Si avvisa la cittadinanza che sono previsti dei lavori di manutenzione sulla rete elettrica dell&#8217;ENEL per Mercoledi 17.2.16 dalle ore 8 alle 16.00 . Verificare se la propia abitazione rientra [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/","og_site_name":"Mandela","article_published_time":"2016-02-15T13:34:11+00:00","article_modified_time":"2016-02-15T13:40:30+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16","datePublished":"2016-02-15T13:34:11+00:00","dateModified":"2016-02-15T13:40:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/"},"wordCount":51,"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/","url":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/","name":"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16 - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"datePublished":"2016-02-15T13:34:11+00:00","dateModified":"2016-02-15T13:40:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2016\/02\/15\/avviso-mancanza-energia-elettrica-per-il-giorno-17-2-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"AVVISO MANCANZA ENERGIA ELETTRICA PER IL GIORNO 17.2.16"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=288"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/288\/revisions"}],"predecessor-version":[{"id":290,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/288\/revisions\/290"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}