{"id":2958,"date":"2021-09-15T12:15:13","date_gmt":"2021-09-15T10:15:13","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=2958"},"modified":"2021-09-15T12:30:34","modified_gmt":"2021-09-15T10:30:34","slug":"servizio-di-trasporto-scolastico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/","title":{"rendered":"SERVIZIO DI TRASPORTO SCOLASTICO"},"content":{"rendered":"<p>Si informa che nel corso di questa settimana tutti i controlli di legge \u2013 Revisioni e Collaudi &#8211; \u00a0previsti per il mezzo dedicato al trasporto scolastico dei ragazzi, saranno ultimati.<\/p>\n<p>A partire <strong><u>da luned\u00ec prossimo 20 settembre inizier\u00e0 il servizio SCUOLABUS<\/u><\/strong> per gli alunni della Scuola elementare di Mandela e per gli alunni della Scuola media di Vicovaro.<\/p>\n<p>Lo scuolabus seguir\u00e0 i seguenti orari di passaggio per il trasporto:<\/p>\n<ul>\n<li>Alunni Scuola media:\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 a partire dalle ore 07:35<\/li>\n<li>Alunni Scuola elementare: a partire dalle ore 08:05<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5>Le iscrizioni per il servizio di trasporto scolastico resteranno aperte fino a venerd\u00ec prossimo.<\/h5>\n<h5>Coloro che hanno gi\u00e0 effettuato l\u2019iscrizione possono effettuare il pagamento direttamente presso gli uffici comunali<\/h5>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che nel corso di questa settimana tutti i controlli di legge \u2013 Revisioni e Collaudi &#8211; \u00a0previsti per il mezzo dedicato al trasporto scolastico dei ragazzi, saranno ultimati. [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZIO DI TRASPORTO SCOLASTICO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZIO DI TRASPORTO SCOLASTICO - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa che nel corso di questa settimana tutti i controlli di legge \u2013 Revisioni e Collaudi &#8211; \u00a0previsti per il mezzo dedicato al trasporto scolastico dei ragazzi, saranno ultimati. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-15T10:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-15T10:30:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"605\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"SERVIZIO DI TRASPORTO SCOLASTICO\",\"datePublished\":\"2021-09-15T10:15:13+00:00\",\"dateModified\":\"2021-09-15T10:30:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/\"},\"wordCount\":117,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/\",\"name\":\"SERVIZIO DI TRASPORTO SCOLASTICO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"datePublished\":\"2021-09-15T10:15:13+00:00\",\"dateModified\":\"2021-09-15T10:30:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/10\\\/SCUOLABUS-OK-1.jpg\",\"width\":605,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/09\\\/15\\\/servizio-di-trasporto-scolastico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZIO DI TRASPORTO SCOLASTICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZIO DI TRASPORTO SCOLASTICO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZIO DI TRASPORTO SCOLASTICO - Mandela","og_description":"Si informa che nel corso di questa settimana tutti i controlli di legge \u2013 Revisioni e Collaudi &#8211; \u00a0previsti per il mezzo dedicato al trasporto scolastico dei ragazzi, saranno ultimati. [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/","og_site_name":"Mandela","article_published_time":"2021-09-15T10:15:13+00:00","article_modified_time":"2021-09-15T10:30:34+00:00","og_image":[{"width":605,"height":454,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"SERVIZIO DI TRASPORTO SCOLASTICO","datePublished":"2021-09-15T10:15:13+00:00","dateModified":"2021-09-15T10:30:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/"},"wordCount":117,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/","name":"SERVIZIO DI TRASPORTO SCOLASTICO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","datePublished":"2021-09-15T10:15:13+00:00","dateModified":"2021-09-15T10:30:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/10\/SCUOLABUS-OK-1.jpg","width":605,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/09\/15\/servizio-di-trasporto-scolastico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"SERVIZIO DI TRASPORTO SCOLASTICO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=2958"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2958\/revisions"}],"predecessor-version":[{"id":2959,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/2958\/revisions\/2959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/673"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=2958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=2958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=2958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}