{"id":3054,"date":"2021-11-11T11:33:18","date_gmt":"2021-11-11T10:33:18","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=3054"},"modified":"2021-11-11T11:33:18","modified_gmt":"2021-11-11T10:33:18","slug":"riparazione-conduttura-idrica-21","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/","title":{"rendered":"RIPARAZIONE CONDUTTURA IDRICA"},"content":{"rendered":"<p style=\"text-align: center\">Si comunica che<\/p>\n<p style=\"text-align: center\"><strong>domani VENERDI&#8217; 12 NOVEMBRE a partire dalle ore 08:00<\/strong><\/p>\n<p>si effettueranno lavori di riparazione della conduttura idrica, nell&#8217;area di Via delle Vignette<\/p>\n<p><span style=\"color: #000080\"><strong>Durante i lavori potrebbe essere\u00a0 necessario interrompere il flusso idrico nella zona di Via San Cosimato e Colle Cappellino<\/strong><\/span><\/p>\n<p>Ci scusiamo per il disagio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che domani VENERDI&#8217; 12 NOVEMBRE a partire dalle ore 08:00 si effettueranno lavori di riparazione della conduttura idrica, nell&#8217;area di Via delle Vignette Durante i lavori potrebbe essere\u00a0 [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":1182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIPARAZIONE CONDUTTURA IDRICA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIPARAZIONE CONDUTTURA IDRICA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si comunica che domani VENERDI&#8217; 12 NOVEMBRE a partire dalle ore 08:00 si effettueranno lavori di riparazione della conduttura idrica, nell&#8217;area di Via delle Vignette Durante i lavori potrebbe essere\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T10:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/01\/CONDUTTURA-IDRICA-LAVORI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"714\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"RIPARAZIONE CONDUTTURA IDRICA\",\"datePublished\":\"2021-11-11T10:33:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/\"},\"wordCount\":50,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/01\\\/CONDUTTURA-IDRICA-LAVORI.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/\",\"name\":\"RIPARAZIONE CONDUTTURA IDRICA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/01\\\/CONDUTTURA-IDRICA-LAVORI.png\",\"datePublished\":\"2021-11-11T10:33:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/01\\\/CONDUTTURA-IDRICA-LAVORI.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/01\\\/CONDUTTURA-IDRICA-LAVORI.png\",\"width\":714,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2021\\\/11\\\/11\\\/riparazione-conduttura-idrica-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIPARAZIONE CONDUTTURA IDRICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIPARAZIONE CONDUTTURA IDRICA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/","og_locale":"it_IT","og_type":"article","og_title":"RIPARAZIONE CONDUTTURA IDRICA - Mandela","og_description":"Si comunica che domani VENERDI&#8217; 12 NOVEMBRE a partire dalle ore 08:00 si effettueranno lavori di riparazione della conduttura idrica, nell&#8217;area di Via delle Vignette Durante i lavori potrebbe essere\u00a0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/","og_site_name":"Mandela","article_published_time":"2021-11-11T10:33:18+00:00","og_image":[{"width":714,"height":440,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/01\/CONDUTTURA-IDRICA-LAVORI.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"RIPARAZIONE CONDUTTURA IDRICA","datePublished":"2021-11-11T10:33:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/"},"wordCount":50,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/01\/CONDUTTURA-IDRICA-LAVORI.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/","url":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/","name":"RIPARAZIONE CONDUTTURA IDRICA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/01\/CONDUTTURA-IDRICA-LAVORI.png","datePublished":"2021-11-11T10:33:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/01\/CONDUTTURA-IDRICA-LAVORI.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2019\/01\/CONDUTTURA-IDRICA-LAVORI.png","width":714,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2021\/11\/11\/riparazione-conduttura-idrica-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"RIPARAZIONE CONDUTTURA IDRICA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=3054"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3054\/revisions"}],"predecessor-version":[{"id":3055,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3054\/revisions\/3055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/1182"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=3054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=3054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=3054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}