{"id":3152,"date":"2022-01-07T09:49:52","date_gmt":"2022-01-07T08:49:52","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=3152"},"modified":"2022-01-07T09:49:52","modified_gmt":"2022-01-07T08:49:52","slug":"aggiornamento-situazione-contagi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/","title":{"rendered":"AGGIORNAMENTO SITUAZIONE CONTAGI"},"content":{"rendered":"<p><strong>Aggiornamento Situazione Contagi Covid-19<\/strong><\/p>\n<p>I dati ufficiali comunicati dalla Asl, relativi a Mandela ad oggi sono 7 casi, ma in via ufficiosa sappiamo che alcuni tamponi effettuati nelle farmacie sono risultati positivi, in attesa di essere o meno confermati da tamponi molecolari.<\/p>\n<p>Si continua a sensibilizzare tutta la popolazione a prestare attenzione e seguire le regole sanitarie previste dal protocollo per ridurre al minimo il rischio di aumento dei contagi.<\/p>\n<p><strong>______________<\/strong><\/p>\n<p>Sulla base della nuova ondata di contagi e al fine di ridurre il rischio al minimo, il Centro Sociale Anziani di Mandela rester\u00e0 chiuso fino a nuova disposizione.<\/p>\n<style>\n\t.bluebanner h4{\n\t\t padding: 20px;\n\t\tcolor: white;\n\t\tbackground-color: #013161;\n\t}\n\t.bluebanner p{\n\t\t padding: 0 30px;\n\t}\n<\/style>\n<div class=\"bluebanner\">\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Aggiornamento Situazione Contagi Covid-19 I dati ufficiali comunicati dalla Asl, relativi a Mandela ad oggi sono 7 casi, ma in via ufficiosa sappiamo che alcuni tamponi effettuati nelle farmacie sono [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":3153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-3152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergenza-coronavirus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AGGIORNAMENTO SITUAZIONE CONTAGI - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AGGIORNAMENTO SITUAZIONE CONTAGI - Mandela\" \/>\n<meta property=\"og:description\" content=\"Aggiornamento Situazione Contagi Covid-19 I dati ufficiali comunicati dalla Asl, relativi a Mandela ad oggi sono 7 casi, ma in via ufficiosa sappiamo che alcuni tamponi effettuati nelle farmacie sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-07T08:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/01\/REPORT-COVID.png\" \/>\n\t<meta property=\"og:image:width\" content=\"703\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"AGGIORNAMENTO SITUAZIONE CONTAGI\",\"datePublished\":\"2022-01-07T08:49:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/\"},\"wordCount\":100,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/01\\\/REPORT-COVID.png\",\"articleSection\":[\"Emergenza Coronavirus\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/\",\"name\":\"AGGIORNAMENTO SITUAZIONE CONTAGI - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/01\\\/REPORT-COVID.png\",\"datePublished\":\"2022-01-07T08:49:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/01\\\/REPORT-COVID.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/01\\\/REPORT-COVID.png\",\"width\":703,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/01\\\/07\\\/aggiornamento-situazione-contagi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AGGIORNAMENTO SITUAZIONE CONTAGI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AGGIORNAMENTO SITUAZIONE CONTAGI - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/","og_locale":"it_IT","og_type":"article","og_title":"AGGIORNAMENTO SITUAZIONE CONTAGI - Mandela","og_description":"Aggiornamento Situazione Contagi Covid-19 I dati ufficiali comunicati dalla Asl, relativi a Mandela ad oggi sono 7 casi, ma in via ufficiosa sappiamo che alcuni tamponi effettuati nelle farmacie sono [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/","og_site_name":"Mandela","article_published_time":"2022-01-07T08:49:52+00:00","og_image":[{"width":703,"height":555,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/01\/REPORT-COVID.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"AGGIORNAMENTO SITUAZIONE CONTAGI","datePublished":"2022-01-07T08:49:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/"},"wordCount":100,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/01\/REPORT-COVID.png","articleSection":["Emergenza Coronavirus"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/","url":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/","name":"AGGIORNAMENTO SITUAZIONE CONTAGI - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/01\/REPORT-COVID.png","datePublished":"2022-01-07T08:49:52+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/01\/REPORT-COVID.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/01\/REPORT-COVID.png","width":703,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2022\/01\/07\/aggiornamento-situazione-contagi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"AGGIORNAMENTO SITUAZIONE CONTAGI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"predecessor-version":[{"id":3154,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3152\/revisions\/3154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/3153"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}