{"id":3254,"date":"2022-03-21T10:48:30","date_gmt":"2022-03-21T09:48:30","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=3254"},"modified":"2022-03-21T10:48:30","modified_gmt":"2022-03-21T09:48:30","slug":"contagi-covid-19-12","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/","title":{"rendered":"CONTAGI COVID-19"},"content":{"rendered":"<p style=\"text-align: center\"><strong>Comunicato Contagi da Covid-19\u00a0<\/strong><\/p>\n<p><strong>I dati ufficiali aggiornati alla data odierna, comunicati dalla Asl Rm5, relativi a Mandela, sono di n\u00b0\u00a0 9\u00a0 attualmente positivi.<\/strong><\/p>\n<p>nella settimana passata sono stati registrati n\u00b0 4 nuovi positivi e n\u00b0 2\u00a0 nuovi negativi\u00a0 (7 + 4 &#8211; 2 = tot 9).<\/p>\n<p>La situazione contagi registra anche questa settimana un lieve aumento dei positivi rispetto alla precedente, continuiamo a prestare la massima attenzione e seguire le regole sanitarie previste dal protocollo per ridurre al minimo il rischio di aumento dei contagi.<\/p>\n<p>Grazie della collaborazione<\/p>\n<style>\n\t.bluebanner h4{\n\t\t padding: 20px;\n\t\tcolor: white;\n\t\tbackground-color: #013161;\n\t}\n\t.bluebanner p{\n\t\t padding: 0 30px;\n\t}\n<\/style>\n<div class=\"bluebanner\">\n\t\t\t\t<h4>\n\t\t\tAggiornamento dati totali\n\t\t<\/h4>\n\t\t\t\t\t<p>Attualmente positivi: <b>9<\/b><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Comunicato Contagi da Covid-19\u00a0 I dati ufficiali aggiornati alla data odierna, comunicati dalla Asl Rm5, relativi a Mandela, sono di n\u00b0\u00a0 9\u00a0 attualmente positivi. nella settimana passata sono stati registrati [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":2599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-3254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergenza-coronavirus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONTAGI COVID-19 - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONTAGI COVID-19 - Mandela\" \/>\n<meta property=\"og:description\" content=\"Comunicato Contagi da Covid-19\u00a0 I dati ufficiali aggiornati alla data odierna, comunicati dalla Asl Rm5, relativi a Mandela, sono di n\u00b0\u00a0 9\u00a0 attualmente positivi. nella settimana passata sono stati registrati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-21T09:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/03\/positivi-covid.png\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"207\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"CONTAGI COVID-19\",\"datePublished\":\"2022-03-21T09:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/\"},\"wordCount\":82,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/positivi-covid.png\",\"articleSection\":[\"Emergenza Coronavirus\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/\",\"name\":\"CONTAGI COVID-19 - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/positivi-covid.png\",\"datePublished\":\"2022-03-21T09:48:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/positivi-covid.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/positivi-covid.png\",\"width\":420,\"height\":207},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/21\\\/contagi-covid-19-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONTAGI COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONTAGI COVID-19 - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/","og_locale":"it_IT","og_type":"article","og_title":"CONTAGI COVID-19 - Mandela","og_description":"Comunicato Contagi da Covid-19\u00a0 I dati ufficiali aggiornati alla data odierna, comunicati dalla Asl Rm5, relativi a Mandela, sono di n\u00b0\u00a0 9\u00a0 attualmente positivi. nella settimana passata sono stati registrati [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/","og_site_name":"Mandela","article_published_time":"2022-03-21T09:48:30+00:00","og_image":[{"width":420,"height":207,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/03\/positivi-covid.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"CONTAGI COVID-19","datePublished":"2022-03-21T09:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/"},"wordCount":82,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/03\/positivi-covid.png","articleSection":["Emergenza Coronavirus"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/","url":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/","name":"CONTAGI COVID-19 - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/03\/positivi-covid.png","datePublished":"2022-03-21T09:48:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/03\/positivi-covid.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2021\/03\/positivi-covid.png","width":420,"height":207},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/21\/contagi-covid-19-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"CONTAGI COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"9","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=3254"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3254\/revisions"}],"predecessor-version":[{"id":3255,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3254\/revisions\/3255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/2599"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=3254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=3254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=3254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}