{"id":3267,"date":"2022-03-28T14:32:59","date_gmt":"2022-03-28T12:32:59","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=3267"},"modified":"2022-03-28T14:32:59","modified_gmt":"2022-03-28T12:32:59","slug":"covid-19-superamento-della-fase-emergenziale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/","title":{"rendered":"COVID-19 &#8211; SUPERAMENTO DELLA FASE EMERGENZIALE"},"content":{"rendered":"<p style=\"text-align: center\">Decreto Legge del 24 marzo 2022, n.24<\/p>\n<p style=\"text-align: center\"><strong>COVID-19 SUPERAMENTO DELLA FASE EMERGENZIALE;<\/strong><\/p>\n<p style=\"text-align: center\">Del sistema delle zone colorate, del green pass in maniera graduale ed eliminazione delle quarantene precauzionali<\/p>\n<p style=\"text-align: center\"><span style=\"color: #800000\"><strong>31 MARZO 2022\u00a0 &#8211; FINE DELLO STATO DI EMERGENZA<\/strong><\/span><\/p>\n<p><strong>GREEN PASS \u2013 MAPPATURA DEI COLORI \u2013 STRUTTURA COMMISSARIALE E CTS<\/strong><\/p>\n<ul>\n<li>Dal 1\u00b0 aprile il green pass sar\u00e0 abolito all&#8217;aperto tranne che per\u00a0\u00a0 eventi\u00a0\u00a0 e\u00a0\u00a0 competizioni\u00a0\u00a0 sportive\u00a0\u00a0 dove\u00a0 c&#8217;\u00e8 assembramento (es. stadi e concerti).<\/li>\n<li>Dal 1\u00b0 maggio il green pass non sar\u00e0 pi\u00f9 necessario.<\/li>\n<li>Dal 1\u00b0 aprile verr\u00e0 eliminato il sistema di classificazione delle Regioni basato sulle zone-colore.<\/li>\n<li>Dal 1\u00b0 aprile decadenza della struttura commissariale e Cts del Comitato Tecnico Scientifico e cessazione dei poteri emergenziali al capo della protezione civile.<\/li>\n<li>Dal 1\u00b0 aprile e fino al 31 dicembre 2022 verr\u00e0 istituita una Unit\u00e0 per il completamento della campagna vaccinale e per l\u2019adozione di altre misure di contrasto alla pandemia presso il Ministero della Difesa.<\/li>\n<li>Verranno adottati eventuali protocolli e linee guida con ordinanza del Ministro della salute.<\/li>\n<\/ul>\n<p><strong>GREEN PASS BASE<\/strong><\/p>\n<p>Dal 1\u00b0 aprile al 30 aprile, \u00e8 consentito l&#8217;accesso ai seguenti servizi e attivit\u00e0, con green pass base:<\/p>\n<ul>\n<li>ristoranti e bar al chiuso (anche al banco);<\/li>\n<li>mense;<\/li>\n<li>concorsi pubblici;<\/li>\n<li>corsi di formazione pubblici e privati;<\/li>\n<li>partecipazione a spettacoli aperti al pubblico, eventi e competizioni sportivi che si svolgono all&#8217;aperto;<\/li>\n<\/ul>\n<p>Dal 1\u00b0 al 30 aprile, \u00e8 consentito l&#8217;accesso ai seguenti mezzi di trasporto e il loro utilizzo:<\/p>\n<ul>\n<li>aerei;<\/li>\n<li>navi e traghetti adibiti a servizi di trasporto interregionale;<\/li>\n<li>treni a lunga percorrenza (Intercity,\u00a0 Intercity\u00a0 Notte\u00a0 e\u00a0 Alta Velocit\u00e0);<\/li>\n<li>autobus interregionali e autobus adibiti a servizi di noleggio con conducente.<\/li>\n<\/ul>\n<p><u>Dal 1\u00b0 maggio il Green Pass non \u00e8 pi\u00f9 necessario.<\/u><\/p>\n<p><strong>GREEN PASS RAFFORZATO<\/strong><\/p>\n<p>Dal 1\u00b0 aprile al 30 aprile, \u00e8\u00a0 consentito\u00a0 l&#8217;accesso\u00a0 ai seguenti servizi al chiuso con green pass rafforzato:<\/p>\n<ul>\n<li>piscine, centri natatori, palestre, sport di squadra e di contatto e centri benessere;<\/li>\n<li>convegni e congressi;<\/li>\n<li>centri culturali, centri sociali e ricreativi;<\/li>\n<li>feste conseguenti e non conseguenti alle cerimonie civili o religiose, nonch\u00e9 eventi assimilati;<\/li>\n<li>attivit\u00e0 di sale gioco, sale scommesse, sale bingo e casin\u00f2;<\/li>\n<li>attivit\u00e0 che abbiano luogo in sale da ballo, discoteche e locali assimilati;<\/li>\n<li>partecipazione del pubblico agli spettacoli aperti al pubblico, eventi e alle competizioni sportivi, che si svolgono al chiuso<\/li>\n<\/ul>\n<p><strong>MASCHERINE<\/strong><\/p>\n<p>Fino al 30 aprile obbligo di mascherine ffp2 negli ambienti al chiuso:<\/p>\n<ol>\n<li>a) per l&#8217;accesso ai mezzi di trasporto:<\/li>\n<\/ol>\n<ul>\n<li>aerei;<\/li>\n<li>navi e traghetti interregionali;<\/li>\n<li>treni interregionali (intercity, intercity notte e Alta velocit\u00e0);<\/li>\n<li>autobus interregionali, a noleggio con conducente;<\/li>\n<li>mezzi di trasporto\u00a0 pubblico\u00a0 locale \u00a0 (TPL)\u00a0 o\u00a0 regionale\u00a0 e mezzi\u00a0 di\u00a0 trasporto\u00a0 scolastico\u00a0 di\u00a0 studenti\u00a0 di\u00a0 primaria, \u00a0secondaria di primo e secondo grado.<\/li>\n<\/ul>\n<ol>\n<li>b) per gli spettacoli aperti al pubblico che si svolgono:<\/li>\n<\/ol>\n<ul>\n<li>sale teatrali, sale da concerto e sale cinematografiche;<\/li>\n<li>locali di\u00a0 intrattenimento\u00a0 e\u00a0 musica\u00a0 dal\u00a0 vivo,\u00a0 sale\u00a0 da\u00a0 ballo, discoteche;<\/li>\n<li>eventi e competizioni sportive (es. stadi).<\/li>\n<\/ul>\n<p><u>Fino al 30 di\u00a0 aprile\u00a0 obbligo\u00a0 di\u00a0 indossare\u00a0 le\u00a0 mascherine chirurgiche nei luoghi di lavoro e in tutti gli altri luoghi al chiuso.<\/u><\/p>\n<p><strong>SCUOLE E QUARANTENE<\/strong><\/p>\n<p>Le classi in cui vengono accertati alunni positivi, almeno 4 casi, continuano\u00a0 le\u00a0 attivit\u00e0\u00a0 in\u00a0 presenza,\u00a0 utilizzando\u00a0 le mascherine FFP2 per 10 giorni dall\u2019ultimo contatto.<\/p>\n<p>In caso di comparsa di sintomi e, se ancora sintomatici, al quinto giorno successivo all\u2019ultimo contatto va effettuato un test antigenico rapido o molecolare o un test antigenico autosomministrato. In quest\u2019ultimo caso l\u2019esito negativo del test \u00e8 attestato con autocertificazione.<\/p>\n<p>Gli\u00a0\u00a0 alunni\u00a0\u00a0 in\u00a0\u00a0 isolamento\u00a0\u00a0 possono\u00a0\u00a0 seguire\u00a0\u00a0 l\u2019attivit\u00e0 scolastica\u00a0\u00a0 in\u00a0\u00a0 DaD (didattica\u00a0 a distanza)\u00a0\u00a0 e\u00a0\u00a0 la riammissione in classe \u00e8 subordinata alla dimostrazione di un test antigenico rapido o molecolare con esito negativo.<\/p>\n<p><strong>OBBLIGO VACCINALE E LAVORO<\/strong><\/p>\n<p>L&#8217;obbligo vaccinale rimane fino al 31 dicembre 2022 per gli operatori\u00a0 di\u00a0 interesse\u00a0 sanitario\u00a0 e\u00a0 per\u00a0 il\u00a0 personale\u00a0 della scuola e universit\u00e0.<\/p>\n<p>Dal 1\u00b0\u00a0 aprile\u00a0 al 30\u00a0 aprile\u00a0 richiesto\u00a0 green\u00a0 pass\u00a0 base\u00a0 per accedere al lavoro per tutte le altre categorie.<\/p>\n<p>Fino al 15 giugno rimane l\u2019obbligo di vaccinazione per gli over 50 e rimane la multa una tantum di 100 euro erogata dall\u2019Agenzia delle entrate, a chi, pur avendo pi\u00f9 di 50 anni ancora non si \u00e8 immunizzato.<\/p>\n<p>Dal \u00a01\u00b0\u00a0 aprile\u00a0 non\u00a0 verranno\u00a0 pi\u00f9\u00a0 previste\u00a0 quarantene\u00a0 da contatto, senza distinzioni tra vaccinati e non vaccinati, per \u00a0ricorrere\u00a0 allo\u00a0 Smart\u00a0 working\u00a0 semplificato\u00a0 servir\u00e0\u00a0 l&#8217;accordo individuale tra azienda e singolo dipendente, prorogato al 30 giugno 2022.<\/p>\n<p><strong>QUARANTENA<\/strong><\/p>\n<p>Dal 1\u00b0 aprile:<\/p>\n<ul>\n<li>Rimane isolato a casa solo chi ha contratto il virus;<\/li>\n<li>Chi ha avuto un contatto con un caso positivo dovr\u00e0 applicare il regime dell&#8217;auto-sorveglianza per 10 giorni con mascherina ffp2 e il tampone sar\u00e0 necessario solo in caso di sintomi.<\/li>\n<\/ul>\n<p><u>Quarantena uguale per tutti, senza distinzione tra chi ha fatto il vaccino e chi no.<\/u><\/p>\n<style>\n\t.bluebanner h4{\n\t\t padding: 20px;\n\t\tcolor: white;\n\t\tbackground-color: #013161;\n\t}\n\t.bluebanner p{\n\t\t padding: 0 30px;\n\t}\n<\/style>\n<div class=\"bluebanner\">\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Decreto Legge del 24 marzo 2022, n.24 COVID-19 SUPERAMENTO DELLA FASE EMERGENZIALE; Del sistema delle zone colorate, del green pass in maniera graduale ed eliminazione delle quarantene precauzionali 31 MARZO [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":3268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-3267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergenza-coronavirus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 - SUPERAMENTO DELLA FASE EMERGENZIALE - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 - SUPERAMENTO DELLA FASE EMERGENZIALE - Mandela\" \/>\n<meta property=\"og:description\" content=\"Decreto Legge del 24 marzo 2022, n.24 COVID-19 SUPERAMENTO DELLA FASE EMERGENZIALE; Del sistema delle zone colorate, del green pass in maniera graduale ed eliminazione delle quarantene precauzionali 31 MARZO [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-28T12:32:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/03\/Fase-emergenziale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"COVID-19 &#8211; SUPERAMENTO DELLA FASE EMERGENZIALE\",\"datePublished\":\"2022-03-28T12:32:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/\"},\"wordCount\":739,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/03\\\/Fase-emergenziale.png\",\"articleSection\":[\"Emergenza Coronavirus\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/\",\"name\":\"COVID-19 - SUPERAMENTO DELLA FASE EMERGENZIALE - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/03\\\/Fase-emergenziale.png\",\"datePublished\":\"2022-03-28T12:32:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/03\\\/Fase-emergenziale.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/03\\\/Fase-emergenziale.png\",\"width\":553,\"height\":464},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2022\\\/03\\\/28\\\/covid-19-superamento-della-fase-emergenziale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19 &#8211; SUPERAMENTO DELLA FASE EMERGENZIALE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 - SUPERAMENTO DELLA FASE EMERGENZIALE - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/","og_locale":"it_IT","og_type":"article","og_title":"COVID-19 - SUPERAMENTO DELLA FASE EMERGENZIALE - Mandela","og_description":"Decreto Legge del 24 marzo 2022, n.24 COVID-19 SUPERAMENTO DELLA FASE EMERGENZIALE; Del sistema delle zone colorate, del green pass in maniera graduale ed eliminazione delle quarantene precauzionali 31 MARZO [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/","og_site_name":"Mandela","article_published_time":"2022-03-28T12:32:59+00:00","og_image":[{"width":553,"height":464,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/03\/Fase-emergenziale.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"COVID-19 &#8211; SUPERAMENTO DELLA FASE EMERGENZIALE","datePublished":"2022-03-28T12:32:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/"},"wordCount":739,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/03\/Fase-emergenziale.png","articleSection":["Emergenza Coronavirus"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/","url":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/","name":"COVID-19 - SUPERAMENTO DELLA FASE EMERGENZIALE - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/03\/Fase-emergenziale.png","datePublished":"2022-03-28T12:32:59+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/03\/Fase-emergenziale.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/03\/Fase-emergenziale.png","width":553,"height":464},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2022\/03\/28\/covid-19-superamento-della-fase-emergenziale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"COVID-19 &#8211; SUPERAMENTO DELLA FASE EMERGENZIALE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=3267"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3267\/revisions"}],"predecessor-version":[{"id":3269,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/3267\/revisions\/3269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/3268"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=3267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=3267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=3267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}