{"id":412,"date":"2016-11-11T10:54:36","date_gmt":"2016-11-11T09:54:36","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=412"},"modified":"2016-11-11T10:54:36","modified_gmt":"2016-11-11T09:54:36","slug":"servizio-scuolabus","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/","title":{"rendered":"SERVIZIO SCUOLABUS"},"content":{"rendered":"<p>L&#8217;istituto scolastico <em>-materna, elementari e medie &#8211;<\/em> a causa dello sciopero indetto per il giorno luned\u00ec 14 novembre p.v. non garantisce il regolare svolgimento delle lezioni, di conseguenza il <strong>servizio di scuolabus\u00a0per i ragazzi\u00a0<\/strong><strong>verr\u00e0 effettuato solo per il viaggio di ritorno.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;istituto scolastico -materna, elementari e medie &#8211; a causa dello sciopero indetto per il giorno luned\u00ec 14 novembre p.v. non garantisce il regolare svolgimento delle lezioni, di conseguenza il servizio [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-412","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZIO SCUOLABUS - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZIO SCUOLABUS - Mandela\" \/>\n<meta property=\"og:description\" content=\"L&#8217;istituto scolastico -materna, elementari e medie &#8211; a causa dello sciopero indetto per il giorno luned\u00ec 14 novembre p.v. non garantisce il regolare svolgimento delle lezioni, di conseguenza il servizio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-11T09:54:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"SERVIZIO SCUOLABUS\",\"datePublished\":\"2016-11-11T09:54:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/\"},\"wordCount\":46,\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/\",\"name\":\"SERVIZIO SCUOLABUS - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"datePublished\":\"2016-11-11T09:54:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2016\\\/11\\\/11\\\/servizio-scuolabus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZIO SCUOLABUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZIO SCUOLABUS - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZIO SCUOLABUS - Mandela","og_description":"L&#8217;istituto scolastico -materna, elementari e medie &#8211; a causa dello sciopero indetto per il giorno luned\u00ec 14 novembre p.v. non garantisce il regolare svolgimento delle lezioni, di conseguenza il servizio [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/","og_site_name":"Mandela","article_published_time":"2016-11-11T09:54:36+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"SERVIZIO SCUOLABUS","datePublished":"2016-11-11T09:54:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/"},"wordCount":46,"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/","url":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/","name":"SERVIZIO SCUOLABUS - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"datePublished":"2016-11-11T09:54:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2016\/11\/11\/servizio-scuolabus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"SERVIZIO SCUOLABUS"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=412"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/412\/revisions"}],"predecessor-version":[{"id":413,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/412\/revisions\/413"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}