{"id":4150,"date":"2024-03-06T19:46:19","date_gmt":"2024-03-06T18:46:19","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4150"},"modified":"2024-03-06T19:46:19","modified_gmt":"2024-03-06T18:46:19","slug":"guasto-illuminazione-pubblica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/","title":{"rendered":"GUASTO ILLUMINAZIONE PUBBLICA"},"content":{"rendered":"<p>Si informa che il guasto dell\u2019impianto di illuminazione pubblica della <strong>zona di Via delle Vignette<\/strong>, malgrado i due interventi gi\u00e0 effettuati sia sul quadro elettrico sia sulla linea, non sono stati risolutivi.<\/p>\n<p><strong>Domani mattina saranno ripresi i lavori<\/strong> al fine di trovare il corto circuito che non permette il normale funzionamento dei pali luce della zona.<\/p>\n<p>Ci scusiamo per il disagio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che il guasto dell\u2019impianto di illuminazione pubblica della zona di Via delle Vignette, malgrado i due interventi gi\u00e0 effettuati sia sul quadro elettrico sia sulla linea, non sono [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":4151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-4150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GUASTO ILLUMINAZIONE PUBBLICA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GUASTO ILLUMINAZIONE PUBBLICA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa che il guasto dell\u2019impianto di illuminazione pubblica della zona di Via delle Vignette, malgrado i due interventi gi\u00e0 effettuati sia sul quadro elettrico sia sulla linea, non sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T18:46:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2024\/03\/illuminazione-pubblica-guasta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"432\" \/>\n\t<meta property=\"og:image:height\" content=\"306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"GUASTO ILLUMINAZIONE PUBBLICA\",\"datePublished\":\"2024-03-06T18:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/\"},\"wordCount\":65,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/illuminazione-pubblica-guasta.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/\",\"name\":\"GUASTO ILLUMINAZIONE PUBBLICA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/illuminazione-pubblica-guasta.png\",\"datePublished\":\"2024-03-06T18:46:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/illuminazione-pubblica-guasta.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/illuminazione-pubblica-guasta.png\",\"width\":432,\"height\":306},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/03\\\/06\\\/guasto-illuminazione-pubblica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GUASTO ILLUMINAZIONE PUBBLICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GUASTO ILLUMINAZIONE PUBBLICA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/","og_locale":"it_IT","og_type":"article","og_title":"GUASTO ILLUMINAZIONE PUBBLICA - Mandela","og_description":"Si informa che il guasto dell\u2019impianto di illuminazione pubblica della zona di Via delle Vignette, malgrado i due interventi gi\u00e0 effettuati sia sul quadro elettrico sia sulla linea, non sono [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/","og_site_name":"Mandela","article_published_time":"2024-03-06T18:46:19+00:00","og_image":[{"width":432,"height":306,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2024\/03\/illuminazione-pubblica-guasta.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"GUASTO ILLUMINAZIONE PUBBLICA","datePublished":"2024-03-06T18:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/"},"wordCount":65,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2024\/03\/illuminazione-pubblica-guasta.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/","url":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/","name":"GUASTO ILLUMINAZIONE PUBBLICA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2024\/03\/illuminazione-pubblica-guasta.png","datePublished":"2024-03-06T18:46:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2024\/03\/illuminazione-pubblica-guasta.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2024\/03\/illuminazione-pubblica-guasta.png","width":432,"height":306},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2024\/03\/06\/guasto-illuminazione-pubblica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"GUASTO ILLUMINAZIONE PUBBLICA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4150"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4150\/revisions"}],"predecessor-version":[{"id":4152,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4150\/revisions\/4152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/4151"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}