{"id":4172,"date":"2024-04-06T12:07:26","date_gmt":"2024-04-06T10:07:26","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4172"},"modified":"2024-04-06T12:07:26","modified_gmt":"2024-04-06T10:07:26","slug":"manutenzione-straordinaria-verde","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/","title":{"rendered":"MANUTENZIONE STRAORDINARIA VERDE"},"content":{"rendered":"<p style=\"padding-left: 40px\">Si informa che luned\u00ec prossimo 8 aprile a partire dalle ore 8, sar\u00e0 effettuata una manutenzione straordinaria del verde pubblico nell&#8217;area di Via delle Vignette (zona villette).<\/p>\n<p>Durante i lavori che saranno eseguiti con l&#8217;ausilio di cestello elevatore, sar\u00e0 interdetto il passaggio e la sosta alle autovetture fino a fine lavori.<\/p>\n<p>Il passaggio pedonale sar\u00e0 in ogni caso garantito.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che luned\u00ec prossimo 8 aprile a partire dalle ore 8, sar\u00e0 effettuata una manutenzione straordinaria del verde pubblico nell&#8217;area di Via delle Vignette (zona villette). Durante i lavori [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":3391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-4172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MANUTENZIONE STRAORDINARIA VERDE - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MANUTENZIONE STRAORDINARIA VERDE - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa che luned\u00ec prossimo 8 aprile a partire dalle ore 8, sar\u00e0 effettuata una manutenzione straordinaria del verde pubblico nell&#8217;area di Via delle Vignette (zona villette). Durante i lavori [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-06T10:07:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/06\/PULIZIA-ERBA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"MANUTENZIONE STRAORDINARIA VERDE\",\"datePublished\":\"2024-04-06T10:07:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/\"},\"wordCount\":61,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/PULIZIA-ERBA.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/\",\"name\":\"MANUTENZIONE STRAORDINARIA VERDE - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/PULIZIA-ERBA.png\",\"datePublished\":\"2024-04-06T10:07:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/PULIZIA-ERBA.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/06\\\/PULIZIA-ERBA.png\",\"width\":638,\"height\":335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2024\\\/04\\\/06\\\/manutenzione-straordinaria-verde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MANUTENZIONE STRAORDINARIA VERDE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MANUTENZIONE STRAORDINARIA VERDE - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/","og_locale":"it_IT","og_type":"article","og_title":"MANUTENZIONE STRAORDINARIA VERDE - Mandela","og_description":"Si informa che luned\u00ec prossimo 8 aprile a partire dalle ore 8, sar\u00e0 effettuata una manutenzione straordinaria del verde pubblico nell&#8217;area di Via delle Vignette (zona villette). Durante i lavori [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/","og_site_name":"Mandela","article_published_time":"2024-04-06T10:07:26+00:00","og_image":[{"width":638,"height":335,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/06\/PULIZIA-ERBA.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"MANUTENZIONE STRAORDINARIA VERDE","datePublished":"2024-04-06T10:07:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/"},"wordCount":61,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/06\/PULIZIA-ERBA.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/","url":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/","name":"MANUTENZIONE STRAORDINARIA VERDE - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/06\/PULIZIA-ERBA.png","datePublished":"2024-04-06T10:07:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/06\/PULIZIA-ERBA.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2022\/06\/PULIZIA-ERBA.png","width":638,"height":335},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2024\/04\/06\/manutenzione-straordinaria-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"MANUTENZIONE STRAORDINARIA VERDE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4172"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4172\/revisions"}],"predecessor-version":[{"id":4173,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4172\/revisions\/4173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/3391"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}