{"id":4506,"date":"2025-02-18T11:33:15","date_gmt":"2025-02-18T10:33:15","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4506"},"modified":"2025-02-18T11:33:15","modified_gmt":"2025-02-18T10:33:15","slug":"interruzione-flusso-idrico-nel-centro-storico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/","title":{"rendered":"Interruzione flusso idrico nel centro storico"},"content":{"rendered":"<p>Si informa che a causa di un guasto sulla conduttura\u00a0 sar\u00e0 interrotto il flusso idrico nel centro storico\u00a0 in data odierna (18\/02\/25) fino a riparazione avvenuta.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Si informa che a causa di un guasto sulla conduttura\u00a0 sar\u00e0 interrotto il flusso idrico nel centro storico\u00a0 in data odierna (18\/02\/25) fino a riparazione avvenuta.<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4506","post","type-post","status-publish","format-standard","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interruzione flusso idrico nel centro storico - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interruzione flusso idrico nel centro storico - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si informa che a causa di un guasto sulla conduttura\u00a0 sar\u00e0 interrotto il flusso idrico nel centro storico\u00a0 in data odierna (18\/02\/25) fino a riparazione avvenuta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T10:33:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"Interruzione flusso idrico nel centro storico\",\"datePublished\":\"2025-02-18T10:33:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/\"},\"wordCount\":31,\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/\",\"name\":\"Interruzione flusso idrico nel centro storico - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"datePublished\":\"2025-02-18T10:33:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/02\\\/18\\\/interruzione-flusso-idrico-nel-centro-storico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interruzione flusso idrico nel centro storico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interruzione flusso idrico nel centro storico - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/","og_locale":"it_IT","og_type":"article","og_title":"Interruzione flusso idrico nel centro storico - Mandela","og_description":"Si informa che a causa di un guasto sulla conduttura\u00a0 sar\u00e0 interrotto il flusso idrico nel centro storico\u00a0 in data odierna (18\/02\/25) fino a riparazione avvenuta.","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/","og_site_name":"Mandela","article_published_time":"2025-02-18T10:33:15+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png","height":600,"width":1200,"type":""}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"Interruzione flusso idrico nel centro storico","datePublished":"2025-02-18T10:33:15+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/"},"wordCount":31,"articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/","name":"Interruzione flusso idrico nel centro storico - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"datePublished":"2025-02-18T10:33:15+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/02\/18\/interruzione-flusso-idrico-nel-centro-storico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"Interruzione flusso idrico nel centro storico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4506"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4506\/revisions"}],"predecessor-version":[{"id":4507,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4506\/revisions\/4507"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}