{"id":4596,"date":"2025-06-09T10:59:48","date_gmt":"2025-06-09T08:59:48","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4596"},"modified":"2025-06-09T10:59:48","modified_gmt":"2025-06-09T08:59:48","slug":"autolettura-contatori-acqua","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/","title":{"rendered":"AUTOLETTURA CONTATORI ACQUA"},"content":{"rendered":"<h3>Si avvisa che a causa di un problema del software, sono state trovate difficolt\u00e0 di accesso al sistema.<\/h3>\n<h3>I tecnici ci hanno informato che da\u00a0 qualche minuto il problema \u00e8 stato risolto, per cui si pu\u00f2 procedere all&#8217;inserimento dei dati<\/h3>\n<p>&nbsp;<\/p>\n<p><u>Si informa che da oggi <strong>FINO AL 20 GIUGNO<\/strong> sar\u00e0 ATTIVO il servizio di <strong>AUTOLETTURA PER I CONSUMI DELL\u2019ACQUA<\/strong>.<\/u><\/p>\n<p>L&#8217;AUTOLETTURA consente di verificare i\u00a0<strong>dati di consumo effettivo<\/strong>;<\/p>\n<p>la trasmissione di tali dati permette di <strong>velocizzare i processi amministrativi e ridurre sensibilmente gli errori di lettura<\/strong><\/p>\n<p>Il sistema \u00e8 molto semplice, basta collegarsi al link<strong> <a href=\"https:\/\/mandelaservizi.it\/\">https:\/\/mandelaservizi.it\/<\/a><\/strong><\/p>\n<ol>\n<li>Inserire il <strong><u>CODICE FISCALE DELL\u2019INTESTATARIO DEL CONTRATTO<\/u><\/strong><\/li>\n<li>Inserire il <strong><u>NUMERO DELL\u2019UTENZA<\/u><\/strong> (indicato sull\u2019ultima fattura)<\/li>\n<li>Inserire la <strong><u>LETTURA ATTUALE<\/u><\/strong><\/li>\n<li><strong>\u00a0INVIO<\/strong><\/li>\n<\/ol>\n<p><strong>La lettura potr\u00e0 essere inserita fino a venerd\u00ec 20 giugno<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si avvisa che a causa di un problema del software, sono state trovate difficolt\u00e0 di accesso al sistema. I tecnici ci hanno informato che da\u00a0 qualche minuto il problema \u00e8 [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":3751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUTOLETTURA CONTATORI ACQUA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUTOLETTURA CONTATORI ACQUA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Si avvisa che a causa di un problema del software, sono state trovate difficolt\u00e0 di accesso al sistema. I tecnici ci hanno informato che da\u00a0 qualche minuto il problema \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T08:59:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2023\/06\/AUTOLETTURA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"538\" \/>\n\t<meta property=\"og:image:height\" content=\"359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"AUTOLETTURA CONTATORI ACQUA\",\"datePublished\":\"2025-06-09T08:59:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/\"},\"wordCount\":131,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/AUTOLETTURA.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/\",\"name\":\"AUTOLETTURA CONTATORI ACQUA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/AUTOLETTURA.png\",\"datePublished\":\"2025-06-09T08:59:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/AUTOLETTURA.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/AUTOLETTURA.png\",\"width\":538,\"height\":359},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/09\\\/autolettura-contatori-acqua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUTOLETTURA CONTATORI ACQUA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUTOLETTURA CONTATORI ACQUA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/","og_locale":"it_IT","og_type":"article","og_title":"AUTOLETTURA CONTATORI ACQUA - Mandela","og_description":"Si avvisa che a causa di un problema del software, sono state trovate difficolt\u00e0 di accesso al sistema. I tecnici ci hanno informato che da\u00a0 qualche minuto il problema \u00e8 [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/","og_site_name":"Mandela","article_published_time":"2025-06-09T08:59:48+00:00","og_image":[{"width":538,"height":359,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2023\/06\/AUTOLETTURA.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"AUTOLETTURA CONTATORI ACQUA","datePublished":"2025-06-09T08:59:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/"},"wordCount":131,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2023\/06\/AUTOLETTURA.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/","name":"AUTOLETTURA CONTATORI ACQUA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2023\/06\/AUTOLETTURA.png","datePublished":"2025-06-09T08:59:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2023\/06\/AUTOLETTURA.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2023\/06\/AUTOLETTURA.png","width":538,"height":359},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/09\/autolettura-contatori-acqua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"AUTOLETTURA CONTATORI ACQUA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4596"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4596\/revisions"}],"predecessor-version":[{"id":4597,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4596\/revisions\/4597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/3751"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}