{"id":4639,"date":"2025-06-27T12:50:58","date_gmt":"2025-06-27T10:50:58","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4639"},"modified":"2025-06-27T12:54:49","modified_gmt":"2025-06-27T10:54:49","slug":"festa-di-settembre-mandela-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/","title":{"rendered":"FESTA DI SETTEMBRE MANDELA"},"content":{"rendered":"<p style=\"text-align: center\" align=\"center\"><strong><span style=\"font-size: 14.0pt;font-family: 'Arial',sans-serif\">Festa di settembre a Mandela \u2013 Unisciti a noi per rendere speciali questi tre giorni di festa!<\/span><\/strong><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Arial',sans-serif\">Anche quest\u2019anno, come da tradizione, la prima settimana di settembre celebreremo insieme la tradizionale <strong>Festa di Mandela dedicata a Maria SS e San Rocco.<\/strong> Sebbene non sia stato costituito un comitato organizzatore ufficiale, <strong>le associazioni del territorio hanno risposto con entusiasmo e spirito di collaborazione<\/strong>, mettendosi a disposizione per dare vita a un programma ricco di eventi, incontri e momenti di condivisione.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Arial',sans-serif\">\u00a0APS Centro Anziani, OdV Arte e Cultura Abusiva, Associazione Semplicemente Mamme e il Comitato Parrocchiale stanno lavorando con passione per offrire a tutti \u2013 grandi e piccini \u2013 <strong>tre giorni di festa, sorrisi e comunit\u00e0.<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Arial',sans-serif\">Per sostenere le attivit\u00e0 previste, \u00e8 attiva una <strong>raccolta fondi<\/strong>: ogni contributo, piccolo o grande, sar\u00e0 fondamentale e <strong>verr\u00e0 utilizzato esclusivamente per la realizzazione della festa<\/strong>. A garanzia della massima trasparenza, le associazioni coinvolte rilasciano regolare ricevuta per ogni donazione.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Arial',sans-serif\">La raccolta avverr\u00e0 tramite il passaparola e contatti diretti, e pu\u00f2 capitare che alcune richieste vengano duplicate: stiamo lavorando per coordinare al meglio questo aspetto e minimizzare eventuali disagi.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Arial',sans-serif\">Ringraziamo sin da ora tutti coloro che sceglieranno di dare il proprio sostegno, economico o organizzativo. <strong>Le persone fanno la festa \u2014 e con il contributo di ciascuno di voi potremo renderla davvero speciale.<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Arial',sans-serif\">Per dubbi, suggerimenti o per partecipare attivamente, <strong>i referenti delle associazioni sono a completa disposizione<\/strong>.<\/span><\/p>\n\t\t\t<h4>Inizio<\/h4>\n<p>05\/09\/2025 07:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>07\/09\/2025 23:55<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Mandela, Roma, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.0308068,12.9233231&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Festa di settembre a Mandela \u2013 Unisciti a noi per rendere speciali questi tre giorni di festa! Anche quest\u2019anno, come da tradizione, la prima settimana di settembre celebreremo insieme la [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":4640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FESTA DI SETTEMBRE MANDELA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESTA DI SETTEMBRE MANDELA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Festa di settembre a Mandela \u2013 Unisciti a noi per rendere speciali questi tre giorni di festa! Anche quest\u2019anno, come da tradizione, la prima settimana di settembre celebreremo insieme la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T10:50:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T10:54:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/06\/raccolta-fondi-festa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"FESTA DI SETTEMBRE MANDELA\",\"datePublished\":\"2025-06-27T10:50:58+00:00\",\"dateModified\":\"2025-06-27T10:54:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/\"},\"wordCount\":232,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/raccolta-fondi-festa.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/\",\"name\":\"FESTA DI SETTEMBRE MANDELA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/raccolta-fondi-festa.png\",\"datePublished\":\"2025-06-27T10:50:58+00:00\",\"dateModified\":\"2025-06-27T10:54:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/raccolta-fondi-festa.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/raccolta-fondi-festa.png\",\"width\":1024,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/06\\\/27\\\/festa-di-settembre-mandela-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FESTA DI SETTEMBRE MANDELA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESTA DI SETTEMBRE MANDELA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/","og_locale":"it_IT","og_type":"article","og_title":"FESTA DI SETTEMBRE MANDELA - Mandela","og_description":"Festa di settembre a Mandela \u2013 Unisciti a noi per rendere speciali questi tre giorni di festa! Anche quest\u2019anno, come da tradizione, la prima settimana di settembre celebreremo insieme la [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/","og_site_name":"Mandela","article_published_time":"2025-06-27T10:50:58+00:00","article_modified_time":"2025-06-27T10:54:49+00:00","og_image":[{"width":1024,"height":1536,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/06\/raccolta-fondi-festa.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"FESTA DI SETTEMBRE MANDELA","datePublished":"2025-06-27T10:50:58+00:00","dateModified":"2025-06-27T10:54:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/"},"wordCount":232,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/06\/raccolta-fondi-festa.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/","name":"FESTA DI SETTEMBRE MANDELA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/06\/raccolta-fondi-festa.png","datePublished":"2025-06-27T10:50:58+00:00","dateModified":"2025-06-27T10:54:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/06\/raccolta-fondi-festa.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/06\/raccolta-fondi-festa.png","width":1024,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/06\/27\/festa-di-settembre-mandela-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"FESTA DI SETTEMBRE MANDELA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"05\/09\/2025 07:00","cc4_eve_data_fine":"07\/09\/2025 23:55","cc4_eve_indirizzo":"Mandela, Roma, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.0308068","longitude":"12.9233231","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4639"}],"version-history":[{"count":5,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4639\/revisions"}],"predecessor-version":[{"id":4645,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4639\/revisions\/4645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/4640"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}