{"id":4691,"date":"2025-07-29T16:50:59","date_gmt":"2025-07-29T14:50:59","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4691"},"modified":"2025-07-29T16:50:59","modified_gmt":"2025-07-29T14:50:59","slug":"rassegna-teatrale-4-appuntamento","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/","title":{"rendered":"RASSEGNA TEATRALE &#8211; 4\u00b0 APPUNTAMENTO"},"content":{"rendered":"<p>Ancora un appuntamento con\u00a0 la rassegna teatrale dell\u2019Artista Matteo Fratarcangeli al <strong><u>Teatro Verde di Mandela<\/u><\/strong><\/p>\n<p>Si informa che <strong>Gioved\u00ec 31 alle ore 21,15<\/strong>, avr\u00e0 luogo una nuova rappresentazione all\u2019interno del ciclo di performance esistenziali dedicate all\u2019arte scenica contemporanea<\/p>\n<p><strong><u>\u201cPaesaggi Introspettivi\u201d,<\/u><\/strong><\/p>\n<p><strong>Teatro Verde \u2013 ore 21:15 Ingresso libero<\/strong><\/p>\n\t\t\t<h4>Inizio<\/h4>\n<p>31\/07\/2025 21:15<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>31\/07\/2025 22:30<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Mandela, Roma, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.0308068,12.9233231&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Ancora un appuntamento con\u00a0 la rassegna teatrale dell\u2019Artista Matteo Fratarcangeli al Teatro Verde di Mandela Si informa che Gioved\u00ec 31 alle ore 21,15, avr\u00e0 luogo una nuova rappresentazione all\u2019interno del [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":4692,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RASSEGNA TEATRALE - 4\u00b0 APPUNTAMENTO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RASSEGNA TEATRALE - 4\u00b0 APPUNTAMENTO - Mandela\" \/>\n<meta property=\"og:description\" content=\"Ancora un appuntamento con\u00a0 la rassegna teatrale dell\u2019Artista Matteo Fratarcangeli al Teatro Verde di Mandela Si informa che Gioved\u00ec 31 alle ore 21,15, avr\u00e0 luogo una nuova rappresentazione all\u2019interno del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T14:50:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"RASSEGNA TEATRALE &#8211; 4\u00b0 APPUNTAMENTO\",\"datePublished\":\"2025-07-29T14:50:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/\"},\"wordCount\":50,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/\",\"name\":\"RASSEGNA TEATRALE - 4\u00b0 APPUNTAMENTO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg\",\"datePublished\":\"2025-07-29T14:50:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/29\\\/rassegna-teatrale-4-appuntamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RASSEGNA TEATRALE &#8211; 4\u00b0 APPUNTAMENTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RASSEGNA TEATRALE - 4\u00b0 APPUNTAMENTO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/","og_locale":"it_IT","og_type":"article","og_title":"RASSEGNA TEATRALE - 4\u00b0 APPUNTAMENTO - Mandela","og_description":"Ancora un appuntamento con\u00a0 la rassegna teatrale dell\u2019Artista Matteo Fratarcangeli al Teatro Verde di Mandela Si informa che Gioved\u00ec 31 alle ore 21,15, avr\u00e0 luogo una nuova rappresentazione all\u2019interno del [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/","og_site_name":"Mandela","article_published_time":"2025-07-29T14:50:59+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"RASSEGNA TEATRALE &#8211; 4\u00b0 APPUNTAMENTO","datePublished":"2025-07-29T14:50:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/"},"wordCount":50,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/","name":"RASSEGNA TEATRALE - 4\u00b0 APPUNTAMENTO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg","datePublished":"2025-07-29T14:50:59+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/WhatsApp-Image-2025-07-29-at-09.48.18.jpeg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/29\/rassegna-teatrale-4-appuntamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"RASSEGNA TEATRALE &#8211; 4\u00b0 APPUNTAMENTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"31\/07\/2025 21:15","cc4_eve_data_fine":"31\/07\/2025 22:30","cc4_eve_indirizzo":"Mandela, Roma, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.0308068","longitude":"12.9233231","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4691"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4691\/revisions"}],"predecessor-version":[{"id":4693,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4691\/revisions\/4693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/4692"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}