{"id":4699,"date":"2025-07-31T08:32:18","date_gmt":"2025-07-31T06:32:18","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4699"},"modified":"2025-07-31T08:32:18","modified_gmt":"2025-07-31T06:32:18","slug":"eventi-a-mandela-domenica-3-agosto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/","title":{"rendered":"EVENTI A MANDELA &#8211; DOMENICA 3 AGOSTO"},"content":{"rendered":"<p><strong>MANDELA CELEBRA L\u2019ARTE E IL DIVERTIMENTO<\/strong><strong> &#8211; Domenica 3 agosto 2025<\/strong><\/p>\n<p><strong>Dalle ore 10:30<\/strong>, nella Sala Consiliare del Comune, <strong>\u201cFestival delle Arti Locali<\/strong>\u201d: una mostra dedicata alle opere degli artisti del territorio, un\u2019occasione per ammirare talento, passione e tradizione.<\/p>\n<p><strong>Nel pomeriggio, alle ore 16:30<\/strong>, il divertimento si trasferisce al Teatro Verde con <strong>&#8220;AcquaFun&#8221;<\/strong>: un evento pensato per i bambini, tra allegria, movimento e sorprese! Un pomeriggio che promette risate, gioco e spensieratezza.<\/p>\n<p>Mandela vi aspetta per una domenica all\u2019insegna della cultura e della felicit\u00e0<\/p>\n\t\t\t<h4>Inizio<\/h4>\n<p>03\/08\/2025 10:30<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>03\/08\/2025 20:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Mandela, Roma, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.0308068,12.9233231&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>MANDELA CELEBRA L\u2019ARTE E IL DIVERTIMENTO &#8211; Domenica 3 agosto 2025 Dalle ore 10:30, nella Sala Consiliare del Comune, \u201cFestival delle Arti Locali\u201d: una mostra dedicata alle opere degli artisti [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":4700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EVENTI A MANDELA - DOMENICA 3 AGOSTO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EVENTI A MANDELA - DOMENICA 3 AGOSTO - Mandela\" \/>\n<meta property=\"og:description\" content=\"MANDELA CELEBRA L\u2019ARTE E IL DIVERTIMENTO &#8211; Domenica 3 agosto 2025 Dalle ore 10:30, nella Sala Consiliare del Comune, \u201cFestival delle Arti Locali\u201d: una mostra dedicata alle opere degli artisti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T06:32:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/EVENTI-3-AGOSTO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1754\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"EVENTI A MANDELA &#8211; DOMENICA 3 AGOSTO\",\"datePublished\":\"2025-07-31T06:32:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/\"},\"wordCount\":89,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/EVENTI-3-AGOSTO.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/\",\"name\":\"EVENTI A MANDELA - DOMENICA 3 AGOSTO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/EVENTI-3-AGOSTO.png\",\"datePublished\":\"2025-07-31T06:32:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/EVENTI-3-AGOSTO.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/EVENTI-3-AGOSTO.png\",\"width\":1754,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/07\\\/31\\\/eventi-a-mandela-domenica-3-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EVENTI A MANDELA &#8211; DOMENICA 3 AGOSTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EVENTI A MANDELA - DOMENICA 3 AGOSTO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/","og_locale":"it_IT","og_type":"article","og_title":"EVENTI A MANDELA - DOMENICA 3 AGOSTO - Mandela","og_description":"MANDELA CELEBRA L\u2019ARTE E IL DIVERTIMENTO &#8211; Domenica 3 agosto 2025 Dalle ore 10:30, nella Sala Consiliare del Comune, \u201cFestival delle Arti Locali\u201d: una mostra dedicata alle opere degli artisti [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/","og_site_name":"Mandela","article_published_time":"2025-07-31T06:32:18+00:00","og_image":[{"width":1754,"height":1240,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/EVENTI-3-AGOSTO.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"EVENTI A MANDELA &#8211; DOMENICA 3 AGOSTO","datePublished":"2025-07-31T06:32:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/"},"wordCount":89,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/EVENTI-3-AGOSTO.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/","name":"EVENTI A MANDELA - DOMENICA 3 AGOSTO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/EVENTI-3-AGOSTO.png","datePublished":"2025-07-31T06:32:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/EVENTI-3-AGOSTO.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/07\/EVENTI-3-AGOSTO.png","width":1754,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/07\/31\/eventi-a-mandela-domenica-3-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"EVENTI A MANDELA &#8211; DOMENICA 3 AGOSTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"03\/08\/2025 10:30","cc4_eve_data_fine":"03\/08\/2025 20:00","cc4_eve_indirizzo":"Mandela, Roma, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.0308068","longitude":"12.9233231","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4699"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4699\/revisions"}],"predecessor-version":[{"id":4701,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4699\/revisions\/4701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/4700"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}