{"id":4780,"date":"2025-09-12T12:38:21","date_gmt":"2025-09-12T10:38:21","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4780"},"modified":"2025-09-12T12:38:21","modified_gmt":"2025-09-12T10:38:21","slug":"mobilita-consapevole-a-mandela","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/","title":{"rendered":"MOBILITA&#8217; CONSAPEVOLE A MANDELA"},"content":{"rendered":"<p><strong>Camminare sicuri \u00e8 un diritto. Guidare con rispetto \u00e8 un dovere. <\/strong><\/p>\n<p>Vi invitiamo a prestare la massima attenzione alla velocit\u00e0 con cui si transita nel Centro storico e in tutte le aree urbane di Mandela. Questi spazi non sono solo strade: sono luoghi di vita, di incontro\u2026 e soprattutto di persone.<\/p>\n<p>Troppo spesso, il passaggio delle autovetture avviene a velocit\u00e0 sostenute, che mettono a rischio la sicurezza dei pedoni \u2014 bambini, anziani, cittadini e turisti \u2014 che possono sbucare all\u2019improvviso da un vicolo o da un portone.<\/p>\n<p><strong>L\u2019intero attraversamento del Centro storico misura appena 260 metri. A 30 km\/h bastano 30 secondi per percorrerlo. Solo 30 secondi.<\/strong><\/p>\n<p><strong>La domanda \u00e8 semplice: vale davvero la pena rischiare la vita di qualcuno per guadagnare qualche secondo?<\/strong><\/p>\n<p>Vi chiediamo di essere parte attiva di una comunit\u00e0 pi\u00f9 sicura e rispettosa. Ridurre la velocit\u00e0 \u00e8 un gesto di civilt\u00e0, di rispetto e di cura verso gli altri. \u00c8 un piccolo impegno che pu\u00f2 fare una grande differenza.<\/p>\n<p>Grazie per la collaborazione e per il vostro senso di responsabilit\u00e0.<\/p>\n<p><strong>Il Sindaco \u2013 Claudio Pettinelli <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Camminare sicuri \u00e8 un diritto. Guidare con rispetto \u00e8 un dovere. Vi invitiamo a prestare la massima attenzione alla velocit\u00e0 con cui si transita nel Centro storico e in tutte [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":4782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MOBILITA&#039; CONSAPEVOLE A MANDELA - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MOBILITA&#039; CONSAPEVOLE A MANDELA - Mandela\" \/>\n<meta property=\"og:description\" content=\"Camminare sicuri \u00e8 un diritto. Guidare con rispetto \u00e8 un dovere. Vi invitiamo a prestare la massima attenzione alla velocit\u00e0 con cui si transita nel Centro storico e in tutte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-12T10:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/09\/velocita-centro-storico-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"310\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"MOBILITA&#8217; CONSAPEVOLE A MANDELA\",\"datePublished\":\"2025-09-12T10:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/\"},\"wordCount\":174,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/velocita-centro-storico-1.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/\",\"name\":\"MOBILITA' CONSAPEVOLE A MANDELA - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/velocita-centro-storico-1.png\",\"datePublished\":\"2025-09-12T10:38:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/velocita-centro-storico-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/velocita-centro-storico-1.png\",\"width\":310,\"height\":465},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/09\\\/12\\\/mobilita-consapevole-a-mandela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MOBILITA&#8217; CONSAPEVOLE A MANDELA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MOBILITA' CONSAPEVOLE A MANDELA - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/","og_locale":"it_IT","og_type":"article","og_title":"MOBILITA' CONSAPEVOLE A MANDELA - Mandela","og_description":"Camminare sicuri \u00e8 un diritto. Guidare con rispetto \u00e8 un dovere. Vi invitiamo a prestare la massima attenzione alla velocit\u00e0 con cui si transita nel Centro storico e in tutte [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/","og_site_name":"Mandela","article_published_time":"2025-09-12T10:38:21+00:00","og_image":[{"width":310,"height":465,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/09\/velocita-centro-storico-1.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"MOBILITA&#8217; CONSAPEVOLE A MANDELA","datePublished":"2025-09-12T10:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/"},"wordCount":174,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/09\/velocita-centro-storico-1.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/","name":"MOBILITA' CONSAPEVOLE A MANDELA - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/09\/velocita-centro-storico-1.png","datePublished":"2025-09-12T10:38:21+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/09\/velocita-centro-storico-1.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/09\/velocita-centro-storico-1.png","width":310,"height":465},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/09\/12\/mobilita-consapevole-a-mandela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"MOBILITA&#8217; CONSAPEVOLE A MANDELA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4780"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4780\/revisions"}],"predecessor-version":[{"id":4783,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4780\/revisions\/4783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/4782"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}