{"id":4790,"date":"2025-10-07T11:34:19","date_gmt":"2025-10-07T09:34:19","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=4790"},"modified":"2025-10-07T11:34:19","modified_gmt":"2025-10-07T09:34:19","slug":"emozioni-in-tango-quartetto-fancelli","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/","title":{"rendered":"EMOZIONI IN TANGO &#8211; QUARTETTO FANCELLI"},"content":{"rendered":"<p><strong>HISTOIRE DU TANGO<\/strong> \u2013 Un viaggio musicale tra passione e tradizione<\/p>\n<p>Sala Teatro Comunale di Mandela<\/p>\n<p><strong>Domenica 12 Ottobre \u2013 Ore 17:00<\/strong><\/p>\n<p>Il Comune di Mandela ti invita a vivere un pomeriggio indimenticabile sulle note del <strong>Tango Argentino<\/strong>. Protagonista il Quartetto Fancelli, ensemble nato dall\u2019amicizia e dalla passione per la musica, che reinterpreta con eleganza e modernit\u00e0 l\u2019opera di Luciano Fancelli.<\/p>\n<p>Lasciati trasportare dalle atmosfere vibranti e suggestive del tango, tra ritmo, emozione e storia. Un\u2019occasione unica per immergersi nella cultura sudamericana e riscoprire la vitalit\u00e0 di uno dei generi pi\u00f9 affascinanti al mondo.<\/p>\n<p>Un appuntamento da non perdere per chi ama la musica che parla al cuore.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>HISTOIRE DU TANGO \u2013 Un viaggio musicale tra passione e tradizione Sala Teatro Comunale di Mandela Domenica 12 Ottobre \u2013 Ore 17:00 Il Comune di Mandela ti invita a vivere [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":4791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMOZIONI IN TANGO - QUARTETTO FANCELLI - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMOZIONI IN TANGO - QUARTETTO FANCELLI - Mandela\" \/>\n<meta property=\"og:description\" content=\"HISTOIRE DU TANGO \u2013 Un viaggio musicale tra passione e tradizione Sala Teatro Comunale di Mandela Domenica 12 Ottobre \u2013 Ore 17:00 Il Comune di Mandela ti invita a vivere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T09:34:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/10\/fancelli-724x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"EMOZIONI IN TANGO &#8211; QUARTETTO FANCELLI\",\"datePublished\":\"2025-10-07T09:34:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/\"},\"wordCount\":114,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/10\\\/fancelli.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/\",\"name\":\"EMOZIONI IN TANGO - QUARTETTO FANCELLI - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/10\\\/fancelli.png\",\"datePublished\":\"2025-10-07T09:34:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/10\\\/fancelli.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/10\\\/fancelli.png\",\"width\":1240,\"height\":1754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2025\\\/10\\\/07\\\/emozioni-in-tango-quartetto-fancelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMOZIONI IN TANGO &#8211; QUARTETTO FANCELLI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMOZIONI IN TANGO - QUARTETTO FANCELLI - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/","og_locale":"it_IT","og_type":"article","og_title":"EMOZIONI IN TANGO - QUARTETTO FANCELLI - Mandela","og_description":"HISTOIRE DU TANGO \u2013 Un viaggio musicale tra passione e tradizione Sala Teatro Comunale di Mandela Domenica 12 Ottobre \u2013 Ore 17:00 Il Comune di Mandela ti invita a vivere [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/","og_site_name":"Mandela","article_published_time":"2025-10-07T09:34:19+00:00","og_image":[{"width":724,"height":1024,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/10\/fancelli-724x1024.png","type":"image\/png"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"EMOZIONI IN TANGO &#8211; QUARTETTO FANCELLI","datePublished":"2025-10-07T09:34:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/"},"wordCount":114,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/10\/fancelli.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/","url":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/","name":"EMOZIONI IN TANGO - QUARTETTO FANCELLI - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/10\/fancelli.png","datePublished":"2025-10-07T09:34:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/10\/fancelli.png","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2025\/10\/fancelli.png","width":1240,"height":1754},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2025\/10\/07\/emozioni-in-tango-quartetto-fancelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"EMOZIONI IN TANGO &#8211; QUARTETTO FANCELLI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=4790"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4790\/revisions"}],"predecessor-version":[{"id":4792,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/4790\/revisions\/4792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/4791"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=4790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=4790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=4790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}