{"id":694,"date":"2017-11-23T15:56:18","date_gmt":"2017-11-23T14:56:18","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=694"},"modified":"2017-11-23T15:56:18","modified_gmt":"2017-11-23T14:56:18","slug":"segnalazione-furti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/","title":{"rendered":"SEGNALAZIONE FURTI"},"content":{"rendered":"<p>Siamo stati informati che in alcuni comuni limitrofi, si sono verificati dei furti nelle abitazioni.<\/p>\n<p>I furti sono concentrati principalmente nel pomeriggio dalle ore 17 alle ore 20 e durante il fine settimana (dal gioved\u00ec alla domenica).<\/p>\n<p>Chiunque notasse atteggiamenti sospetti \u00a0o segnali di pericolo \u00e8 pregato di <strong><u>informare al pi\u00f9 presto le autorit\u00e0 competenti di zona.<\/u><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo stati informati che in alcuni comuni limitrofi, si sono verificati dei furti nelle abitazioni. I furti sono concentrati principalmente nel pomeriggio dalle ore 17 alle ore 20 e durante [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEGNALAZIONE FURTI - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEGNALAZIONE FURTI - Mandela\" \/>\n<meta property=\"og:description\" content=\"Siamo stati informati che in alcuni comuni limitrofi, si sono verificati dei furti nelle abitazioni. I furti sono concentrati principalmente nel pomeriggio dalle ore 17 alle ore 20 e durante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-23T14:56:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/11\/Furti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"SEGNALAZIONE FURTI\",\"datePublished\":\"2017-11-23T14:56:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/\"},\"wordCount\":56,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/Furti.jpg\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/\",\"name\":\"SEGNALAZIONE FURTI - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/Furti.jpg\",\"datePublished\":\"2017-11-23T14:56:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/Furti.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/Furti.jpg\",\"width\":300,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2017\\\/11\\\/23\\\/segnalazione-furti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEGNALAZIONE FURTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEGNALAZIONE FURTI - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/","og_locale":"it_IT","og_type":"article","og_title":"SEGNALAZIONE FURTI - Mandela","og_description":"Siamo stati informati che in alcuni comuni limitrofi, si sono verificati dei furti nelle abitazioni. I furti sono concentrati principalmente nel pomeriggio dalle ore 17 alle ore 20 e durante [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/","og_site_name":"Mandela","article_published_time":"2017-11-23T14:56:18+00:00","og_image":[{"width":300,"height":150,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/11\/Furti.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"SEGNALAZIONE FURTI","datePublished":"2017-11-23T14:56:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/"},"wordCount":56,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/11\/Furti.jpg","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/","url":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/","name":"SEGNALAZIONE FURTI - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/11\/Furti.jpg","datePublished":"2017-11-23T14:56:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/11\/Furti.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2017\/11\/Furti.jpg","width":300,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2017\/11\/23\/segnalazione-furti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"SEGNALAZIONE FURTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=694"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/694\/revisions"}],"predecessor-version":[{"id":697,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/694\/revisions\/697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/695"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}