{"id":781,"date":"2018-01-23T09:32:12","date_gmt":"2018-01-23T08:32:12","guid":{"rendered":"https:\/\/comunicacity.net\/mandela\/?p=781"},"modified":"2018-01-23T09:32:12","modified_gmt":"2018-01-23T08:32:12","slug":"caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/","title":{"rendered":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA  SOTTO PALAZZO CHIGI &#8211; SEDE DEL GOVERNO"},"content":{"rendered":"<p style=\"text-align: center\">CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA<\/p>\n<p style=\"text-align: center\">SOTTO PALAZZO CHIGI SEDE DEL GOVERNO<\/p>\n<p style=\"text-align: center\"><em>(aggiornamento del 22\/1\/2018)<\/em><\/p>\n<p>I Sindaci e gli amministratori locali di Lazio e Abruzzo, di nuovo riuniti in data odierna presso il Comune di Carsoli per concordare ulteriori e pi\u00f9 incisive iniziative contro gli aumenti dei pedaggi autostradali, pur avendo preso atto delle notizie relative alle possibili agevolazioni a favore dei \u201cpendolari\u201d, delle quali tuttavia non si conoscono ancora con precisione entit\u00e0, destinatari e modalit\u00e0 di applicazione, preoccupati per la totale assenza di contatti e informazioni in merito al confronto in atto tra Governo e Gestore, confermano:<\/p>\n<ul>\n<li>La richiesta di una immediata sospensione degli aumenti dei pedaggi condizionata all\u2019apertura di un tavolo istituzionale teso a ridefinire l\u2019atto di concessione autostradale con Strada\u00a0dei Parchi Spa e gli accordi conseguenti affinch\u00e9 i pendolari e i cittadini\u00a0tutti possano pagare una tariffa adeguata e riparametrata ad un\u2019area interna\u00a0svantaggiata come \u00e8 quella di questi territori;<\/li>\n<li>La richiesta di declassificazione del tratto urbano della A\/24 che va dalla barriera di\u00a0Roma Est all\u2019intersezione con la Tangenziale Est di Roma (Verano);<\/li>\n<li>La richiesta di declassificazione da tratto montano a tratto non montano dalla\u00a0barriera di Vicovaro \u2013 Mandela a Roma.<\/li>\n<\/ul>\n<p>Tali richieste, gi\u00e0 da tempo consegnate al Ministro Delrio, ai Presidenti Zingaretti e D\u2019Alfonso, e trasmesse alle Commissioni Trasporti e Infrastrutture della Camera e del Senato, ai Prefetti di Roma e de L\u2019Aquila e alla Societ\u00e0 Strada dei Parchi, sono contenute in un documento sottoscritto da circa 100 comuni in rappresentanza di oltre 400 mila abitanti, saranno sottoposte all\u2019attenzione e all\u2019approvazione delle istituzioni locali e sovracomunali che hanno aderito alla forte mobilitazione di queste settimane.<\/p>\n<p>Determinati a proseguire nell\u2019azione di contrasto all\u2019ultimo ingiustificato aumento del pedaggio autostradale, che rischia di strangolare definitivamente famiglie e imprese di territori che da anni lottano contro lo spopolamento dei centri abitati e l\u2019impoverimento del tessuto sociale ed economico, i Sindaci e gli amministratori locali di Lazio e Abruzzo si danno appuntamento mercoled\u00ec mattina (24.01.18) alle ore 10,30 a Roma sotto Palazzo Chigi con le fasce tricolori e i gonfaloni dei comuni.<\/p>\n<p><em>Carsoli, Luned\u00ec 22 Gennaio 2018<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI SEDE DEL GOVERNO (aggiornamento del 22\/1\/2018) I Sindaci e gli amministratori locali di Lazio e Abruzzo, di [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI - SEDE DEL GOVERNO - Mandela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI - SEDE DEL GOVERNO - Mandela\" \/>\n<meta property=\"og:description\" content=\"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI SEDE DEL GOVERNO (aggiornamento del 22\/1\/2018) I Sindaci e gli amministratori locali di Lazio e Abruzzo, di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/\" \/>\n<meta property=\"og:site_name\" content=\"Mandela\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-23T08:32:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/01\/24-gennaio-pedaggio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunemandela\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunemandela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/\"},\"author\":{\"name\":\"comunemandela\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"headline\":\"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI &#8211; SEDE DEL GOVERNO\",\"datePublished\":\"2018-01-23T08:32:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/\"},\"wordCount\":372,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/01\\\/24-gennaio-pedaggio.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/\",\"name\":\"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI - SEDE DEL GOVERNO - Mandela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/01\\\/24-gennaio-pedaggio.jpg\",\"datePublished\":\"2018-01-23T08:32:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/01\\\/24-gennaio-pedaggio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/01\\\/24-gennaio-pedaggio.jpg\",\"width\":654,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/2018\\\/01\\\/23\\\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI &#8211; SEDE DEL GOVERNO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/\",\"name\":\"Mandela\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/#\\\/schema\\\/person\\\/c6455d17307d7bf5f7b97ae82adafe61\",\"name\":\"comunemandela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g\",\"caption\":\"comunemandela\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/mandela\\\/author\\\/comunemandela\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI - SEDE DEL GOVERNO - Mandela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/","og_locale":"it_IT","og_type":"article","og_title":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI - SEDE DEL GOVERNO - Mandela","og_description":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI SEDE DEL GOVERNO (aggiornamento del 22\/1\/2018) I Sindaci e gli amministratori locali di Lazio e Abruzzo, di [&hellip;]","og_url":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/","og_site_name":"Mandela","article_published_time":"2018-01-23T08:32:12+00:00","og_image":[{"width":654,"height":680,"url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/01\/24-gennaio-pedaggio.jpg","type":"image\/jpeg"}],"author":"comunemandela","twitter_misc":{"Scritto da":"comunemandela","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/"},"author":{"name":"comunemandela","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"headline":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI &#8211; SEDE DEL GOVERNO","datePublished":"2018-01-23T08:32:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/"},"wordCount":372,"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/01\/24-gennaio-pedaggio.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/","url":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/","name":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI - SEDE DEL GOVERNO - Mandela","isPartOf":{"@id":"https:\/\/comunicacity.net\/mandela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/01\/24-gennaio-pedaggio.jpg","datePublished":"2018-01-23T08:32:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#primaryimage","url":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/01\/24-gennaio-pedaggio.jpg","contentUrl":"https:\/\/comunicacity.net\/mandela\/wp-content\/uploads\/sites\/7\/2018\/01\/24-gennaio-pedaggio.jpg","width":654,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/mandela\/2018\/01\/23\/caro-pedaggi-mercoledi-mattina-nuovo-presidio-di-protesta-a-roma-sotto-palazzo-chigi-sede-del-governo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/mandela\/"},{"@type":"ListItem","position":2,"name":"CARO PEDAGGI: MERCOLEDI\u2019 MATTINA NUOVO PRESIDIO DI PROTESTA A ROMA SOTTO PALAZZO CHIGI &#8211; SEDE DEL GOVERNO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/mandela\/#website","url":"https:\/\/comunicacity.net\/mandela\/","name":"Mandela","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/mandela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/mandela\/#\/schema\/person\/c6455d17307d7bf5f7b97ae82adafe61","name":"comunemandela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b660835417e75130e3e56763cff867a5eee406575ac2f5b9bdaf30825263a25e?s=96&d=mm&r=g","caption":"comunemandela"},"url":"https:\/\/comunicacity.net\/mandela\/author\/comunemandela\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/comments?post=781"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/781\/revisions"}],"predecessor-version":[{"id":783,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/posts\/781\/revisions\/783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media\/782"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/media?parent=781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/categories?post=781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/mandela\/wp-json\/wp\/v2\/tags?post=781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}