{"id":101,"date":"2018-12-14T12:45:31","date_gmt":"2018-12-14T11:45:31","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=101"},"modified":"2018-12-14T12:45:31","modified_gmt":"2018-12-14T11:45:31","slug":"viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/","title":{"rendered":"VIABILITA&#8217;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE]"},"content":{"rendered":"<div>Si comunica che, con Ordinanza del Comandante della Polizia Locale n\u00b011 del 14.12.2018 (<em>Integrazione dell&#8217;Ord. n\u00b010 del 12.12.2018<\/em>),<strong>\u00a0il divieto di accesso e sosta in Piazza Cesare Battisti<\/strong>\u00a0nei giorni:<\/p>\n<\/div>\n<ul>\n<li><strong>14 dicembre 2018 dalle ore 14,00 a fine evento, nella parte di piazza antistante la Palestra Comunale tra i giardini e l&#8217;edificio Comunale.<\/strong><\/li>\n<li><strong>16 dicembre 2018 dalle ore 7,00 alle ore 16,30 in tutta la piazza;<\/strong><\/li>\n<li><strong>18 dicembre 2018\u00a0<\/strong><strong>dalle ore 14,00 a fine evento del 20 dicembre, nella parte di piazza antistante la Palestra Comunale tra i giardini e l&#8217;edificio Comunale.<\/strong><\/li>\n<li><strong>19 dicembre 2018\u00a0<\/strong><strong>dalle ore 14,00 a fine evento del 20 dicembre, nella parte di piazza antistante la Palestra Comunale tra i giardini e l&#8217;edificio Comunale.<\/strong><\/li>\n<li><strong>20 dicembre 2018 dalle ore 9,00 a fine evento in tutta la piazza;<\/strong><\/li>\n<li><strong>Dal 23 dicembre 2018 al 6 gennaio 2019 tutti i giorni dalle ore 9,00 a fine eventi in tutta la piazza.<\/strong><\/li>\n<\/ul>\n<div>Per tutte le manifestazioni in Piazza Cesare Battisti dei giorni sopra descritti la sosta in divieto di quanto sopra sar\u00e0 considerata di grave intralcio ai fini dell&#8217;applicazione della sanzione accessoria della rimozione dei veicoli ai sensi dell&#8217;articolo 159 del Codice della Strada.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che, con Ordinanza del Comandante della Polizia Locale n\u00b011 del 14.12.2018 (Integrazione dell&#8217;Ord. n\u00b010 del 12.12.2018),\u00a0il divieto di accesso e sosta in Piazza Cesare Battisti\u00a0nei giorni: 14 dicembre [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIABILITA&#039;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE] - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIABILITA&#039;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE] - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica che, con Ordinanza del Comandante della Polizia Locale n\u00b011 del 14.12.2018 (Integrazione dell&#8217;Ord. n\u00b010 del 12.12.2018),\u00a0il divieto di accesso e sosta in Piazza Cesare Battisti\u00a0nei giorni: 14 dicembre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-14T11:45:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2018\/12\/SPLASH_NEWS_ORD_divietososta_12_CC.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"VIABILITA&#8217;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE]\",\"datePublished\":\"2018-12-14T11:45:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/\"},\"wordCount\":187,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2018\\\/12\\\/SPLASH_NEWS_ORD_divietososta_12_CC.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/\",\"name\":\"VIABILITA': divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE] - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2018\\\/12\\\/SPLASH_NEWS_ORD_divietososta_12_CC.png\",\"datePublished\":\"2018-12-14T11:45:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2018\\\/12\\\/SPLASH_NEWS_ORD_divietososta_12_CC.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2018\\\/12\\\/SPLASH_NEWS_ORD_divietososta_12_CC.png\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2018\\\/12\\\/14\\\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIABILITA&#8217;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIABILITA': divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE] - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/","og_locale":"it_IT","og_type":"article","og_title":"VIABILITA': divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE] - Marcellina","og_description":"Si comunica che, con Ordinanza del Comandante della Polizia Locale n\u00b011 del 14.12.2018 (Integrazione dell&#8217;Ord. n\u00b010 del 12.12.2018),\u00a0il divieto di accesso e sosta in Piazza Cesare Battisti\u00a0nei giorni: 14 dicembre [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-12-14T11:45:31+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2018\/12\/SPLASH_NEWS_ORD_divietososta_12_CC.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"VIABILITA&#8217;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE]","datePublished":"2018-12-14T11:45:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/"},"wordCount":187,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2018\/12\/SPLASH_NEWS_ORD_divietososta_12_CC.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/","url":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/","name":"VIABILITA': divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE] - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2018\/12\/SPLASH_NEWS_ORD_divietososta_12_CC.png","datePublished":"2018-12-14T11:45:31+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2018\/12\/SPLASH_NEWS_ORD_divietososta_12_CC.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2018\/12\/SPLASH_NEWS_ORD_divietososta_12_CC.png","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2018\/12\/14\/viabilita-divieto-di-accesso-in-piazza-cesare-battisti-nei-giorni-1416181920-e-dal-23-dicembre-2018-al-6-gennaio-2019-per-manifestazioni-varie-integrazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"VIABILITA&#8217;: divieto di accesso in Piazza Cesare Battisti nei giorni 14,16,18,19,20 e dal 23 dicembre 2018 al 6 gennaio 2019 per manifestazioni varie. [INTEGRAZIONE]"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=101"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/101\/revisions"}],"predecessor-version":[{"id":103,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/101\/revisions\/103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/102"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}