{"id":1133,"date":"2020-02-18T13:53:26","date_gmt":"2020-02-18T12:53:26","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1133"},"modified":"2020-02-18T13:53:26","modified_gmt":"2020-02-18T12:53:26","slug":"viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/","title":{"rendered":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale"},"content":{"rendered":"<div>\n<div>Si comunica che con Ordinanza n\u00b0 2 del Responsabile del Servizio, nella giornata di<strong> gioved\u00ec 20 febbraio 2020<\/strong> verranno attuate le seguenti limitazioni alla circolazione veicolare:<\/div>\n<\/div>\n<div><\/div>\n<div>\n<ul>\n<li><strong>Divieto di sosta in corso Vittorio Emanuele nel tratto compreso tra Via M.llo Diaz e il civico n\u00b0 102 dalle ore 15,00 alle ore 17,00;<\/strong><\/li>\n<li><strong>Divieto di sosta in via Regina Elena nel tratto compreso tra i numeri civici 31\/a (Farmacia Rossessi) e 35\/d (Alimentari De Paola) dalle ore 15,00 fino alla fine delle manifestazioni;<\/strong><\/li>\n<li><strong>Chiusura al transito e divieto di sosta in piazza Cesare Battisti dalle ore 15,00 fino alla fine delle manifestazioni;<\/strong><\/li>\n<li><strong>Divieto di transito per tutti i veicoli in via Arno, via della Stazione, corso Vittorio Emanuele, piazza Vittorio Veneto e via Regina Elena per il tempo strettamente necessario a consentire il passaggio del corteo carnevalesco e fino a cessate esigenze;<\/strong><\/li>\n<\/ul>\n<div>La sosta in divieto di quanto sopra sar\u00e0 considerata di grave intralcio e pericolo per la circolazione ai fini dell&#8217;applicazione della sanzione accessoria della rimozione dei veicoli ai sensi dell&#8217;articolo 159 del Codice della Strada.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che con Ordinanza n\u00b0 2 del Responsabile del Servizio, nella giornata di gioved\u00ec 20 febbraio 2020 verranno attuate le seguenti limitazioni alla circolazione veicolare: Divieto di sosta in [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica che con Ordinanza n\u00b0 2 del Responsabile del Servizio, nella giornata di gioved\u00ec 20 febbraio 2020 verranno attuate le seguenti limitazioni alla circolazione veicolare: Divieto di sosta in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-18T12:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_ORD_chiusura_divieto_TW-768x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale\",\"datePublished\":\"2020-02-18T12:53:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/\"},\"wordCount\":181,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/\",\"name\":\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png\",\"datePublished\":\"2020-02-18T12:53:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/02\\\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/02\\\/18\\\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/","og_locale":"it_IT","og_type":"article","og_title":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale - Marcellina","og_description":"Si comunica che con Ordinanza n\u00b0 2 del Responsabile del Servizio, nella giornata di gioved\u00ec 20 febbraio 2020 verranno attuate le seguenti limitazioni alla circolazione veicolare: Divieto di sosta in [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-02-18T12:53:26+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_ORD_chiusura_divieto_TW-768x576.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale","datePublished":"2020-02-18T12:53:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/"},"wordCount":181,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/","name":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png","datePublished":"2020-02-18T12:53:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/02\/SPLASH_NEWS_ORD_chiusura_divieto_TW.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/02\/18\/viabilita-chiusura-temporanea-al-traffico-e-divieto-di-sosta-per-i-festeggiamenti-del-carnevale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"VIABILIT\u00c0: chiusura temporanea al traffico e divieto di sosta per i festeggiamenti del Carnevale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1133\/revisions"}],"predecessor-version":[{"id":1134,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1133\/revisions\/1134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/384"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}