{"id":1195,"date":"2020-03-09T18:40:57","date_gmt":"2020-03-09T17:40:57","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1195"},"modified":"2020-03-09T18:40:57","modified_gmt":"2020-03-09T17:40:57","slug":"amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/","title":{"rendered":"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali"},"content":{"rendered":"<div><strong>SI INFORMA<\/strong><br \/>\nChe, con disposizione del Sindaco, preso atto del continuo evolversi della situazione epidemiologica da COVID-19 e del carattere particolarmente diffusivo dell&#8217;epidemia, alla luce delle disposizioni contenute, da ultimo, nei decreti del Presidente del Consiglio dei Ministri del 4 marzo 2020 e 8 marzo 2020, nonch\u00e9 nell\u2019ordinanza del Presidente della Regione Lazio n. 4 del 8 marzo 2020, in considerazione della necessit\u00e0 di contrastare e contenere il diffondersi del virus su tutto il territorio nazionale, al fine di limitare le situazioni che possano comportare affollamento di persone tale da non consentire il rispetto della distanza di sicurezza interpersonale di almeno un metro prescritta ai sensi dei sopra richiamati provvedimenti, <strong>nel periodo dalla data del 09 marzo fino al 03 aprile 2020, salvo proroga<\/strong>:<\/p>\n<p><strong>1 &#8211;\u00a0SONO TEMPORANEAMENTE SOSPESE LE ATTIVIT\u00c0 DI RICEVIMENTO AL PUBBLICO PRESSO LE STRUTTURE COMUNALI, PER LE QUALI NON SIA STRETTAMENTE ESSENZIALE LA PRESENZA FISICA DEGLI UTENTI. <\/strong>In tale fattispecie rientrano, tra gli altri:<\/p>\n<p>&#8211; i Servizi Scolastici<br \/>\n&#8211; i Servizi di Amministrazione Generale<br \/>\n&#8211; i Servizi Culturali<br \/>\n&#8211; i Servizi Cimiteriali<br \/>\n&#8211; il Servizio Tributi<br \/>\n&#8211; i Servizi Tecnici<br \/>\n&#8211; il Servizio Polizia Locale<br \/>\n&#8211; il Servizio Sociale<br \/>\n&#8211; la Segreteria Comunale<\/p>\n<p><strong>Gli utenti potranno ricevere assistenza telefonica<\/strong>, nei giorni e negli orari ordinariamente dedicati al ricevimento al pubblico, telefonando ai seguenti numeri:<\/p>\n<p>&#8211; Protocollo 0774\/427033<\/p><\/div>\n<div>&#8211; i Servizi Scolastici 0774\/427022<br \/>\n&#8211; i Servizi di Amministrazione Generale 0774\/427032<br \/>\n&#8211; i Servizi Culturali 0774\/427022<br \/>\n&#8211; i Servizi Cimiteriali 0774\/427030<br \/>\n&#8211; il Servizio Tributi 0774\/427043<br \/>\n&#8211; Lavori Pubblici e Manutenzione 0774\/427036<br \/>\n&#8211; Patrimonio e Ambiente 0774\/427039<br \/>\n&#8211; Urbanistica ed edilizia privata 0774\/427038<br \/>\n&#8211; il Servizio Polizia Locale 0774\/427095 &#8211; 427096<br \/>\n&#8211; il Servizio Sociale 0774\/427060 &#8211; 427061<br \/>\n&#8211; la Segreteria Comunale 0774\/427032<\/p>\n<p><strong>ovvero mediante strumenti di comunicazione telematica<\/strong>, mediante invio tramite posta elettronica certificata ovvero invio a mezzo email (in questo caso corredata da fotocopia del documento di identit\u00e0 in corso di validit\u00e0 del richiedente).<br \/>\n<strong>L\u2019accesso agli uffici comunali sar\u00e0 consentito <u>esclusivamente<\/u> in caso di motivata urgenza ed indifferibilit\u00e0, previa fissazione di un appuntamento da concordare telefonicamente con il personale addetto chiamando ai predetti numeri telefonici<\/strong>.<\/p>\n<p><strong>2 &#8211; Per quanto concerne i servizi per i quali<\/strong>, viceversa, <strong>\u00e8 strettamente necessaria la presenza fisica del richiedente presso le strutture comunali (variazioni anagrafiche di residenza ed altri servizi demografici) &#8211; PUR DOVENDOSI RICHIAMARE LA CITTADINANZA A LIMITARE, OVE NON STRETTAMENTE NECESSARI ED INDIFFERIBILI, GLI ACCESSI AGLI UFFICI PUBBLICI &#8211; l\u2019accesso agli uffici comunali sar\u00e0 consentito in maniera contingentata (1 utente alla volta, salve diverse necessit\u00e0)<\/strong> per garantire la distanza di sicurezza interpersonale di almeno un metro, <strong>evitando assembramento di persone nelle stanze o nei corridoi<\/strong>. Nel prosieguo potr\u00e0 valutarsi l\u2019introduzione di sistemi di prenotazione degli appuntamenti al fine di calendarizzare al meglio le attivit\u00e0 non urgenti ed indifferibili.<\/p>\n<p><strong>3 &#8211;\u00a0Tutte le istanze e\/o comunicazioni indirizzate al Comune dovranno essere trasmesse agli uffici competenti <u>PRIORITARIAMENTE<\/u> mediante posta elettronica certificata (pec) indirizzata al seguente indirizzo: <\/strong><a href=\"mailto:protocollo@pec.comune.marcellina.rm.it\">protocollo@pec.comune.marcellina.rm.it<\/a>, <strong>oppure mediante e-mail al seguente indirizzo<\/strong> <a href=\"mailto:protocollo@comune.marcellina.rm.it\">protocollo@comune.marcellina.rm.it<\/a> (in questo caso allegando all\u2019istanza fotocopia del documento di identit\u00e0 in corso di validit\u00e0 del richiedente). Nel caso in cui la consegna cartacea sia necessaria ed indifferibile, l\u2019accesso al pubblico all\u2019Ufficio Protocollo sar\u00e0 consentito alle medesime condizioni di cui al punto precedente.Fermo quanto innanzi disposto per il ricevimento al pubblico, <strong>\u00e8 momentaneamente precluso l\u2019accesso agli uffici comunali da parte di persone esterne non dipendenti, se non per adempimenti degli uffici indifferibili ed urgenti e previa fissazione telefonica di apposito appuntamento con il personale interessato.<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SI INFORMA Che, con disposizione del Sindaco, preso atto del continuo evolversi della situazione epidemiologica da COVID-19 e del carattere particolarmente diffusivo dell&#8217;epidemia, alla luce delle disposizioni contenute, da ultimo, [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali - Marcellina\" \/>\n<meta property=\"og:description\" content=\"SI INFORMA Che, con disposizione del Sindaco, preso atto del continuo evolversi della situazione epidemiologica da COVID-19 e del carattere particolarmente diffusivo dell&#8217;epidemia, alla luce delle disposizioni contenute, da ultimo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-09T17:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali\",\"datePublished\":\"2020-03-09T17:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/\"},\"wordCount\":581,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/\",\"name\":\"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"datePublished\":\"2020-03-09T17:40:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/09\\\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/","og_locale":"it_IT","og_type":"article","og_title":"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali - Marcellina","og_description":"SI INFORMA Che, con disposizione del Sindaco, preso atto del continuo evolversi della situazione epidemiologica da COVID-19 e del carattere particolarmente diffusivo dell&#8217;epidemia, alla luce delle disposizioni contenute, da ultimo, [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-09T17:40:57+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali","datePublished":"2020-03-09T17:40:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/"},"wordCount":581,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/","name":"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","datePublished":"2020-03-09T17:40:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/09\/amministrazione-avviso-di-temporanea-sospensione-delle-attivita-di-ricevimento-al-pubblico-presso-le-strutture-comunali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AMMINISTRAZIONE: avviso di temporanea sospensione delle attivit\u00e0 di ricevimento al pubblico presso le strutture comunali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1195"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1195\/revisions"}],"predecessor-version":[{"id":1196,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1195\/revisions\/1196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/792"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}