{"id":1220,"date":"2020-03-13T16:41:36","date_gmt":"2020-03-13T15:41:36","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1220"},"modified":"2020-03-13T16:41:36","modified_gmt":"2020-03-13T15:41:36","slug":"coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/","title":{"rendered":"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina"},"content":{"rendered":"<div>Si comunica che nell&#8217;ambito delle iniziative a tutela della cittadinanza per l&#8217;emergenza Coronavirus in corso, sul territorio del nostro Comune abbiamo previsto\u00a0<strong>interventi di sanificazione delle strade<\/strong>\u00a0che si terranno\u00a0<strong>luned\u00ec 16 e marted\u00ec 17 marzo 2020 dalle ore 23,00<\/strong>.\n<\/div>\n<div>Si raccomanda ai cittadini di chiudere le finestre durante il trattamento e di non sostare all&#8217;esterno per evitare contatti accidentali con la soluzione nebulizzata durante lo svolgimento del servizio di sanificazione e disinfezione.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che nell&#8217;ambito delle iniziative a tutela della cittadinanza per l&#8217;emergenza Coronavirus in corso, sul territorio del nostro Comune abbiamo previsto\u00a0interventi di sanificazione delle strade\u00a0che si terranno\u00a0luned\u00ec 16 e [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":1221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si comunica che nell&#8217;ambito delle iniziative a tutela della cittadinanza per l&#8217;emergenza Coronavirus in corso, sul territorio del nostro Comune abbiamo previsto\u00a0interventi di sanificazione delle strade\u00a0che si terranno\u00a0luned\u00ec 16 e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-13T15:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/03\/SPLASH_NEWS_SAN_sanificazione_CC.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina\",\"datePublished\":\"2020-03-13T15:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/\"},\"wordCount\":80,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/03\\\/SPLASH_NEWS_SAN_sanificazione_CC.png\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/\",\"name\":\"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/03\\\/SPLASH_NEWS_SAN_sanificazione_CC.png\",\"datePublished\":\"2020-03-13T15:41:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/03\\\/SPLASH_NEWS_SAN_sanificazione_CC.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/03\\\/SPLASH_NEWS_SAN_sanificazione_CC.png\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/13\\\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/","og_locale":"it_IT","og_type":"article","og_title":"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina - Marcellina","og_description":"Si comunica che nell&#8217;ambito delle iniziative a tutela della cittadinanza per l&#8217;emergenza Coronavirus in corso, sul territorio del nostro Comune abbiamo previsto\u00a0interventi di sanificazione delle strade\u00a0che si terranno\u00a0luned\u00ec 16 e [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-13T15:41:36+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/03\/SPLASH_NEWS_SAN_sanificazione_CC.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina","datePublished":"2020-03-13T15:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/"},"wordCount":80,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/03\/SPLASH_NEWS_SAN_sanificazione_CC.png","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/","name":"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/03\/SPLASH_NEWS_SAN_sanificazione_CC.png","datePublished":"2020-03-13T15:41:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/03\/SPLASH_NEWS_SAN_sanificazione_CC.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/03\/SPLASH_NEWS_SAN_sanificazione_CC.png","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/13\/coronavirus-il-16-e-17-marzo-2020-parte-la-sanificazione-delle-strade-di-marcellina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"CORONAVIRUS: il 16 e 17 marzo 2020 parte la sanificazione delle strade di Marcellina"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1220\/revisions"}],"predecessor-version":[{"id":1222,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1220\/revisions\/1222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/1221"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}