{"id":1225,"date":"2020-03-15T17:45:51","date_gmt":"2020-03-15T16:45:51","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1225"},"modified":"2020-03-15T17:45:51","modified_gmt":"2020-03-15T16:45:51","slug":"%f0%9f%93%a2-avviso-alla-cittadinanza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/","title":{"rendered":"\ud83d\udce2 AVVISO ALLA CITTADINANZA"},"content":{"rendered":"<p>In riferimento a notizie diffuse dalla stampa locale riguardante la morte per coronavirus di un cittadino di Marcellina, dopo un riscontro con ASL si comunica che il paziente era ricoverato all&#8217;ospedale di Tivoli e non si trattava di un caso seguito dall&#8217;Autorit\u00e0 sanitaria. La positivit\u00e0, al momento, \u00e8 ancora da verificare.<\/p>\n<p>Trattandosi di un paziente affetto da polmonite con un decorso veloce \u00e8 stato eseguito un tampone per eseguire ulteriori acce<span class=\"text_exposed_show\">rtamenti, come avvenuto per altri casi simili. <\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>In caso di positivit\u00e0, si provveder\u00e0 a informare la cittadinanza circa eventuali comunicazioni provenienti dall&#8217;Autorit\u00e0 sanitaria.<\/p>\n<p>Ad oggi, non sono stati riscontrati ulteriori casi di positivit\u00e0 al COVID-19 oltre a quello gi\u00e0 riportato nei giorni scorsi.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In riferimento a notizie diffuse dalla stampa locale riguardante la morte per coronavirus di un cittadino di Marcellina, dopo un riscontro con ASL si comunica che il paziente era ricoverato [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1225","post","type-post","status-publish","format-standard","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83d\udce2 AVVISO ALLA CITTADINANZA - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/\ud83d\udce2-avviso-alla-cittadinanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udce2 AVVISO ALLA CITTADINANZA - Marcellina\" \/>\n<meta property=\"og:description\" content=\"In riferimento a notizie diffuse dalla stampa locale riguardante la morte per coronavirus di un cittadino di Marcellina, dopo un riscontro con ASL si comunica che il paziente era ricoverato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/\ud83d\udce2-avviso-alla-cittadinanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-15T16:45:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/sanita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"\ud83d\udce2 AVVISO ALLA CITTADINANZA\",\"datePublished\":\"2020-03-15T16:45:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/\"},\"wordCount\":114,\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/\",\"name\":\"\ud83d\udce2 AVVISO ALLA CITTADINANZA - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"datePublished\":\"2020-03-15T16:45:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/03\\\/15\\\/%f0%9f%93%a2-avviso-alla-cittadinanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83d\udce2 AVVISO ALLA CITTADINANZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udce2 AVVISO ALLA CITTADINANZA - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/\ud83d\udce2-avviso-alla-cittadinanza\/","og_locale":"it_IT","og_type":"article","og_title":"\ud83d\udce2 AVVISO ALLA CITTADINANZA - Marcellina","og_description":"In riferimento a notizie diffuse dalla stampa locale riguardante la morte per coronavirus di un cittadino di Marcellina, dopo un riscontro con ASL si comunica che il paziente era ricoverato [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/\ud83d\udce2-avviso-alla-cittadinanza\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-15T16:45:51+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/sanita.png","height":600,"width":1200,"type":""}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"\ud83d\udce2 AVVISO ALLA CITTADINANZA","datePublished":"2020-03-15T16:45:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/"},"wordCount":114,"articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/","name":"\ud83d\udce2 AVVISO ALLA CITTADINANZA - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"datePublished":"2020-03-15T16:45:51+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/03\/15\/%f0%9f%93%a2-avviso-alla-cittadinanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"\ud83d\udce2 AVVISO ALLA CITTADINANZA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1225"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1225\/revisions"}],"predecessor-version":[{"id":1226,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1225\/revisions\/1226"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}