{"id":1345,"date":"2020-04-15T11:24:30","date_gmt":"2020-04-15T09:24:30","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1345"},"modified":"2020-04-15T11:24:30","modified_gmt":"2020-04-15T09:24:30","slug":"servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/","title":{"rendered":"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione &#8211; annualit\u00e0 2019 &#8211; Graduatoria definitiva"},"content":{"rendered":"<p>Si rende noto in allegato la\u00a0<strong>graduatoria definitiva<\/strong>\u00a0<strong>ammessi\u00a0<\/strong>dell\u2019avviso pubblico per la concessione dei\u00a0<strong>contributi integrativi per il pagamento dei canoni di locazione per l\u2019annualit\u00e0 2019<\/strong>.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1346\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/graduatoria.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/graduatoria.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>graduatoria<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si rende noto in allegato la\u00a0graduatoria definitiva\u00a0ammessi\u00a0dell\u2019avviso pubblico per la concessione dei\u00a0contributi integrativi per il pagamento dei canoni di locazione per l\u2019annualit\u00e0 2019. \ud83d\udcce Allegatigraduatoria<\/p>\n","protected":false},"author":283,"featured_media":958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione - annualit\u00e0 2019 - Graduatoria definitiva - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione - annualit\u00e0 2019 - Graduatoria definitiva - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Si rende noto in allegato la\u00a0graduatoria definitiva\u00a0ammessi\u00a0dell\u2019avviso pubblico per la concessione dei\u00a0contributi integrativi per il pagamento dei canoni di locazione per l\u2019annualit\u00e0 2019. \ud83d\udcce Allegatigraduatoria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T09:24:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/11\/SPLASH_NEWS_SS_locazione2019_TW.png\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione &#8211; annualit\u00e0 2019 &#8211; Graduatoria definitiva\",\"datePublished\":\"2020-04-15T09:24:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/\"},\"wordCount\":46,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/11\\\/SPLASH_NEWS_SS_locazione2019_TW.png\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/\",\"name\":\"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione - annualit\u00e0 2019 - Graduatoria definitiva - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/11\\\/SPLASH_NEWS_SS_locazione2019_TW.png\",\"datePublished\":\"2020-04-15T09:24:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/11\\\/SPLASH_NEWS_SS_locazione2019_TW.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/11\\\/SPLASH_NEWS_SS_locazione2019_TW.png\",\"width\":699,\"height\":524},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/15\\\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione &#8211; annualit\u00e0 2019 &#8211; Graduatoria definitiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione - annualit\u00e0 2019 - Graduatoria definitiva - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione - annualit\u00e0 2019 - Graduatoria definitiva - Marcellina","og_description":"Si rende noto in allegato la\u00a0graduatoria definitiva\u00a0ammessi\u00a0dell\u2019avviso pubblico per la concessione dei\u00a0contributi integrativi per il pagamento dei canoni di locazione per l\u2019annualit\u00e0 2019. \ud83d\udcce Allegatigraduatoria","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-15T09:24:30+00:00","og_image":[{"width":699,"height":524,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/11\/SPLASH_NEWS_SS_locazione2019_TW.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione &#8211; annualit\u00e0 2019 &#8211; Graduatoria definitiva","datePublished":"2020-04-15T09:24:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/"},"wordCount":46,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/11\/SPLASH_NEWS_SS_locazione2019_TW.png","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/","name":"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione - annualit\u00e0 2019 - Graduatoria definitiva - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/11\/SPLASH_NEWS_SS_locazione2019_TW.png","datePublished":"2020-04-15T09:24:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/11\/SPLASH_NEWS_SS_locazione2019_TW.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/11\/SPLASH_NEWS_SS_locazione2019_TW.png","width":699,"height":524},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/15\/servizi-sociali-avviso-pubblico-contributi-integrativi-per-il-pagamento-dei-canoni-di-locazione-annualita-2019-graduatoria-definitiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"SERVIZI SOCIALI: avviso pubblico, contributi integrativi per il pagamento dei canoni di locazione &#8211; annualit\u00e0 2019 &#8211; Graduatoria definitiva"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1345"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1345\/revisions"}],"predecessor-version":[{"id":1347,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1345\/revisions\/1347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/958"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}