{"id":1380,"date":"2020-04-27T12:59:57","date_gmt":"2020-04-27T10:59:57","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1380"},"modified":"2020-04-28T10:05:29","modified_gmt":"2020-04-28T08:05:29","slug":"emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/","title":{"rendered":"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane"},"content":{"rendered":"<p>Riceviamo e pubblichiamo.<br \/>\nProsegue l\u2019impegno di Poste Italiane nell\u2019assicurare l\u2019erogazione dei propri servizi nel rispetto delle disposizioni normative in materia di contenimento e gestione dell\u2019emergenza epidemiologica da COVID-19.<\/p>\n<p>Come gi\u00e0 avvenuto lo scorso mese, l\u2019erogazione dei ratei pensionistici sar\u00e0 anticipata a partire dal giorno 27 di aprile fino al 2 maggio, mediante un\u2019azione di ampliamento della rete e degli orari degli Uffici Postali attivi su tutto il territorio nazionale.<br \/>\nInoltre Poste Italiane adotter\u00e0 misure di programmazione dell\u2019accesso agli sportelli dei soggetti titolari del diritto alla riscossione, consentendo l\u2019accesso anche nell\u2019arco dei giorni lavorativi precedenti al mese di competenza delle prestazioni medesime.<br \/>\nIn particolare, il calendario relativo alle pensioni del mese di maggio sar\u00e0 il seguente:<\/p>\n<p><strong><u>Per gli Uffici Postali aperti 5 giorni<\/u>:<\/strong><br \/>\nI cognomi: \u00a0Dalla A alla B luned\u00ec 27 aprile<br \/>\nDalla C alla D marted\u00ec 28 aprile<br \/>\nDalla E alla K mercoled\u00ec 29 aprile<br \/>\nDalla L alla P gioved\u00ec 30 aprile<br \/>\nDalla Q alla Z sabato 2 maggio<\/p>\n<p><u><\/u><br \/>\nLa lista degli Uffici Postali abilitati al pagamento delle pensioni e relative informazioni sulle giornate di apertura saranno disponibili anche sul sito aziendale\u00a0<a href=\"http:\/\/www.poste.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.poste.it<\/a>\u00a0e al numero verde 800.00.33.22.<\/p>\n<p>Ufficio Postale sito in VIA PRINCIPE DI PIEMONTE 11 sar\u00e0 aperto il 27, 28, 29, 30 aprile dalle8.20 alle 13.35 ed il 2 maggio dalle 8.20 alle 12.35<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo. Prosegue l\u2019impegno di Poste Italiane nell\u2019assicurare l\u2019erogazione dei propri servizi nel rispetto delle disposizioni normative in materia di contenimento e gestione dell\u2019emergenza epidemiologica da COVID-19. Come gi\u00e0 [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":1381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Riceviamo e pubblichiamo. Prosegue l\u2019impegno di Poste Italiane nell\u2019assicurare l\u2019erogazione dei propri servizi nel rispetto delle disposizioni normative in materia di contenimento e gestione dell\u2019emergenza epidemiologica da COVID-19. Come gi\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T10:59:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-28T08:05:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/Poste.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane\",\"datePublished\":\"2020-04-27T10:59:57+00:00\",\"dateModified\":\"2020-04-28T08:05:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/\"},\"wordCount\":217,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/04\\\/Poste.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/\",\"name\":\"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/04\\\/Poste.jpeg\",\"datePublished\":\"2020-04-27T10:59:57+00:00\",\"dateModified\":\"2020-04-28T08:05:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/04\\\/Poste.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2020\\\/04\\\/Poste.jpeg\",\"width\":630,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/04\\\/27\\\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/","og_locale":"it_IT","og_type":"article","og_title":"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane - Marcellina","og_description":"Riceviamo e pubblichiamo. Prosegue l\u2019impegno di Poste Italiane nell\u2019assicurare l\u2019erogazione dei propri servizi nel rispetto delle disposizioni normative in materia di contenimento e gestione dell\u2019emergenza epidemiologica da COVID-19. Come gi\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-27T10:59:57+00:00","article_modified_time":"2020-04-28T08:05:29+00:00","og_image":[{"width":630,"height":420,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/Poste.jpeg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane","datePublished":"2020-04-27T10:59:57+00:00","dateModified":"2020-04-28T08:05:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/"},"wordCount":217,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/Poste.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/","name":"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/Poste.jpeg","datePublished":"2020-04-27T10:59:57+00:00","dateModified":"2020-04-28T08:05:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/Poste.jpeg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2020\/04\/Poste.jpeg","width":630,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/04\/27\/emergenza-covid-19-comunicazione-pagamento-pensioni-maggio-poste-italiane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"Emergenza Covid 19 \u2013 Comunicazione pagamento pensioni Maggio Poste Italiane"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1380\/revisions"}],"predecessor-version":[{"id":1386,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1380\/revisions\/1386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/1381"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}