{"id":1551,"date":"2020-08-03T15:53:48","date_gmt":"2020-08-03T13:53:48","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=1551"},"modified":"2020-08-03T15:53:48","modified_gmt":"2020-08-03T13:53:48","slug":"amministrazione-intervento-nei-confronti-di-acea","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/","title":{"rendered":"AMMINISTRAZIONE: intervento nei confronti di ACEA"},"content":{"rendered":"<div>La criticit\u00e0 idrica che da settimane attanaglia il paese ci ha visti costretti a intervenire, anche nelle ultime ore, nei confronti di\u00a0<strong>ACEA<\/strong>,\u00a0<strong>per pretendere iniziative al fine di garantire la giusta portata idrica su tutto il territorio<\/strong>\u00a0e limitare i disagi dei cittadini attraverso un pi\u00f9 attento intervento presso le utenze private che segnalano problemi.<\/p>\n<p>A seguito del confronto con ACEA sono inoltre in corso di installazione dei limitatori di portata, tarati in relazione alla disponibilit\u00e0 idrica esistente, al fine di ottenere un bilanciamento della risorsa idrica per tutte le utenze, anche quelle che in queste settimane sono state pi\u00f9 svantaggiate.<\/p>\n<p>Infatti, si ricorda che\u00a0<strong>\u00e8 di fondamentale importanza evitare l\u2019eccessivo consumo di acqua\u00a0<\/strong>e pertanto si ricorda a tutti i cittadini l\u2019obbligo di osservare l\u2019ordinanza n. 12 del 05\/05\/2020 \u201cDivieto di utilizzo della fornitura idrica per usi diversi da quello potabile\u201d.<\/p>\n<p>A tal proposito sar\u00e0 inoltre avviata un\u2019iniziativa di controllo da parte del Gestore, in collaborazione con il Comune, per contrastare il fenomeno degli abusi nei consumi di acqua.<\/p><\/div>\n<div>\n<strong>Il Sindaco<\/strong><br \/>\n<em>Alessandro Lundini<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La criticit\u00e0 idrica che da settimane attanaglia il paese ci ha visti costretti a intervenire, anche nelle ultime ore, nei confronti di\u00a0ACEA,\u00a0per pretendere iniziative al fine di garantire la giusta [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMMINISTRAZIONE: intervento nei confronti di ACEA - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMMINISTRAZIONE: intervento nei confronti di ACEA - Marcellina\" \/>\n<meta property=\"og:description\" content=\"La criticit\u00e0 idrica che da settimane attanaglia il paese ci ha visti costretti a intervenire, anche nelle ultime ore, nei confronti di\u00a0ACEA,\u00a0per pretendere iniziative al fine di garantire la giusta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-03T13:53:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"AMMINISTRAZIONE: intervento nei confronti di ACEA\",\"datePublished\":\"2020-08-03T13:53:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/\"},\"wordCount\":182,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/\",\"name\":\"AMMINISTRAZIONE: intervento nei confronti di ACEA - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"datePublished\":\"2020-08-03T13:53:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2019\\\/08\\\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2020\\\/08\\\/03\\\/amministrazione-intervento-nei-confronti-di-acea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMMINISTRAZIONE: intervento nei confronti di ACEA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMMINISTRAZIONE: intervento nei confronti di ACEA - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/","og_locale":"it_IT","og_type":"article","og_title":"AMMINISTRAZIONE: intervento nei confronti di ACEA - Marcellina","og_description":"La criticit\u00e0 idrica che da settimane attanaglia il paese ci ha visti costretti a intervenire, anche nelle ultime ore, nei confronti di\u00a0ACEA,\u00a0per pretendere iniziative al fine di garantire la giusta [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-08-03T13:53:48+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","type":"image\/png"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"AMMINISTRAZIONE: intervento nei confronti di ACEA","datePublished":"2020-08-03T13:53:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/"},"wordCount":182,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/","url":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/","name":"AMMINISTRAZIONE: intervento nei confronti di ACEA - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","datePublished":"2020-08-03T13:53:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2019\/08\/SPLASH_NEWS_AMM_COMUNICAZIONI_TW-e1608655224747.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2020\/08\/03\/amministrazione-intervento-nei-confronti-di-acea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"AMMINISTRAZIONE: intervento nei confronti di ACEA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=1551"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1551\/revisions"}],"predecessor-version":[{"id":1552,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/1551\/revisions\/1552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/792"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=1551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=1551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=1551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}