{"id":2062,"date":"2021-03-04T17:02:40","date_gmt":"2021-03-04T16:02:40","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=2062"},"modified":"2021-03-04T17:02:40","modified_gmt":"2021-03-04T16:02:40","slug":"%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/","title":{"rendered":"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<div>Si informano gli utenti che il servizio di refezione scolastica <strong>dal 15 marzo 2021<\/strong> cambier\u00e0 la modalit\u00e0 di comunicazione dell\u2019assenza del proprio figlio e sar\u00e0 possibile effettuarla via APP e via WEB accedendo all\u2019area riservata del sito internet:\u00a0<a href=\"https:\/\/marcellina.ecivis.it\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/marcellina.ecivis.it<\/strong><\/a><\/p>\n<p>Area amministrativa<br \/>\nUfficio Servizi Scolastici<br \/>\nInfo:<br \/>\ntel. 0774 427022<br \/>\ne-mail: emidio.cecchetti@comune.marcellina.rm.it<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Si informano gli utenti che il servizio di refezione scolastica dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione dell\u2019assenza del proprio figlio e sar\u00e0 possibile effettuarla via APP [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":2063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/\ud83c\udf7d-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze - Marcellina\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Si informano gli utenti che il servizio di refezione scolastica dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione dell\u2019assenza del proprio figlio e sar\u00e0 possibile effettuarla via APP [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/\ud83c\udf7d-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-04T16:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/mensa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze\",\"datePublished\":\"2021-03-04T16:02:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/\"},\"wordCount\":68,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/mensa.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/\",\"name\":\"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/mensa.jpg\",\"datePublished\":\"2021-03-04T16:02:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/mensa.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/mensa.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/04\\\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/\ud83c\udf7d-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/","og_locale":"it_IT","og_type":"article","og_title":"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze - Marcellina","og_description":"&nbsp; Si informano gli utenti che il servizio di refezione scolastica dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione dell\u2019assenza del proprio figlio e sar\u00e0 possibile effettuarla via APP [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/\ud83c\udf7d-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-04T16:02:40+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/mensa.jpg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze","datePublished":"2021-03-04T16:02:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/"},"wordCount":68,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/mensa.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/","url":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/","name":"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/mensa.jpg","datePublished":"2021-03-04T16:02:40+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/mensa.jpg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/mensa.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/04\/%f0%9f%8d%bd-mensa-scolastica-dal-15-marzo-2021-cambiera-la-modalita-di-comunicazione-delle-assenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"\ud83c\udf7d MENSA SCOLASTICA: dal 15 marzo 2021 cambier\u00e0 la modalit\u00e0 di comunicazione delle assenze"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=2062"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2062\/revisions"}],"predecessor-version":[{"id":2064,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2062\/revisions\/2064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/2063"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=2062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=2062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=2062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}