{"id":2093,"date":"2021-03-15T12:41:57","date_gmt":"2021-03-15T11:41:57","guid":{"rendered":"https:\/\/comunicacity.net\/marcellina\/?p=2093"},"modified":"2021-03-15T12:41:57","modified_gmt":"2021-03-15T11:41:57","slug":"%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/","title":{"rendered":"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I  SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0"},"content":{"rendered":"<p>Al fine di poter essere maggiormente vicini ai cittadini in difficolt\u00e0, l&#8217;Amministrazione comunale mantiene attivo il\u00a0<strong>Centro Operativo Comunale<\/strong>\u00a0con la collaborazione delle associazioni di protezione civile.<\/p>\n<p>Per le persone anziane o con particolari fragilit\u00e0 sono quindi attivi i servizi di assistenza al cittadino, quali ad esempio la consegna a domicilio della spesa o dei medicinali.<\/p>\n<p>Per informazioni o attivare i servizi, ricordiamo che \u00e8 sempre possibile rivolgersi allo\u00a0<strong>SPORTELLO COVID<\/strong>\u00a0gi\u00e0 istituito dal Comune di Marcellina scrivendo alla mail\u00a0<strong>emergenzacovid@comune.marcellina.rm.it<\/strong>, oppure per info ai numeri della protezione civile\u00a0<strong>\u00a03496004611<\/strong>\u00a0e\u00a0<strong>3382403331<\/strong>.<\/p>\n<p><strong>IL SINDACO\u00a0<\/strong><br \/>\n<em>Alessandro Lundini\u00a0<\/em><\/p>\n<p><strong>L&#8217;ASSESSORE ALL&#8217;URBANISTICA E ALLA PROTEZIONE CIVILE<\/strong><br \/>\n<em>Enrico Salvatori<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2094\" src=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-1024x1024.jpeg\" alt=\"\" width=\"640\" height=\"640\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al fine di poter essere maggiormente vicini ai cittadini in difficolt\u00e0, l&#8217;Amministrazione comunale mantiene attivo il\u00a0Centro Operativo Comunale\u00a0con la collaborazione delle associazioni di protezione civile. Per le persone anziane o [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":2094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0 - Marcellina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/\ud83d\udea8\u2623\ufe0f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0 - Marcellina\" \/>\n<meta property=\"og:description\" content=\"Al fine di poter essere maggiormente vicini ai cittadini in difficolt\u00e0, l&#8217;Amministrazione comunale mantiene attivo il\u00a0Centro Operativo Comunale\u00a0con la collaborazione delle associazioni di protezione civile. Per le persone anziane o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/\ud83d\udea8\u2623\ufe0f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcellina\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T11:41:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-e1615808433641.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pcerquatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pcerquatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/\"},\"author\":{\"name\":\"pcerquatti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"headline\":\"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0\",\"datePublished\":\"2021-03-15T11:41:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/\"},\"wordCount\":119,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/ZonaROssa-e1615808433641.jpeg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/\",\"name\":\"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0 - Marcellina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/ZonaROssa-e1615808433641.jpeg\",\"datePublished\":\"2021-03-15T11:41:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/ZonaROssa-e1615808433641.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/wp-content\\\/uploads\\\/sites\\\/162\\\/2021\\\/03\\\/ZonaROssa-e1615808433641.jpeg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/2021\\\/03\\\/15\\\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/\",\"name\":\"Marcellina\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/#\\\/schema\\\/person\\\/46a8c6fea6b87cf6560c1b2aef9df1a4\",\"name\":\"pcerquatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g\",\"caption\":\"pcerquatti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/marcellina\\\/author\\\/pcerquatti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0 - Marcellina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/\ud83d\udea8\u2623\ufe0f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/","og_locale":"it_IT","og_type":"article","og_title":"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0 - Marcellina","og_description":"Al fine di poter essere maggiormente vicini ai cittadini in difficolt\u00e0, l&#8217;Amministrazione comunale mantiene attivo il\u00a0Centro Operativo Comunale\u00a0con la collaborazione delle associazioni di protezione civile. Per le persone anziane o [&hellip;]","og_url":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/\ud83d\udea8\u2623\ufe0f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/","og_site_name":"Marcellina","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-15T11:41:57+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-e1615808433641.jpeg","type":"image\/jpeg"}],"author":"pcerquatti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pcerquatti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/"},"author":{"name":"pcerquatti","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"headline":"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0","datePublished":"2021-03-15T11:41:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/"},"wordCount":119,"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-e1615808433641.jpeg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/","url":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/","name":"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0 - Marcellina","isPartOf":{"@id":"https:\/\/comunicacity.net\/marcellina\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-e1615808433641.jpeg","datePublished":"2021-03-15T11:41:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#primaryimage","url":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-e1615808433641.jpeg","contentUrl":"https:\/\/comunicacity.net\/marcellina\/wp-content\/uploads\/sites\/162\/2021\/03\/ZonaROssa-e1615808433641.jpeg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/marcellina\/2021\/03\/15\/%f0%9f%9a%a8%e2%98%a3%ef%b8%8f-lazio-zona-rossa-attivi-i-servizi-di-assistenza-ai-cittadini-anziani-o-con-fragilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/marcellina\/"},{"@type":"ListItem","position":2,"name":"\ud83d\udea8\u2623\ufe0f LAZIO ZONA ROSSA: ATTIVI I SERVIZI DI ASSISTENZA AI CITTADINI ANZIANI O CON FRAGILIT\u00c0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/marcellina\/#website","url":"https:\/\/comunicacity.net\/marcellina\/","name":"Marcellina","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/marcellina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/marcellina\/#\/schema\/person\/46a8c6fea6b87cf6560c1b2aef9df1a4","name":"pcerquatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f48169bd0c03c6f8285cd7be676047b02fa7704daf268da30a513e9a1f50845c?s=96&d=mm&r=g","caption":"pcerquatti"},"url":"https:\/\/comunicacity.net\/marcellina\/author\/pcerquatti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/comments?post=2093"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2093\/revisions"}],"predecessor-version":[{"id":2095,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/posts\/2093\/revisions\/2095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media\/2094"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/media?parent=2093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/categories?post=2093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/marcellina\/wp-json\/wp\/v2\/tags?post=2093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}